{"id":47658,"date":"2022-12-24T10:20:00","date_gmt":"2022-12-24T13:20:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=47658"},"modified":"2022-12-23T17:27:32","modified_gmt":"2022-12-23T20:27:32","slug":"china-covid-esta-infectando-37-milhoes-de-pessoas-por-dia-diz-site","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/12\/24\/china-covid-esta-infectando-37-milhoes-de-pessoas-por-dia-diz-site","title":{"rendered":"China: Covid est\u00e1 infectando 37 milh\u00f5es de pessoas por dia, diz site"},"content":{"rendered":"<div id=\"chunk-b0m8a\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"24\" data-block-id=\"3\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Quase<strong>\u00a037 milh\u00f5es de pessoas<\/strong>\u00a0na China podem ter sido infectadas pelo SARS-CoV-2 (o v\u00edrus causador da Covid-19)\u00a0<strong>em um \u00fanico dia nesta semana.<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"wall protected-content\">\n<div id=\"chunk-94tff\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"29\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O dado foi divulgado pelo site norte-americano Bloomberg News, nesta sexta-feira (23), citando estimativas da principal ag\u00eancia de sa\u00fade do governo chin\u00eas, a Comiss\u00e3o Nacional de Sa\u00fade de China.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-eoqcf\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"29\" data-block-id=\"5\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">Ainda segundo o relat\u00f3rio obtido pelo site, cerca de 248 milh\u00f5es de pessoas (quase 18% da popula\u00e7\u00e3o do pa\u00eds) provavelmente contra\u00edram o v\u00edrus nos primeiros 20 dias de dezembro.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-8qnm5\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"13\" data-block-id=\"6\">\n<h4 class=\"content-text__container \" data-track-category=\"Link no Texto\"><strong>O que explica a explos\u00e3o de casos?\u00a0<\/strong>Segundo infectologistas ouvidos pelo\u00a0<strong>g1:<\/strong><\/h4>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" style=\"text-align: justify;\" data-block-type=\"raw\" data-block-weight=\"24\" data-block-id=\"7\">\n<ul class=\"content-unordered-list\">\n<li>Flexibiliza\u00e7\u00e3o das restri\u00e7\u00f5es, o que permite maior mobilidade e mais pontos de aglomera\u00e7\u00e3o;<\/li>\n<li>Baixa cobertura vacinal das doses de refor\u00e7o e entre os idosos.<\/li>\n<\/ul>\n<\/div>\n<div id=\"chunk-8fjr0\" style=\"text-align: justify;\">\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"8\">\n<div id=\"banner_materia2\" class=\"tag-manager-publicidade-container mc-has-reveal mc-has-ad-lazyload tag-manager-publicidade-banner_materia2 tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" data-id=\"banner_materia2\" data-google-query-id=\"CPDmnMHIkPwCFZWzlQIdoAEO0A\">\n<div id=\"google_ads_iframe_\/95377733\/tvg_G1\/Saude_3__container__\"><iframe id=\"google_ads_iframe_\/95377733\/tvg_G1\/Saude_3\" tabindex=\"0\" title=\"3rd party ad content\" role=\"region\" name=\"google_ads_iframe_\/95377733\/tvg_G1\/Saude_3\" width=\"970\" height=\"250\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" aria-label=\"Advertisement\" data-load-complete=\"true\" data-google-container-id=\"5\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"chunk-34j9e\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"13\" data-block-id=\"9\">\n<h4 class=\"content-text__container \" data-track-category=\"Link no Texto\"><strong>Quais os principais efeitos<\/strong> que a explos\u00e3o da Covid pode causar no mundo?<\/h4>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" style=\"text-align: justify;\" data-block-type=\"raw\" data-block-weight=\"66\" data-block-id=\"10\">\n<ul class=\"content-unordered-list\">\n<li>A situa\u00e7\u00e3o\u00a0<strong>pode trazer impacto sanit\u00e1rio e econ\u00f4mico<\/strong>\u00a0em outros pa\u00edses, como no\u00a0<strong>Brasil<\/strong>;<\/li>\n<li>A principal preocupa\u00e7\u00e3o \u00e9 sobre o risco do\u00a0<strong>surgimento de novas variantes<\/strong>\u00a0mais transmiss\u00edveis e que escapem da prote\u00e7\u00e3o que as atuais vacinas d\u00e3o para casos graves da doen\u00e7a;<\/li>\n<li>Risco de\u00a0<strong>falta dos mais diversos tipos de insumos<\/strong>\u00a0(incluindo material hospitalar e medicamentos) produzidos pela China e exportados para todos os continentes.<\/li>\n<\/ul>\n<\/div>\n<div id=\"chunk-5v075\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"30\" data-block-id=\"13\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A flexibiliza\u00e7\u00e3o das medidas restritivas e a baixa cobertura vacinal de dose de refor\u00e7o e entre os idosos\u00a0s\u00e3o apontadas como fatores principais para a explos\u00e3o da Covid na China.<\/p>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" style=\"text-align: justify;\" data-block-type=\"raw\" data-block-weight=\"97\" data-block-id=\"14\">\n<ul class=\"content-unordered-list\">\n<li>A China tem uma alta cobertura vacinal na primeira e na segunda dose (91% e 89%), mas\u00a0<strong>apenas 57% da popula\u00e7\u00e3o tomou doses de refor\u00e7o<\/strong>\u00a0&#8211; s\u00e3o elas que garantem a prote\u00e7\u00e3o completa, principalmente frente \u00e0 variante \u00f4micron e suas sublinhagens;<\/li>\n<li>Entre<strong>\u00a0idosos<\/strong>, cerca de metade das pessoas com 80 anos ou mais receberam as primeiras vacinas e menos de 60% da faixa et\u00e1ria entre 60 e 69 anos est\u00e3o totalmente vacinadas;<\/li>\n<li>Al\u00e9m disso, o governo chin\u00eas decidiu\u00a0<strong>n\u00e3o usar as vacinas bivalentes<\/strong>, que s\u00e3o mais eficazes contra a \u00f4micron e suas sublinhagens, predominantes hoje no mundo.<\/li>\n<\/ul>\n<\/div>\n<div id=\"chunk-rm2s\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles quote\">\n<div class=\"quote__caption\">Estudos cient\u00edficos j\u00e1 mostraram que os idosos chineses n\u00e3o gostam de vacinar, porque seguem a medicina tradicional chinesa, que n\u00e3o inclui vacina. Esse \u00e9 um ponto muito importante. \u00c9 outra cultura<\/div>\n<div class=\"quote__author\">\u2014 Alexandre Naime Barbosa, infectologista<\/div>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" style=\"text-align: justify;\" data-block-type=\"raw\" data-block-weight=\"3\" data-block-id=\"16\">\n<div class=\"content-intertitle\">\n<h4>Falta de transpar\u00eancia<\/h4>\n<\/div>\n<\/div>\n<div id=\"chunk-2sm0b\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"32\" data-block-id=\"17\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Na quinta (22), o secret\u00e1rio de Estado americano, Antony Blinken, pediu, que a China compartilhe informa\u00e7\u00f5es sobre o surto de Covid registrado no pa\u00eds, e refor\u00e7ou a oferta de compartilhar vacinas americanas.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-dp154\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"62\" data-block-id=\"18\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;\u00c9 muito importante que todos os pa\u00edses, inclusive a China, se concentrem em que as pessoas se vacinem, que os testes e o tratamento estejam dispon\u00edveis e, o que \u00e9 mais importante, que compartilhem informa\u00e7\u00e3o com o mundo sobre o que est\u00e3o vivenciando porque tem implica\u00e7\u00f5es n\u00e3o s\u00f3 para a China, mas para o mundo inteiro&#8221;, disse Blinken durante coletiva de imprensa.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-3g3p1\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"38\" data-block-id=\"19\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Blinken afirmou ainda que a China, advers\u00e1ria frequente dos Estados Unidos, n\u00e3o pediu ajuda. O pa\u00eds asi\u00e1tico promoveu as exporta\u00e7\u00f5es de vacinas locais, que especialistas internacionais em sa\u00fade consideram menos eficazes do que as fabricadas nos Estados Unidos.<\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><span style=\"color: initial;\">&#8220;Estamos completamente preparados para dar assist\u00eancia a qualquer um que solicite e acredite que possa ser \u00fatil&#8221;, disse Blinken.<\/span><\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-9jde3\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"36\" data-block-id=\"22\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;A cada vez que o v\u00edrus se propaga ou circula, existe a possibilidade de que uma nova variante se desenvolva, e essa variante se propague ainda mais. Vem e nos atinge, ou atinge outros pa\u00edses&#8221;, lembrou.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Fonte de informa\u00e7\u00f5es: g1<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quase\u00a037 milh\u00f5es de pessoas\u00a0na China podem ter sido infectadas pelo SARS-CoV-2 (o v\u00edrus causador da Covid-19)\u00a0em um \u00fanico dia nesta semana. O dado foi divulgado pelo site norte-americano Bloomberg News, nesta sexta-feira (23), citando estimativas da principal ag\u00eancia de sa\u00fade do governo chin\u00eas, a Comiss\u00e3o Nacional de Sa\u00fade de China. Ainda segundo o relat\u00f3rio obtido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":47659,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1624,10093],"tags":[3228,3155],"class_list":["post-47658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","category-internacional","tag-china","tag-covid-19-2"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1.png","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1.png",500,330,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1-150x150.png",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1-300x198.png",300,198,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1.png",500,330,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1.png",500,330,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1.png",500,330,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1.png",500,330,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1.png",500,330,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1-420x307.png",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1-300x330.png",300,330,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1-464x290.png",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1.png",500,330,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1-322x230.png",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/china_covid-1.png",500,330,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Quase\u00a037 milh\u00f5es de pessoas\u00a0na China podem ter sido infectadas pelo SARS-CoV-2 (o v\u00edrus causador da Covid-19)\u00a0em um \u00fanico dia nesta semana. O dado foi divulgado pelo site norte-americano Bloomberg News, nesta sexta-feira (23), citando estimativas da principal ag\u00eancia de sa\u00fade do governo chin\u00eas, a Comiss\u00e3o Nacional de Sa\u00fade de China. Ainda segundo o relat\u00f3rio obtido&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47658"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47658\/revisions"}],"predecessor-version":[{"id":47660,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47658\/revisions\/47660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/47659"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}