{"id":48668,"date":"2023-01-16T17:36:23","date_gmt":"2023-01-16T20:36:23","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=48668"},"modified":"2023-01-16T17:38:02","modified_gmt":"2023-01-16T20:38:02","slug":"covid-19-juazeiro-atualiza-boletim-com-balanco-do-final-de-semana-nesta-segunda-feira-2","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/01\/16\/covid-19-juazeiro-atualiza-boletim-com-balanco-do-final-de-semana-nesta-segunda-feira-2","title":{"rendered":"Covid-19: Juazeiro atualiza boletim com balan\u00e7o do final de semana nesta segunda-feira"},"content":{"rendered":"<p style=\"text-align: justify;\">Juazeiro registrou apenas 01 novo caso de Covid-19. A informa\u00e7\u00e3o est\u00e1 no boletim epidemiol\u00f3gico da Secretaria Municipal de Sa\u00fade (Sesau) desta segunda-feira (16). O munic\u00edpio n\u00e3o registrou novo \u00f3bito por complica\u00e7\u00f5es da doen\u00e7a nas \u00faltimas 24 horas e permanece com 507 mortes.<\/p>\n<p style=\"text-align: justify;\">De acordo com o levantamento, 30.072 moradores foram infectados desde o in\u00edcio da pandemia na cidade, dos quais 29.547 j\u00e1 est\u00e3o recuperados. Os casos descartados somam 50.414. Juazeiro tem 18 casos ativos do novo coronav\u00edrus.<\/p>\n<h4 style=\"text-align: justify;\"><strong>Testes<\/strong><\/h4>\n<p style=\"text-align: justify;\">Foram realizados desde o in\u00edcio da pandemia 69.735 testes r\u00e1pidos no munic\u00edpio e 9.340 RT-PCR pelo Lacen, em Salvador.<\/p>\n<h4 style=\"text-align: justify;\"><strong>Ocupa\u00e7\u00e3o de leitos<\/strong><\/h4>\n<p style=\"text-align: justify;\">Na rede hospitalar, o percentual de ocupa\u00e7\u00e3o dos leitos de UTI para Juazeiro na rede PEBA (hospitais de Pernambuco e Bahia) \u00e9 de 23%, com 23 leitos dispon\u00edveis. Somente em Juazeiro, 20% dos leitos de UTI para pacientes com Covid-19 est\u00e3o ocupados, com 08 leitos dispon\u00edveis.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-78637\" src=\"https:\/\/www.juazeiro.ba.gov.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-scaled.jpg\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" srcset=\"https:\/\/www.juazeiro.ba.gov.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-scaled.jpg 2560w, https:\/\/www.juazeiro.ba.gov.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-300x300.jpg 300w, https:\/\/www.juazeiro.ba.gov.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1024x1024.jpg 1024w, https:\/\/www.juazeiro.ba.gov.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-150x150.jpg 150w, https:\/\/www.juazeiro.ba.gov.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-768x768.jpg 768w, https:\/\/www.juazeiro.ba.gov.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536.jpg 1536w, https:\/\/www.juazeiro.ba.gov.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-2048x2048.jpg 2048w, https:\/\/www.juazeiro.ba.gov.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-48x48.jpg 48w\" alt=\"\" width=\"2560\" height=\"2560\"><\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Ascom\/Sesau\/PMJ<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juazeiro registrou apenas 01 novo caso de Covid-19. A informa\u00e7\u00e3o est\u00e1 no boletim epidemiol\u00f3gico da Secretaria Municipal de Sa\u00fade (Sesau) desta segunda-feira (16). O munic\u00edpio n\u00e3o registrou novo \u00f3bito por complica\u00e7\u00f5es da doen\u00e7a nas \u00faltimas 24 horas e permanece com 507 mortes. De acordo com o levantamento, 30.072 moradores foram infectados desde o in\u00edcio da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":48669,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1624,203],"tags":[3155,143],"class_list":["post-48668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","category-juazeiro","tag-covid-19-2","tag-juazeiro-da-bahia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-e1673901378819.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-e1673901378819.jpg",500,500,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-300x300.jpg",300,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-768x768.jpg",640,640,true],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-1024x1024.jpg",640,640,true],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-e1673901378819.jpg",500,500,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-1020x741.jpg",1020,741,true],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-300x443.jpg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-600x500.jpg",600,500,true],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/Boletim-covid-16.01-Juazeiro-1536x1536-1-1210x642.jpg",1210,642,true]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Juazeiro registrou apenas 01 novo caso de Covid-19. A informa\u00e7\u00e3o est\u00e1 no boletim epidemiol\u00f3gico da Secretaria Municipal de Sa\u00fade (Sesau) desta segunda-feira (16). O munic\u00edpio n\u00e3o registrou novo \u00f3bito por complica\u00e7\u00f5es da doen\u00e7a nas \u00faltimas 24 horas e permanece com 507 mortes. De acordo com o levantamento, 30.072 moradores foram infectados desde o in\u00edcio da&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=48668"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48668\/revisions"}],"predecessor-version":[{"id":48671,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/48668\/revisions\/48671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/48669"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=48668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=48668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=48668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}