{"id":4917,"date":"2019-11-20T08:30:16","date_gmt":"2019-11-20T11:30:16","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=4917"},"modified":"2019-11-20T08:39:56","modified_gmt":"2019-11-20T11:39:56","slug":"homem-e-condenado-por-mentir-ao-dizer-que-apanhou-de-policiais","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2019\/11\/20\/homem-e-condenado-por-mentir-ao-dizer-que-apanhou-de-policiais","title":{"rendered":"Homem \u00e9 condenado por mentir ao dizer que apanhou de policiais"},"content":{"rendered":"<p style=\"text-align: justify;\">A Justi\u00e7a de Ara\u00e7atuba (SP) condenou Lucas Leandro da Costa, 21 anos, a 2 anos de reclus\u00e3o por ter mentido ao afirmar que apanhou de dois policiais militares quando foi preso em flagrante por tr\u00e1fico de drogas, em junho de 2017, no bairro \u00c1gua Branca.<\/p>\n<p style=\"text-align: justify;\">A informa\u00e7\u00e3o de que teria sido agredido foi feita pelo durante audi\u00eancia de cust\u00f3dia e resultou na instaura\u00e7\u00e3o de inqu\u00e9rito por denuncia\u00e7\u00e3o caluniosa.<\/p>\n<p style=\"text-align: justify;\">A Pol\u00edcia Militar tamb\u00e9m instaurou investiga\u00e7\u00e3o, que apontou n\u00e3o ter ocorrido qualquer irregularidade na pris\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Em inqu\u00e9rito, os policiais acusados disseram que na ocasi\u00e3o Costa arremessou no quintal de uma resid\u00eancia uma sacola ao ver a viatura e tentou fugir em seguida. Dentro dessa sacola havia 62 pinos contendo coca\u00edna e com ele, R$ 20,00 em dinheiro.<\/p>\n<p style=\"text-align: justify;\">Em depoimento, o r\u00e9u alegou que durante a abordagem um dos policiais deu um tapa na cabe\u00e7a dele, agress\u00e3o que teria sido presenciada por uma amiga dele. Essa testemunha foi ouvida e negou ter presenciado a agress\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>Videoconfer\u00eancia<\/strong><\/p>\n<p style=\"text-align: justify;\">O r\u00e9u foi denunciado pelo Minist\u00e9rio P\u00fablico e a audi\u00eancia de julgamento aconteceu nesta quarta-feira (13). Como ele est\u00e1 preso no CDP (Centro de Deten\u00e7\u00e3o Provis\u00f3ria) de Nova Independ\u00eancia, foi ouvido por videoconfer\u00eancia.<\/p>\n<p style=\"text-align: justify;\">A senten\u00e7a foi proferida pelo juiz da 3\u00aa Vara Criminal de Ara\u00e7atuba, Emerson Sumariva J\u00fanior, que considerou n\u00e3o haver d\u00favida de que Costa imputou aos policiais a pr\u00e1tica do crime de abuso de autoridade, mesmo sabendo que eles eram inocentes.<\/p>\n<p style=\"text-align: justify;\">\u201cFicou bem definido nos autos que os policiais agiram com toda a lisura necess\u00e1ria e o r\u00e9u, talvez contando com a impunidade que reina no pa\u00eds, tenha achado que alegando ter apanhado dos policiais sairia livre na audi\u00eancia de cust\u00f3dia\u201d, consta na decis\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Apesar de a pena ser de 2 anos de reclus\u00e3o, ela foi convertida em presta\u00e7\u00e3o de servi\u00e7os \u00e0 comunidade e pagamento de dois sal\u00e1rios m\u00ednimos para entidade filantr\u00f3pica. Cabe recurso.<\/p>\n<pre>Fonte: Hoje Mais<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Militar tamb\u00e9m instaurou investiga\u00e7\u00e3o, que apontou n\u00e3o ter ocorrido qualquer irregularidade na pris\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":4926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[202],"tags":[1004,170,1231,231],"class_list":["post-4917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-condenacao","tag-justica","tag-mentira","tag-policia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-300x169.jpg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",420,236,false],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",300,169,false],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",464,261,false],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",322,181,false],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/11\/xjustica.jpg.pagespeed.ic_.45gTMcFNfy-e1621782525226.jpg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A Pol\u00edcia Militar tamb\u00e9m instaurou investiga\u00e7\u00e3o, que apontou n\u00e3o ter ocorrido qualquer irregularidade na pris\u00e3o","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4917"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4917\/revisions"}],"predecessor-version":[{"id":4919,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4917\/revisions\/4919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/4926"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}