{"id":49936,"date":"2023-02-22T16:02:00","date_gmt":"2023-02-22T19:02:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=49936"},"modified":"2023-02-22T15:10:29","modified_gmt":"2023-02-22T18:10:29","slug":"marielle-e-anderson-dino-determina-que-pf-investigue-mortes","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/02\/22\/marielle-e-anderson-dino-determina-que-pf-investigue-mortes","title":{"rendered":"Marielle e Anderson: Dino determina que PF investigue mortes"},"content":{"rendered":"<p style=\"text-align: justify;\">O ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica,\u00a0Fl\u00e1vio Dino, pediu a abertura de inqu\u00e9rito na\u00a0Pol\u00edcia Federal (PF) para apurar o assassinato da vereadora\u00a0Marielle Franco e seu motorista, Anderson Gomes, em 2018, no Rio de Janeiro. O crime segue sem solu\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">\u201cA fim de ampliar a colabora\u00e7\u00e3o federal com as investiga\u00e7\u00f5es sobre a organiza\u00e7\u00e3o criminosa que perpetrou os homic\u00eddios de Marielle e Anderson, determinei a instaura\u00e7\u00e3o de inqu\u00e9rito na Pol\u00edcia Federal. Estamos fazendo o m\u00e1ximo para ajudar a esclarecer tais crimes\u201d, disse o chefe da pasta no Twitter.<\/p>\n<div class=\"column is-half-widescreen is-two-thirds-desktop is-full\">\n<div class=\"m-wrapper\">\n<div class=\"columns is-multiline\">\n<div class=\"column is-full\">\n<article class=\"m-content\">\n<div class=\"twitter-tweet twitter-tweet-rendered\" style=\"text-align: justify;\"><iframe id=\"twitter-widget-0\" class=\"\" title=\"Twitter Tweet\" src=\"https:\/\/platform.twitter.com\/embed\/Tweet.html?creatorScreenName=Metropoles&amp;dnt=false&amp;embedId=twitter-widget-0&amp;features=eyJ0ZndfdGltZWxpbmVfbGlzdCI6eyJidWNrZXQiOltdLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X2ZvbGxvd2VyX2NvdW50X3N1bnNldCI6eyJidWNrZXQiOnRydWUsInZlcnNpb24iOm51bGx9LCJ0ZndfdHdlZXRfZWRpdF9iYWNrZW5kIjp7ImJ1Y2tldCI6Im9uIiwidmVyc2lvbiI6bnVsbH0sInRmd19yZWZzcmNfc2Vzc2lvbiI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9LCJ0Zndfc2hvd19idXNpbmVzc192ZXJpZmllZF9iYWRnZSI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9LCJ0ZndfbWl4ZWRfbWVkaWFfMTU4OTciOnsiYnVja2V0IjoidHJlYXRtZW50IiwidmVyc2lvbiI6bnVsbH0sInRmd19leHBlcmltZW50c19jb29raWVfZXhwaXJhdGlvbiI6eyJidWNrZXQiOjEyMDk2MDAsInZlcnNpb24iOm51bGx9LCJ0ZndfZHVwbGljYXRlX3NjcmliZXNfdG9fc2V0dGluZ3MiOnsiYnVja2V0Ijoib24iLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X3ZpZGVvX2hsc19keW5hbWljX21hbmlmZXN0c18xNTA4MiI6eyJidWNrZXQiOiJ0cnVlX2JpdHJhdGUiLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X3Nob3dfYmx1ZV92ZXJpZmllZF9iYWRnZSI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9LCJ0ZndfbGVnYWN5X3RpbWVsaW5lX3N1bnNldCI6eyJidWNrZXQiOnRydWUsInZlcnNpb24iOm51bGx9LCJ0Zndfc2hvd19nb3ZfdmVyaWZpZWRfYmFkZ2UiOnsiYnVja2V0Ijoib24iLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X3Nob3dfYnVzaW5lc3NfYWZmaWxpYXRlX2JhZGdlIjp7ImJ1Y2tldCI6Im9uIiwidmVyc2lvbiI6bnVsbH0sInRmd190d2VldF9lZGl0X2Zyb250ZW5kIjp7ImJ1Y2tldCI6Im9uIiwidmVyc2lvbiI6bnVsbH19&amp;frame=false&amp;hideCard=false&amp;hideThread=false&amp;id=1628346489993822209&amp;lang=pt&amp;origin=https%3A%2F%2Fwww.metropoles.com%2Fbrasil%2Fpolitica-brasil%2Fmarielle-e-anderson-dino-determina-que-pf-abra-inquerito-sobre-mortes&amp;sessionId=611aa7834e5fe37c5c0f422759635820efd9c3fc&amp;siteScreenName=Metropoles&amp;theme=light&amp;widgetsVersion=aaf4084522e3a%3A1674595607486&amp;width=550px\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"1628346489993822209\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">O empreendimento de esfor\u00e7os para, quatro anos depois, solucionar o caso foi uma promessa de Dino quando assumiu o minist\u00e9rio. No discurso de posse, ele disse ser \u201cquest\u00e3o de honra do Estado brasileiro empreender todos os esfor\u00e7os poss\u00edveis e cab\u00edveis para que esse crime seja desvendado definitivamente e n\u00f3s saibamos quem matou Marielle Franco e quem mandou matar Marielle Franco naquele dia no Rio de Janeiro\u201d.<\/p>\n<p style=\"text-align: justify;\">No come\u00e7o do m\u00eas, o ministro criou uma for\u00e7a-tarefa para investigar o crime. No grupo, est\u00e3o inclu\u00eddos investigadores da Pol\u00edcia Civil do Rio,\u00a0promotores\u00a0do Grupo de Atua\u00e7\u00e3o Especial no Combate ao Crime Organizado (Gaeco) do Minist\u00e9rio P\u00fablico do Rio de Janeiro (MPRJ) e integrantes da Pol\u00edcia Federal (PF).<\/p>\n<h4 style=\"text-align: justify;\">Caso Marielle<\/h4>\n<p style=\"text-align: justify;\">Marielle Franco (PSol), ent\u00e3o vereadora do Rio de Janeiro, e o motorista dela, Anderson Gomes, foram assassinados em 14 de mar\u00e7o de 2018, e a investiga\u00e7\u00e3o nunca foi conclu\u00edda. S\u00f3 acabaram presos os\u00a0supostos executores do crime, Ronnie Lessa e \u00c9lcio Queiroz. Eles jamais foram denunciados \u00e0 Justi\u00e7a.<\/p>\n<p style=\"text-align: justify;\">Em setembro de 2022, a Justi\u00e7a do Rio negou recurso e manteve as pris\u00f5es dos dois. Na decis\u00e3o, o juiz Gustavo Gomes Kalil, da 4\u00aa Vara Criminal do Rio, ainda criticou os \u201csucessivos\u201d apelos por liberdade.<\/p>\n<p style=\"text-align: justify;\">\u201cMantenho, por ora, as pris\u00f5es preventivas, com base nos fundamentos j\u00e1 lan\u00e7ados na senten\u00e7a de pron\u00fancia (Pasta n\u00ba 6167), destacando que a demora na presta\u00e7\u00e3o jurisdicional se d\u00e1 por iniciativa da defesa, que interp\u00f4s sucessivos recursos em face da decis\u00e3o de pron\u00fancia, devendo arcar com o \u00f4nus da demora, n\u00e3o causada pela m\u00e1quina judici\u00e1ria\u201d, diz um trecho da senten\u00e7a.<\/p>\n<p style=\"text-align: justify;\">Na cerim\u00f4nia de posse, no in\u00edcio de janeiro,\u00a0o ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica j\u00e1 havia defendido a federaliza\u00e7\u00e3o da investiga\u00e7\u00e3o, negada pelo Superior Tribunal de Justi\u00e7a (STJ) em 2020.\u00a0Anielle Franco, irm\u00e3 de Marielle, \u00e9 ministra da Igualdade Racial\u00a0do governo de\u00a0Luiz In\u00e1cio Lula da Silva\u00a0(PT).<\/p>\n<div class=\"hstpnetworkads\" style=\"text-align: justify;\"><\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"column is-one-third-desktop is-one-quarter-widescreen is-full\">\n<div class=\"m-sidebar\">\n<div class=\"columns is-gapless is-multiline\">\n<div class=\"column is-full\"><\/div>\n<div class=\"column is-full\">\n<div class=\"m-social-media-header\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica,\u00a0Fl\u00e1vio Dino, pediu a abertura de inqu\u00e9rito na\u00a0Pol\u00edcia Federal (PF) para apurar o assassinato da vereadora\u00a0Marielle Franco e seu motorista, Anderson Gomes, em 2018, no Rio de Janeiro. O crime segue sem solu\u00e7\u00e3o. \u201cA fim de ampliar a colabora\u00e7\u00e3o federal com as investiga\u00e7\u00f5es sobre a organiza\u00e7\u00e3o criminosa que perpetrou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49937,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200,202],"tags":[2395],"class_list":["post-49936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-policia","tag-policia-federal-2"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/MG_5319-500x333-1.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica,\u00a0Fl\u00e1vio Dino, pediu a abertura de inqu\u00e9rito na\u00a0Pol\u00edcia Federal (PF) para apurar o assassinato da vereadora\u00a0Marielle Franco e seu motorista, Anderson Gomes, em 2018, no Rio de Janeiro. O crime segue sem solu\u00e7\u00e3o. \u201cA fim de ampliar a colabora\u00e7\u00e3o federal com as investiga\u00e7\u00f5es sobre a organiza\u00e7\u00e3o criminosa que perpetrou&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49936"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49936\/revisions"}],"predecessor-version":[{"id":49938,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49936\/revisions\/49938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/49937"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}