{"id":50622,"date":"2023-03-16T12:00:00","date_gmt":"2023-03-16T15:00:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=50622"},"modified":"2023-03-15T21:01:26","modified_gmt":"2023-03-16T00:01:26","slug":"servidores-publicos-pressionam-por-reajuste-salarial-durante-manifesto-na-camara-municipal-de-juazeiro-ba","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/03\/16\/servidores-publicos-pressionam-por-reajuste-salarial-durante-manifesto-na-camara-municipal-de-juazeiro-ba","title":{"rendered":"Servidores p\u00fablicos pressionam por reajuste salarial durante manifesto na C\u00e2mara Municipal de Juazeiro, BA"},"content":{"rendered":"<p style=\"text-align: justify;\">Categoria acompanhou sess\u00e3o na CMJ, na manh\u00e3 desta quarta-feira (15). Servidores alegam que o Executivo Municipal est\u00e1 dificultando o aumento real da categoria.<\/p>\n<p style=\"text-align: justify;\">Servidores p\u00fablicos municipais de Juazeiro realizaram um manifesto na manh\u00e3 desta quarta-feira (15) na C\u00e2mara Municipal da cidade baiana.<\/p>\n<p style=\"text-align: justify;\">De acordo com publica\u00e7\u00e3o do Portal Spy, o objetivo do protesto foi reivindicar reajuste salarial para a categoria.<\/p>\n<p style=\"text-align: justify;\">Segundo relatos do presidente dos Servidores Municipais de Juazeiro (Sinserp), Luiz Alberto Silva, o sindicato esperava que a prefeitura enviasse hoje o Projeto de Lei para aprecia\u00e7\u00e3o e vota\u00e7\u00e3o na Casa Legislativa, garantindo um aumento real nos sal\u00e1rios de acordo com a orienta\u00e7\u00e3o nacional.<\/p>\n<p style=\"text-align: justify;\">No entanto, de acordo com o vereador Alex Tanuri, o PL ainda n\u00e3o foi enviado pelo Executivo Municipal. Ao final da sess\u00e3o ordin\u00e1ria desta quarta-feira, representantes sindicais, da APLB e do Sinserp se reuniram para buscar mecanismos para convencer o governo municipal a enviar o PL do reajuste de forma urgente, contemplando um aumento de pelo menos 7%. Os sindicalistas afirmam que a sugest\u00e3o do munic\u00edpio \u00e9 conceder apenas 6%.<\/p>\n<p style=\"text-align: justify;\">A decis\u00e3o de participar da sess\u00e3o da C\u00e2mara foi tomada em Assembleia Extraordin\u00e1ria convocada pelo Sinserp, que tamb\u00e9m decidiu pela paralisa\u00e7\u00e3o de advert\u00eancia de 48 horas, incluindo atividades de mobiliza\u00e7\u00e3o da categoria em frente ao Pa\u00e7o Municipal. Os servidores p\u00fablicos municipais lutam por um aumento de pelo menos 7,49% nos sal\u00e1rios e esperam que suas reivindica\u00e7\u00f5es sejam atendidas pelo governo local.<\/p>\n<p style=\"text-align: justify;\">Fonte: <a href=\"https:\/\/www.portalspy.com.br\/2023\/03\/servidores-publicos-pressionam-por.html\">Portal Spy\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Categoria acompanhou sess\u00e3o na CMJ, na manh\u00e3 desta quarta-feira (15). Servidores alegam que o Executivo Municipal est\u00e1 dificultando o aumento real da categoria. Servidores p\u00fablicos municipais de Juazeiro realizaram um manifesto na manh\u00e3 desta quarta-feira (15) na C\u00e2mara Municipal da cidade baiana. De acordo com publica\u00e7\u00e3o do Portal Spy, o objetivo do protesto foi reivindicar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50604,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,197],"tags":[],"class_list":["post-50622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44.jpeg",500,326,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44-300x196.jpeg",300,196,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44.jpeg",500,326,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44.jpeg",500,326,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44.jpeg",500,326,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44.jpeg",500,326,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44.jpeg",500,326,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44-300x326.jpeg",300,326,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44.jpeg",500,326,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-15.28.44.jpeg",500,326,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Categoria acompanhou sess\u00e3o na CMJ, na manh\u00e3 desta quarta-feira (15). Servidores alegam que o Executivo Municipal est\u00e1 dificultando o aumento real da categoria. Servidores p\u00fablicos municipais de Juazeiro realizaram um manifesto na manh\u00e3 desta quarta-feira (15) na C\u00e2mara Municipal da cidade baiana. De acordo com publica\u00e7\u00e3o do Portal Spy, o objetivo do protesto foi reivindicar&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=50622"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50622\/revisions"}],"predecessor-version":[{"id":50624,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50622\/revisions\/50624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/50604"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=50622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=50622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=50622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}