{"id":50854,"date":"2023-03-23T12:00:00","date_gmt":"2023-03-23T15:00:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=50854"},"modified":"2023-03-22T21:16:44","modified_gmt":"2023-03-23T00:16:44","slug":"escola-municipal-e-furtada-no-serrote-do-urubu-em-petrolina","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/03\/23\/escola-municipal-e-furtada-no-serrote-do-urubu-em-petrolina","title":{"rendered":"Escola Municipal \u00e9 furtada no Serrote do Urubu, em Petrolina"},"content":{"rendered":"<p style=\"text-align: justify;\">Nesta quarta-feira, a Escola Municipal Luiz de Souza, localizada no Serrote do Urubu, em Petrolina, foi furtada. Os bandidos levaram botij\u00f5es de g\u00e1s e alguns pacotes.<\/p>\n<p style=\"text-align: justify;\">De acordo com a Pol\u00edcia Civil, os homens entraram no pr\u00e9dio escalando o muro e furtaram diversos objetos que se encontravam na cozinha. Um inqu\u00e9rito foi instaurado e o caso ser\u00e1 investigado.<\/p>\n<p style=\"text-align: justify;\">Por nota, a Secretaria de Educa\u00e7\u00e3o de Petrolina informou que todas as medidas legais est\u00e3o sendo tomadas para garantir a seguran\u00e7a da unidade e inibir as a\u00e7\u00f5es de v\u00e2ndalos. Al\u00e9m disso, a equipe de manuten\u00e7\u00e3o deu suporte \u00e0 institui\u00e7\u00e3o, na reposi\u00e7\u00e3o dos itens furtados, como alimentos, botij\u00e3o e utens\u00edlios dom\u00e9sticos.<\/p>\n<p style=\"text-align: justify;\">A nota informou ainda que a &#8220;Gest\u00e3o da Institui\u00e7\u00e3o de Ensino fez o registro do Boletim de Ocorr\u00eancia (BO). Flagrados pelas c\u00e2meras de videomonitoramento do local, os suspeitos foram localizados nas imedia\u00e7\u00f5es da unidade de ensino, sendo presos e conduzido \u00e0 delegacia da Pol\u00edcia Civil&#8221;.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: g1 Petrolina<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira, a Escola Municipal Luiz de Souza, localizada no Serrote do Urubu, em Petrolina, foi furtada. Os bandidos levaram botij\u00f5es de g\u00e1s e alguns pacotes. De acordo com a Pol\u00edcia Civil, os homens entraram no pr\u00e9dio escalando o muro e furtaram diversos objetos que se encontravam na cozinha. Um inqu\u00e9rito foi instaurado e o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":50855,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[851,202],"tags":[58],"class_list":["post-50854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-petrolina","category-policia","tag-petrolina"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1.jpeg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1-300x169.jpeg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1.jpeg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1.jpeg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1.jpeg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1.jpeg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1.jpeg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1-420x281.jpeg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1-300x281.jpeg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1-464x281.jpeg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1.jpeg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-22-at-21.15.30-1.jpeg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Nesta quarta-feira, a Escola Municipal Luiz de Souza, localizada no Serrote do Urubu, em Petrolina, foi furtada. Os bandidos levaram botij\u00f5es de g\u00e1s e alguns pacotes. De acordo com a Pol\u00edcia Civil, os homens entraram no pr\u00e9dio escalando o muro e furtaram diversos objetos que se encontravam na cozinha. Um inqu\u00e9rito foi instaurado e o&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=50854"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50854\/revisions"}],"predecessor-version":[{"id":50856,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50854\/revisions\/50856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/50855"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=50854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=50854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=50854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}