{"id":51265,"date":"2023-04-06T14:00:00","date_gmt":"2023-04-06T17:00:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=51265"},"modified":"2023-04-05T22:53:27","modified_gmt":"2023-04-06T01:53:27","slug":"cartao-corporativo-bolsonaro-gastou-r-754-mil-em-lanches-na-campanha","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/04\/06\/cartao-corporativo-bolsonaro-gastou-r-754-mil-em-lanches-na-campanha","title":{"rendered":"Cart\u00e3o corporativo: Bolsonaro gastou R$ 754 mil em lanches na campanha"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00c1s v\u00e9speras do depoimento \u00e0 Pol\u00edcia Federal (PF), novas notas fiscais de Jair Bolsonaro (PL) revelam que o ex-presidente pagou ao menos 21.447 lanches com o cart\u00e3o corporativo em viagens durante a campanha \u00e0 reelei\u00e7\u00e3o em 2022. Os comprovantes incluem outras 5.075 compras de refei\u00e7\u00f5es, somando um total de R$ 754 mil.<\/p>\n<p style=\"text-align: justify;\">Os dados obtidos pelo UOL, por meio da Lei de Acesso \u00e0 Informa\u00e7\u00e3o (LAI), mostram que os lanches n\u00e3o alimentavam apenas a equipe de seguran\u00e7a e assessores, em torno de 20 pessoas, do \u00e0 \u00e9poca, presidente e candidato. Bolsonaro tamb\u00e9m pagou centenas de kits-lanche destinados a militares e policiais que integravam o grupo de seguran\u00e7a de motociatas, com\u00edcios, festas de pe\u00e3o e cultos religiosos.<\/p>\n<p style=\"text-align: justify;\">De acordo com especialistas de direito eleitoral, n\u00e3o cabe ao presidente da Rep\u00fablica, nem ao candidato, fornecer alimenta\u00e7\u00e3o a for\u00e7as de seguran\u00e7a locais escaladas para atuar nos eventos.<\/p>\n<p style=\"text-align: justify;\">No entanto, em outubro do ano passado, o governo federal editou uma portaria que autoriza a solicita\u00e7\u00e3o de \u201calimenta\u00e7\u00e3o, quando necess\u00e1ria, para os integrantes de apoio local, desde que os indicados n\u00e3o estejam recebendo di\u00e1rias pelos \u00f3rg\u00e3os ou entidades a que perten\u00e7am\u201d.<\/p>\n<p style=\"text-align: justify;\">Os pedidos ficaram p\u00fablicos em 11 de janeiro, ap\u00f3s solicita\u00e7\u00e3o da Fiquem Sabendo, ag\u00eancia de dados especializada no acesso a informa\u00e7\u00f5es p\u00fablicas. A ag\u00eancia escaneou milhares de notas fiscais dos gastos.<\/p>\n<p style=\"text-align: justify;\">Durante o governo, alguns gastos de Bolsonaro no cart\u00e3o corporativo chamaram a aten\u00e7\u00e3o. Entre eles, a hospedagem em um hotel no Guaruj\u00e1 (SP) que custou R$ 1,46 milh\u00e3o dos cofres p\u00fablicos. E tamb\u00e9m os R$ 100 mil pagos na viagem de casamento do filho 03, Eduardo Bolsonaro (PL-SP).<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Metr\u00f3poles<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1s v\u00e9speras do depoimento \u00e0 Pol\u00edcia Federal (PF), novas notas fiscais de Jair Bolsonaro (PL) revelam que o ex-presidente pagou ao menos 21.447 lanches com o cart\u00e3o corporativo em viagens durante a campanha \u00e0 reelei\u00e7\u00e3o em 2022. Os comprovantes incluem outras 5.075 compras de refei\u00e7\u00f5es, somando um total de R$ 754 mil. Os dados obtidos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":48691,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200,197],"tags":[11,10560,1324],"class_list":["post-51265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-politica","tag-bahia","tag-cartao-corporativo","tag-jair-bolsonaro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1.jpg",499,334,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1-300x201.jpg",300,201,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1.jpg",499,334,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1.jpg",499,334,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1.jpg",499,334,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1.jpg",499,334,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1.jpg",499,334,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1-300x334.jpg",300,334,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1.jpg",499,334,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/01\/jair-bolsonaro-1.jpg",499,334,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"\u00c1s v\u00e9speras do depoimento \u00e0 Pol\u00edcia Federal (PF), novas notas fiscais de Jair Bolsonaro (PL) revelam que o ex-presidente pagou ao menos 21.447 lanches com o cart\u00e3o corporativo em viagens durante a campanha \u00e0 reelei\u00e7\u00e3o em 2022. Os comprovantes incluem outras 5.075 compras de refei\u00e7\u00f5es, somando um total de R$ 754 mil. Os dados obtidos&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=51265"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51265\/revisions"}],"predecessor-version":[{"id":51266,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/51265\/revisions\/51266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/48691"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=51265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=51265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=51265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}