{"id":52650,"date":"2023-05-17T10:22:00","date_gmt":"2023-05-17T13:22:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=52650"},"modified":"2023-05-16T14:24:05","modified_gmt":"2023-05-16T17:24:05","slug":"maternidade-de-juazeiro-sesau-oferta-atendimento-completo-aos-recem-nascidos-nas-primeiras-horas-de-vida","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/05\/17\/maternidade-de-juazeiro-sesau-oferta-atendimento-completo-aos-recem-nascidos-nas-primeiras-horas-de-vida","title":{"rendered":"Maternidade de Juazeiro: SESAU oferta atendimento completo aos Rec\u00e9m-Nascidos nas primeiras horas de vida"},"content":{"rendered":"<p style=\"text-align: justify;\">O \u2018Estatuto da Crian\u00e7a e do Adolescente\u2019, institu\u00eddo pela Lei Federal n\u00b0 8.069\/1990 e tamb\u00e9m a normativa do Minist\u00e9rio da Sa\u00fade, Portaria MS\/GM n\u00b0 930\/2012 garantem ao Rec\u00e9m-Nascido (RN) em todas as unidades neonatais brasileiras, p\u00fablicas e privadas a realiza\u00e7\u00e3o dos testes de triagem neonatal: pezinho, olhinho e orelhinha, entre outros. Em Juazeiro todos esses procedimentos est\u00e3o garantidos na rede municipal de sa\u00fade, uma vez que a Prefeitura de Juazeiro, atrav\u00e9s da Secretaria Municipal de Sa\u00fade (Sesau), trabalham para garantir a sa\u00fade do RN nas suas primeiras horas e dias de vida.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>\u201cNa Semana do Beb\u00ea, quando destacamos a import\u00e2ncia do investimento na primeira inf\u00e2ncia para uma sociedade com indiv\u00edduos saud\u00e1veis tanto fisicamente como emocional, temos que informar sobre os procedimentos realizados nas primeiras horas de vida dos nascidos na nossa maternidade. Muitas m\u00e3es e familiares n\u00e3o t\u00eam conhecimento dos procedimentos realizados nos beb\u00eas para garantir a sa\u00fade do rec\u00e9m-nascido nas suas primeiras horas e dias de vida\u201d, destacou a prefeita Suzana Ramos, acrescentando que \u201c\u00e9 uma luta di\u00e1ria e conjunta, com parceria de v\u00e1rias institui\u00e7\u00f5es, para reduzirmos cada vez mais os \u00edndices de mortalidade infantil no munic\u00edpio\u201d, completou Suzana Ramos.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>A coordenadora de enfermagem da Maternidade de Juazeiro, Fl\u00e1via Ribeiro enfatizou que na unidade, a aten\u00e7\u00e3o ao neonatal \u00e9 integral. \u201cOs Rec\u00e9m-Nascidos passam pelos procedimentos cl\u00ednicos atestando todas as condi\u00e7\u00f5es de sa\u00fade e depois s\u00e3o encaminhados para os testes que v\u00e3o indicar a sa\u00fade do beb\u00ea\u201d, relatou a enfermeira.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/><b>Testes e procedimentos<\/b><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Fl\u00e1via citou os testes e procedimentos realizados nos beb\u00eas logo ap\u00f3s seu nascimento na Maternidade de Juazeiro: \u201cEntre os principais cuidados nos primeiros dias de vida est\u00e3o: as primeiras vacinas, como hepatite B e a BCG; o Teste de Olhinho, um exame r\u00e1pido e indolor que \u00e9 realizado no RN para detectar qualquer anormalidade nos olhos; o Teste da Orelhinha, um exame realizado para detectar problemas de audi\u00e7\u00e3o; o Teste do Cora\u00e7\u00e3ozinho, que ajuda a identificar problemas card\u00edacos cong\u00eanitos em beb\u00eas\u201d, explicou Fl\u00e1via Ribeiro.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Al\u00e9m dos testes citados, a unidade de sa\u00fade disp\u00f5e do servi\u00e7o Ambulat\u00f3rio do Egresso. \u201cUma consulta de acompanhamento com um pediatra ap\u00f3s o beb\u00ea receber alta da maternidade. \u00c9 uma oportunidade para os pais discutirem quaisquer preocupa\u00e7\u00f5es que tenham sobre a sa\u00fade do beb\u00ea e receberem conselhos e orienta\u00e7\u00f5es sobre como cuidar de um rec\u00e9m-nascido\u201d, finalizou Fl\u00e1via.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O \u2018Estatuto da Crian\u00e7a e do Adolescente\u2019, institu\u00eddo pela Lei Federal n\u00b0 8.069\/1990 e tamb\u00e9m a normativa do Minist\u00e9rio da Sa\u00fade, Portaria MS\/GM n\u00b0 930\/2012 garantem ao Rec\u00e9m-Nascido (RN) em todas as unidades neonatais brasileiras, p\u00fablicas e privadas a realiza\u00e7\u00e3o dos testes de triagem neonatal: pezinho, olhinho e orelhinha, entre outros. Em Juazeiro todos esses [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52651,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,205],"tags":[],"class_list":["post-52650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-saude"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/thumbnail_Avaliacao-Bebe.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O \u2018Estatuto da Crian\u00e7a e do Adolescente\u2019, institu\u00eddo pela Lei Federal n\u00b0 8.069\/1990 e tamb\u00e9m a normativa do Minist\u00e9rio da Sa\u00fade, Portaria MS\/GM n\u00b0 930\/2012 garantem ao Rec\u00e9m-Nascido (RN) em todas as unidades neonatais brasileiras, p\u00fablicas e privadas a realiza\u00e7\u00e3o dos testes de triagem neonatal: pezinho, olhinho e orelhinha, entre outros. Em Juazeiro todos esses&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52650"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52650\/revisions"}],"predecessor-version":[{"id":52652,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52650\/revisions\/52652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/52651"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}