{"id":54461,"date":"2023-07-02T13:30:00","date_gmt":"2023-07-02T16:30:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=54461"},"modified":"2023-07-02T11:42:06","modified_gmt":"2023-07-02T14:42:06","slug":"estado-da-bahia-tem-apenas-28-das-estradas-em-estado-bom-ou-otimo-aponta-estudo","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/07\/02\/estado-da-bahia-tem-apenas-28-das-estradas-em-estado-bom-ou-otimo-aponta-estudo","title":{"rendered":"ESTADO DA BAHIA TEM APENAS 28% DAS ESTRADAS EM ESTADO \u2018BOM OU \u00d3TIMO\u2019, APONTA ESTUDO"},"content":{"rendered":"<p style=\"text-align: justify;\">Apenas 28% das estradas da Bahia possuem estado \u201cbom ou \u00f3timo\u201d, de acordo com a pesquisa feita pela Confedera\u00e7\u00e3o Nacional do Transporte (CNT). A Confedera\u00e7\u00e3o avalia 100% da malha rodovi\u00e1ria pavimentada federal e as principais rodovias estaduais.<\/p>\n<p style=\"text-align: justify;\">Ao todo, apenas 264 quil\u00f4metros est\u00e3o em estado \u201c\u00f3timo\u201d na Bahia, segundo o levantamento. Outros 2.368 km tem estado \u201cbom\u201d, dos 9.266 km presentes no territ\u00f3rio baiano. Em \u201cregular\u201d, a Bahia possui a maior parte dos trechos, com 4.585 quil\u00f4metros. Em estado \u201cruim\u201d est\u00e3o 1.694 km, e 355 km em estado \u201cp\u00e9ssimo\u201d.<\/p>\n<p style=\"text-align: justify;\">Outro ponto analisado pelo relat\u00f3rio \u00e9 a pavimenta\u00e7\u00e3o. A Bahia possui 4.468 km dos 9.266 km totais em estado \u201cbom ou \u00f3timo\u201d. Outros 3.334 km de pavimenta\u00e7\u00e3o na Bahia est\u00e3o em estado \u201cregular\u201d e com 1.464 km em estado \u201cruim ou p\u00e9ssimo\u201d.<\/p>\n<p style=\"text-align: justify;\">A sinaliza\u00e7\u00e3o pelas vias e rodovias tamb\u00e9m foi alvo do relat\u00f3rio. A Bahia teve 2.623 km com a sinaliza\u00e7\u00e3o avaliada com \u201c\u00f3timo ou bom\u201d, 4.072 quil\u00f4metros em n\u00edvel \u201cregular\u201d, al\u00e9m de 2.571 km como \u201cruim e p\u00e9ssimo\u201d.<\/p>\n<p style=\"text-align: justify;\">Diante desse cen\u00e1rio, a Confedera\u00e7\u00e3o Nacional do Transporte (CNT) alertou sobre a urg\u00eancia de amplia\u00e7\u00e3o dos recursos \u2013 sobretudo p\u00fablicos \u2013 destinados para investimentos em transporte e log\u00edstica, mais especificamente na infraestrutura rodovi\u00e1ria. Al\u00e9m disso, sugeriu que atrair o capital privado, ampliar a seguran\u00e7a jur\u00eddica e constituir pol\u00edticas p\u00fablicas voltadas ao transporte ser\u00e3o igualmente fundamentais.<\/p>\n<p style=\"text-align: justify;\">Os resultados da 25\u00aa edi\u00e7\u00e3o da Pesquisa CNT de Rodovias demonstram \u201ca urg\u00eancia de estrutura\u00e7\u00e3o de a\u00e7\u00f5es voltadas \u00e0 melhoria de nossas rodovias, vez que houve piora dos \u00edndices de qualidade em rela\u00e7\u00e3o ao ano passado\u201d. O relat\u00f3rio tem o objetivo de colaborar para o desenvolvimento do transporte rodovi\u00e1rio de cargas e de passageiros. Durante 30 dias, 22 equipes percorreram as 5 regi\u00f5es do Brasil de forma a compor os resultados da Pesquisa de 2022, que passa a integrar a maior s\u00e9rie hist\u00f3rica de informa\u00e7\u00f5es rodovi\u00e1rias do pa\u00eds, realizada pela CNT desde 1995. Trata-se do maior e mais completo acompanhamento sobre o estado geral das rodovias brasileiras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apenas 28% das estradas da Bahia possuem estado \u201cbom ou \u00f3timo\u201d, de acordo com a pesquisa feita pela Confedera\u00e7\u00e3o Nacional do Transporte (CNT). A Confedera\u00e7\u00e3o avalia 100% da malha rodovi\u00e1ria pavimentada federal e as principais rodovias estaduais. Ao todo, apenas 264 quil\u00f4metros est\u00e3o em estado \u201c\u00f3timo\u201d na Bahia, segundo o levantamento. Outros 2.368 km tem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54462,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199],"tags":[11],"class_list":["post-54461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","tag-bahia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2.jpeg",500,296,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2-300x178.jpeg",300,178,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2.jpeg",500,296,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2.jpeg",500,296,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2.jpeg",500,296,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2.jpeg",500,296,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2.jpeg",500,296,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2-420x296.jpeg",420,296,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2-300x296.jpeg",300,296,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2.jpeg",500,296,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-01-23-at-06.44.40-2.jpeg",500,296,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Apenas 28% das estradas da Bahia possuem estado \u201cbom ou \u00f3timo\u201d, de acordo com a pesquisa feita pela Confedera\u00e7\u00e3o Nacional do Transporte (CNT). A Confedera\u00e7\u00e3o avalia 100% da malha rodovi\u00e1ria pavimentada federal e as principais rodovias estaduais. Ao todo, apenas 264 quil\u00f4metros est\u00e3o em estado \u201c\u00f3timo\u201d na Bahia, segundo o levantamento. Outros 2.368 km tem&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54461"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54461\/revisions"}],"predecessor-version":[{"id":54463,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54461\/revisions\/54463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/54462"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}