{"id":56805,"date":"2023-09-01T10:00:00","date_gmt":"2023-09-01T13:00:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=56805"},"modified":"2023-09-01T01:32:21","modified_gmt":"2023-09-01T04:32:21","slug":"orcamento-de-2024-preve-salario-minimo-de-r-1-421","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/09\/01\/orcamento-de-2024-preve-salario-minimo-de-r-1-421","title":{"rendered":"Or\u00e7amento de 2024 prev\u00ea sal\u00e1rio m\u00ednimo de R$ 1.421"},"content":{"rendered":"<p style=\"text-align: justify;\">A proposta de or\u00e7amento para 2024 enviada pelo governo federal ao Congresso Nacional, nesta quinta-feira (31), prev\u00ea aumento do sal\u00e1rio m\u00ednimo de R$ 1.320 para R$ 1.421 em 2024, aumento de R$ 101. A informa\u00e7\u00e3o consta no Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA).<\/p>\n<p style=\"text-align: justify;\">Contudo, o valor final do sal\u00e1rio m\u00ednimo poder\u00e1 sofrer altera\u00e7\u00f5es at\u00e9 1\u00b0 de janeiro de 2024, pois\u00a0se a infla\u00e7\u00e3o no acumulado de doze meses at\u00e9 novembro deste ano for diferente da estimativa inicial, o governo vai ter de alterar a quantia.<\/p>\n<p style=\"text-align: justify;\">Pela lei vigente,\u00a0o valor ser\u00e1 reajustado anualmente com previs\u00e3o de aumento real. O c\u00e1lculo foi utilizado nos governos do PT (Lula e Dilma) e tamb\u00e9m de Michel Temer, mas a partir de 2019,\u00a0o sal\u00e1rio m\u00ednimo passou a ser reajustado apenas segundo a infla\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Blog do Waldiney Passos<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A proposta de or\u00e7amento para 2024 enviada pelo governo federal ao Congresso Nacional, nesta quinta-feira (31), prev\u00ea aumento do sal\u00e1rio m\u00ednimo de R$ 1.320 para R$ 1.421 em 2024, aumento de R$ 101. A informa\u00e7\u00e3o consta no Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA). Contudo, o valor final do sal\u00e1rio m\u00ednimo poder\u00e1 sofrer altera\u00e7\u00f5es at\u00e9 1\u00b0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14212,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200,206],"tags":[11,14,143,11034,58,11035,7008],"class_list":["post-56805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-economia","tag-bahia","tag-brasil","tag-juazeiro-da-bahia","tag-orcamento-de-2024","tag-petrolina","tag-ploa","tag-salario-minimo-2"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro.jpg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro-300x169.jpg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro.jpg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro.jpg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro.jpg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro.jpg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro.jpg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro-420x281.jpg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro-300x281.jpg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro-464x281.jpg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro.jpg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/dinheiro.jpg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A proposta de or\u00e7amento para 2024 enviada pelo governo federal ao Congresso Nacional, nesta quinta-feira (31), prev\u00ea aumento do sal\u00e1rio m\u00ednimo de R$ 1.320 para R$ 1.421 em 2024, aumento de R$ 101. A informa\u00e7\u00e3o consta no Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA). Contudo, o valor final do sal\u00e1rio m\u00ednimo poder\u00e1 sofrer altera\u00e7\u00f5es at\u00e9 1\u00b0&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=56805"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56805\/revisions"}],"predecessor-version":[{"id":56806,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56805\/revisions\/56806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/14212"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=56805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=56805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=56805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}