{"id":58237,"date":"2023-10-18T17:01:00","date_gmt":"2023-10-18T20:01:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=58237"},"modified":"2023-10-18T09:05:43","modified_gmt":"2023-10-18T12:05:43","slug":"projeto-canta-baixinho-para-ouvir-melhor-recebera-moesio-belfort-neste-sabado","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/10\/18\/projeto-canta-baixinho-para-ouvir-melhor-recebera-moesio-belfort-neste-sabado","title":{"rendered":"Projeto \u201cCanta Baixinho para Ouvir Melhor\u201d receber\u00e1 Moesio Belfort neste s\u00e1bado"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O projeto \u201cCanta Baixinho para Ouvir Melhor\u201d vai apresentar neste s\u00e1bado (21), o show \u201cNa Medida do Improv\u00e1vel\u201d, do cantor, compositor e instrumentista, Moesio Belfort. A apresenta\u00e7\u00e3o autoral, com can\u00e7\u00f5es que atravessam diversos estilos da M\u00fasica Popular Brasileira, acontecer\u00e1 \u00e0s 20h, na sala 1, do Centro de Cultura Jo\u00e3o Gilberto, em Juazeiro (BA).<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Idealizado pelo coletivo cultural Indiv\u00edduo Coletivo, o projeto visa possibilitar ao p\u00fablico a aprecia\u00e7\u00e3o de performances autorais de artistas locais. \u201cAl\u00e9m de contribuir para a divulga\u00e7\u00e3o do trabalho de artistas que constroem a cena musical de Juazeiro, o nosso objetivo \u00e9, tamb\u00e9m, formar plateia e fazer com que o p\u00fablico vivencie uma experi\u00eancia que favore\u00e7a a escuta desses trabalhos, a aprecia\u00e7\u00e3o dessas can\u00e7\u00f5es, sem muitas distra\u00e7\u00f5es. At\u00e9 o final do ano, o projeto ainda receber\u00e1 mais duas atra\u00e7\u00f5es, sempre uma vez por m\u00eas\u201d, relata Iramar Cavalcante, uma das idealizadoras do \u201cCanta Baixinho\u201d.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Em sua primeira apresenta\u00e7\u00e3o completamente autoral, Moesio Belfort promete contar um pouco da sua hist\u00f3ria como compositor. \u201cO show \u2018Na medida do Improv\u00e1vel\u2019 \u00e9 uma colet\u00e2nea de can\u00e7\u00f5es que eu venho fazendo desde que me propus a compor e a trabalhar com m\u00fasica. Uma compila\u00e7\u00e3o, que re\u00fane can\u00e7\u00f5es da minha adolesc\u00eancia at\u00e9 composi\u00e7\u00f5es mais recentes, desenhando a minha hist\u00f3ria como compositor\u201d, conta Moesio.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O \u201cCanta Baixinho para Ouvir Melhor\u201d conta com apoio do edital Ocupe seu Espa\u00e7o, da Secretaria de Cultura do Estado da Bahia (Secult).<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><b>Servi\u00e7o:<\/b><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O qu\u00ea: \u201cCanta Baixinho para Ouvir Melhor\u201d \u2013 Show \u201cNa Medida do Improv\u00e1vel\u201d, de Moesio Belfort<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Onde: Centro de Cultura Jo\u00e3o Gilberto<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Quando: S\u00e1bado (21), \u00e0s 20h<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Ingressos: R$ 20 (inteira) | R$10 (meia)<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Informa\u00e7\u00f5es: 74 98825-5249\/ 74 98815 8656 \/ 74 98815 4269 (whatsapp)<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><b>Moesio Belfort<\/b><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Artista multilinguagem, Moesio Belfort \u00e9 diretor e desenhista de curtas-metragens, compositor, m\u00fasico, instrumentista e criador de trilhas sonoras para espet\u00e1culos c\u00eanicos e produ\u00e7\u00f5es audiovisuais. Em sua principal \u00e1rea de atua\u00e7\u00e3o, a m\u00fasica, o artista se destaca como vencedor da edi\u00e7\u00e3o 2012 do Festival Ed\u00e9sio Santos da Can\u00e7\u00e3o (Juazeiro), quando foi premiado em 1\u00b0 lugar, com a can\u00e7\u00e3o \u201cAmor L\u00edquido\u201d, e na edi\u00e7\u00e3o 2017, quando alcan\u00e7ou a 3\u00b0 coloca\u00e7\u00e3o, com a m\u00fasica \u201cQuintal\u201d. Em 2020, produziu o videoclipe coletivo da sua can\u00e7\u00e3o \u201cRaio de som\u201d.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Na produ\u00e7\u00e3o de trilhas sonoras, Moesio foi indicado duas vezes na categoria melhor trilha sonora no Festival Internacional de Artes C\u00eanicas e M\u00fasica de Pernambuco (Janeiro de Grandes Espet\u00e1culos), com as trilhas do espet\u00e1culo infantil \u201cChico e Flor \u2013 contra os monstros da Ilha do Fogo\u201d (2018), da Cia Biruta de Teatro, e com o espet\u00e1culo de dan\u00e7a \u201cAluga-se um cora\u00e7\u00e3o\u201d (2012), da Quaquer Um dos 2 Cia de Dan\u00e7a.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Com o parceiro Carlos Hiury ainda assina a trilha de \u201cMeu Livro Proibido\u201d, e dos curtas-metragens \u201cContando o Rio Opar\u00e1\u201d, \u201cHist\u00f3rias de mulheres fortes, para meninas mais fortes ainda\u201d, \u201cDevaneios e retrato de artista enquanto outra\u201d.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><b><i>Videoclipe Raio de Som:<\/i><\/b><i>\u00a0<\/i><i><a href=\"https:\/\/www.youtube.com\/watch?v=VbfCMtNIFzc\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\">https:\/\/www.youtube.com\/watch?v=VbfCMtNIFzc<\/a><\/i><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><b><i>Can\u00e7\u00f5es:<\/i><\/b><i>\u00a0<a href=\"https:\/\/soundcloud.com\/moesbelf\/sets\/na-medida-do-prov-vel\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"1\">https:\/\/soundcloud.com\/moesbelf\/sets\/na-medida-do-prov-vel<\/a><\/i><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><b><i>Instagram:<\/i><\/b><i>\u00a0@moesio_belf<\/i><\/p>\n<div style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O projeto \u201cCanta Baixinho para Ouvir Melhor\u201d vai apresentar neste s\u00e1bado (21), o show \u201cNa Medida do Improv\u00e1vel\u201d, do cantor, compositor e instrumentista, Moesio Belfort. A apresenta\u00e7\u00e3o autoral, com can\u00e7\u00f5es que atravessam diversos estilos da M\u00fasica Popular Brasileira, acontecer\u00e1 \u00e0s 20h, na sala 1, do Centro de Cultura Jo\u00e3o Gilberto, em Juazeiro (BA). Idealizado pelo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58238,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[9216,134,720],"class_list":["post-58237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-centro-de-cultura-joao-gilberto","tag-cultura","tag-vale-do-sao-francisco"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02.jpg",500,500,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02-300x300.jpg",300,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02.jpg",500,500,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02.jpg",500,500,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02.jpg",500,500,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02.jpg",500,500,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02.jpg",500,500,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02-300x443.jpg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02.jpg",500,500,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Canta-Baixinho-Para-Ouvir-Melhor-02.jpg",500,500,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O projeto \u201cCanta Baixinho para Ouvir Melhor\u201d vai apresentar neste s\u00e1bado (21), o show \u201cNa Medida do Improv\u00e1vel\u201d, do cantor, compositor e instrumentista, Moesio Belfort. A apresenta\u00e7\u00e3o autoral, com can\u00e7\u00f5es que atravessam diversos estilos da M\u00fasica Popular Brasileira, acontecer\u00e1 \u00e0s 20h, na sala 1, do Centro de Cultura Jo\u00e3o Gilberto, em Juazeiro (BA). Idealizado pelo&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=58237"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58237\/revisions"}],"predecessor-version":[{"id":58239,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58237\/revisions\/58239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/58238"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=58237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=58237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=58237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}