{"id":58496,"date":"2023-10-25T16:23:00","date_gmt":"2023-10-25T19:23:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=58496"},"modified":"2023-10-24T21:39:54","modified_gmt":"2023-10-25T00:39:54","slug":"projeto-canta-baixinho-para-ouvir-melhor-encanta-o-publico-em-mais-uma-noite-de-apresentacao","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/10\/25\/projeto-canta-baixinho-para-ouvir-melhor-encanta-o-publico-em-mais-uma-noite-de-apresentacao","title":{"rendered":"Projeto \u201cCanta Baixinho para Ouvir Melhor\u201d encanta o p\u00fablico em mais uma noite de apresenta\u00e7\u00e3o"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Em mais uma noite de muita m\u00fasica, o projeto \u201cCanta Baixinho para Ouvir Melhor\u201d encantou a plateia que lotou a sala multiuso do Centro de Cultura Jo\u00e3o Gilberto, neste s\u00e1bado (21). O p\u00fablico teve a oportunidade de conferir toda a versatilidade do cantor, compositor e instrumentista, Moesio Belfort, no show \u201cNa Medida do Improv\u00e1vel\u201d.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Acompanhado dos m\u00fasicos Carlos Hiury (piano), Patrick Souza (guitarra) e Aislan Santos (percuss\u00e3o), Moesio e seu viol\u00e3o fizeram um passeio por suas can\u00e7\u00f5es, que passam por diversos\u00a0ritmos da M\u00fasica Popular Brasileira para contar a sua hist\u00f3ria como compositor. No repert\u00f3rio, can\u00e7\u00f5es premiadas, bossa, blues, samba e participa\u00e7\u00f5es especiais de Joedson Silva e Joyce Guirra.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Moesio Belfort demonstrou a sua satisfa\u00e7\u00e3o com a apresenta\u00e7\u00e3o no projeto. \u201cO show para mim teve uma import\u00e2ncia muito grande, porque foi um momento em que eu consegui me mostrar como cantor e compositor, em um show totalmente autoral, com todas as can\u00e7\u00f5es da minha carreira. Foi um momento muito \u00edntimo no qual eu pude mostrar ao p\u00fablico essas composi\u00e7\u00f5es e sentir que a recep\u00e7\u00e3o das pessoas foi muito boa\u201d.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">A professora Andrea Cristiana Santos comentou a apresenta\u00e7\u00e3o. \u201cEu j\u00e1 conhecia um pouco a obra de Moesio, mas apresentar essas m\u00fasicas com um car\u00e1ter mais intimista deu uma sensa\u00e7\u00e3o de afetividade e de enlace. A proposta de cantar baixinho \u00e9 um reencontro com essa sensa\u00e7\u00e3o mais intimista de curtir uma m\u00fasica, fruir, aproveitar a m\u00fasica de uma forma mais delicada, sens\u00edvel\u201d, disse Andrea sobre o projeto.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Carlos Santana Dam\u00e1sio tamb\u00e9m elogiou a performance do artista. \u201cO show foi muito bom. Moesio \u00e9 um letrista e instrumentista de muito talento. Foi encantador admirar a complexidade e as v\u00e1rias camadas sonoras das can\u00e7\u00f5es dele, maravilhoso\u201d, disse Carlos, que est\u00e1 na plateia do &#8220;Canta Baixinho&#8221; desde a primeira edi\u00e7\u00e3o.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><b>O Projeto<\/b><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O projeto, idealizado pelo coletivo cultural Indiv\u00edduo Coletivo, visa possibilitar a aprecia\u00e7\u00e3o de performances autorais de artistas locais e vem atraindo a aten\u00e7\u00e3o do p\u00fablico. \u201cQuando pensamos o projeto n\u00e3o imagin\u00e1vamos que ter\u00edamos uma ades\u00e3o t\u00e3o grande do p\u00fablico. As pessoas est\u00e3o gostando, dando retornos muito positivos e embarcando na nossa proposta de aprecia\u00e7\u00e3o musical. Tanto Joyce Guirra, que foi a nossa primeira atra\u00e7\u00e3o, como Moesio Belfort, surpreenderam o p\u00fablico com a qualidade do seu trabalho. Isso nos deixa muito felizes\u201d, pontuou Iramar Cavalcante, que \u00e9 membro do Indiv\u00edduo Coletivo.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O projeto conta com apoio da Secretaria de Cultura do Estado da Bahia (Secult), atrav\u00e9s do edital \u201cOcupe seu Espa\u00e7o\u201d. A cenografia e ilumina\u00e7\u00e3o do projeto s\u00e3o assinadas por Cristiane Crispim, Joana Crispim e Ant\u00f4nio Veronaldo. A execu\u00e7\u00e3o de luz foi de Elson Campos.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><b>Pr\u00f3xima atra\u00e7\u00e3o<\/b><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Nesta primeira temporada, o projeto contar\u00e1, ainda, com mais dois shows, um por m\u00eas, at\u00e9 dezembro. A pr\u00f3xima atra\u00e7\u00e3o ser\u00e1 o cantor e compositor, Rog\u00e9rio Leal, no dia 18 de novembro, no Centro de Cultura Jo\u00e3o Gilberto, \u00e0s 20h, com o show \u201cPausa\u201d.<\/p>\n<div style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Em mais uma noite de muita m\u00fasica, o projeto \u201cCanta Baixinho para Ouvir Melhor\u201d encantou a plateia que lotou a sala multiuso do Centro de Cultura Jo\u00e3o Gilberto, neste s\u00e1bado (21). O p\u00fablico teve a oportunidade de conferir toda a versatilidade do cantor, compositor e instrumentista, Moesio Belfort, no show \u201cNa Medida do Improv\u00e1vel\u201d. Acompanhado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58497,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1784],"tags":[9216,221,720],"class_list":["post-58496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-2","tag-centro-de-cultura-joao-gilberto","tag-musica","tag-vale-do-sao-francisco"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/10\/thumbnail_Foto_Leonidas-Vidal-01.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Em mais uma noite de muita m\u00fasica, o projeto \u201cCanta Baixinho para Ouvir Melhor\u201d encantou a plateia que lotou a sala multiuso do Centro de Cultura Jo\u00e3o Gilberto, neste s\u00e1bado (21). O p\u00fablico teve a oportunidade de conferir toda a versatilidade do cantor, compositor e instrumentista, Moesio Belfort, no show \u201cNa Medida do Improv\u00e1vel\u201d. Acompanhado&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=58496"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58496\/revisions"}],"predecessor-version":[{"id":58498,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/58496\/revisions\/58498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/58497"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=58496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=58496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=58496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}