{"id":59676,"date":"2023-11-27T14:12:33","date_gmt":"2023-11-27T17:12:33","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=59676"},"modified":"2023-11-27T14:12:37","modified_gmt":"2023-11-27T17:12:37","slug":"neoenergia-vai-trocar-lampadas-led-de-forma-gratuita-em-petrolina-a-partir-desta-terca-feira","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/11\/27\/neoenergia-vai-trocar-lampadas-led-de-forma-gratuita-em-petrolina-a-partir-desta-terca-feira","title":{"rendered":"Neoenergia vai trocar l\u00e2mpadas LED de forma gratuita em Petrolina, a partir desta ter\u00e7a-feira"},"content":{"rendered":"<div class=\"entry-content\">\n<p style=\"text-align: justify;\">Os clientes da\u00a0Neoenergia\u00a0Pernambuco que moram no munic\u00edpio de Petrolina poder\u00e3o se beneficiar do projeto Energia com Cidadania, que promove a substitui\u00e7\u00e3o de l\u00e2mpadas usadas por novas, de LED, a partir desta ter\u00e7a-feira (28) at\u00e9 sexta-feira (01).<\/p>\n<p style=\"text-align: justify;\">A substitui\u00e7\u00e3o ser\u00e1 realizada pela equipe da distribuidora, no caminh\u00e3o fixo, localizado na Pra\u00e7a da Juventude, Av. Aila Silva, no bairro Jo\u00e3o de Deus, ao lado da feira livre, das 8h30 \u00e0s 16h30. Para ter acesso ao benef\u00edcio, os moradores devem entregar uma l\u00e2mpada fluorescente compacta, incandescente ou hal\u00f3gena, com pot\u00eancia a partir de 14W para receber l\u00e2mpada da tecnologia LED.<\/p>\n<p style=\"text-align: justify;\">\u201c<em>Apesar do crescimento da utiliza\u00e7\u00e3o de l\u00e2mpadas LED, ainda \u00e9 muito comum encontrarmos l\u00e2mpadas ineficientes, de alto consumo e baixa luminosidade na casa das pessoas. Por meio do Energia com Cidadania, buscamos eficientizar a ilumina\u00e7\u00e3o das resid\u00eancias, promovendo uma melhor qualidade de vida e a diminui\u00e7\u00e3o no consumo de energia el\u00e9trica dos clientes<\/em>\u201d,\u00a0afirmou o supervisor de Efici\u00eancia Energ\u00e9tica da Neoenergia Pernambuco, Artur Costa.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de fornecer uma melhor ilumina\u00e7\u00e3o, a l\u00e2mpada LED traz v\u00e1rios benef\u00edcios para fam\u00edlias que podem ser contempladas, como, por exemplo, uma redu\u00e7\u00e3o significativa no valor da fatura de energia. Estima-se que uma l\u00e2mpada LED pode ser at\u00e9 40% mais econ\u00f4mica do que as demais. A a\u00e7\u00e3o faz parte do Programa de Efici\u00eancia Energ\u00e9tica da Neoenergia Pernambuco, regulado pela Ag\u00eancia Nacional de Energia El\u00e9trica (ANEEL).<\/p>\n<p style=\"text-align: justify;\">Para ser contemplado, \u00e9 necess\u00e1rio que o cliente seja morador de comunidade popular ou esteja cadastrado na Tarifa Social de Energia El\u00e9trica. Tamb\u00e9m \u00e9 obrigat\u00f3rio apresentar, no momento da troca, a conta de energia do m\u00eas anterior e n\u00e3o ter trocado mais de oito l\u00e2mpadas em projetos da Neoenergia Pernambuco nos \u00faltimos 6 anos.<\/p>\n<\/div>\n<footer class=\"entry-footer\">\n<div class=\"social-wrap\">\n<div class=\"meta-social-share\" style=\"text-align: justify;\"><i class=\"fa fa-print-social\"><\/i><em>Fonte: Blog do Waldiney Passos<\/em><\/div>\n<\/div>\n<\/footer>\n","protected":false},"excerpt":{"rendered":"<p>Os clientes da\u00a0Neoenergia\u00a0Pernambuco que moram no munic\u00edpio de Petrolina poder\u00e3o se beneficiar do projeto Energia com Cidadania, que promove a substitui\u00e7\u00e3o de l\u00e2mpadas usadas por novas, de LED, a partir desta ter\u00e7a-feira (28) at\u00e9 sexta-feira (01). A substitui\u00e7\u00e3o ser\u00e1 realizada pela equipe da distribuidora, no caminh\u00e3o fixo, localizado na Pra\u00e7a da Juventude, Av. Aila Silva, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59677,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1504,851],"tags":[11203,9467,58],"class_list":["post-59676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidade","category-petrolina","tag-lampadas-led","tag-neoenergia","tag-petrolina"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388.png","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388.png",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388-150x150.png",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388-300x169.png",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388.png",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388.png",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388.png",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388.png",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388.png",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388-420x281.png",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388-300x281.png",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388-464x281.png",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388.png",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388-322x230.png",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/Sem-titulo-388.png",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Os clientes da\u00a0Neoenergia\u00a0Pernambuco que moram no munic\u00edpio de Petrolina poder\u00e3o se beneficiar do projeto Energia com Cidadania, que promove a substitui\u00e7\u00e3o de l\u00e2mpadas usadas por novas, de LED, a partir desta ter\u00e7a-feira (28) at\u00e9 sexta-feira (01). A substitui\u00e7\u00e3o ser\u00e1 realizada pela equipe da distribuidora, no caminh\u00e3o fixo, localizado na Pra\u00e7a da Juventude, Av. Aila Silva,&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=59676"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59676\/revisions"}],"predecessor-version":[{"id":59678,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59676\/revisions\/59678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/59677"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=59676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=59676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=59676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}