{"id":59744,"date":"2023-11-29T16:34:00","date_gmt":"2023-11-29T19:34:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=59744"},"modified":"2023-11-28T18:25:20","modified_gmt":"2023-11-28T21:25:20","slug":"prefeita-suzana-ramos-entrega-8a-casa-adaptada-do-programa-transformar","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/11\/29\/prefeita-suzana-ramos-entrega-8a-casa-adaptada-do-programa-transformar","title":{"rendered":"Prefeita Suzana Ramos entrega 8\u00aa casa adaptada do Programa Transformar"},"content":{"rendered":"<p style=\"text-align: justify;\">Muita alegria e emo\u00e7\u00e3o marcaram a manh\u00e3 desta ter\u00e7a-feira (28) na entrega de mais uma casa do Programa Transformar, da Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Desenvolvimento Social, Mulher e Diversidade (Sedes). O contemplado foi o pequeno Samuel Silva, de 7 anos, usu\u00e1rio de cadeira de rodas.<\/p>\n<p style=\"text-align: justify;\">\u201cSonhei tanto com esse momento e Deus, atrav\u00e9s da prefeita Suzana Ramos, realizou meu sonho. Hoje, Samuel, juntamente com nossa fam\u00edlia, inicia um novo ciclo de conquistas e alegrias. Muito obrigada por sua sensibilidade com o pr\u00f3ximo, prefeita\u201d, destacou a m\u00e3e do Samuel, Sara Silva.<\/p>\n<p style=\"text-align: justify;\">A prefeita Suzana Ramos, sempre atenta \u00e0s necessidades da popula\u00e7\u00e3o, destaca a relev\u00e2ncia do projeto no munic\u00edpio. \u201cN\u00e3o tem presente ou trabalho melhor do que realizar a\u00e7\u00f5es para o benef\u00edcio das pessoas, ainda mais quando se trata de pessoa com alguma dificuldade de locomo\u00e7\u00e3o. A meta \u00e9 trabalhar mais para entregar mais equipamentos at\u00e9 o final do ano\u201d, enfatizou a prefeita. O Programa Transformar promove acessibilidade e autonomia \u00e0s pessoas com defici\u00eancia. \u201cEssa casa adaptada e\/ou reformada melhora as condi\u00e7\u00f5es de vida da pessoa com defici\u00eancia, considerando suas especificidades de mobilidade f\u00edsica\u201d, disse a prefeita.<\/p>\n<p style=\"text-align: justify;\"><strong>Adapta\u00e7\u00f5es na casa de Samuel<\/strong><\/p>\n<p style=\"text-align: justify;\">A casa passou por transforma\u00e7\u00e3o e adapta\u00e7\u00e3o para melhor autonomia de Samuel. Os servi\u00e7os prestados foram de nivelamento do piso para facilitar a mobilidade dentro do im\u00f3vel, revis\u00e3o da parte el\u00e9trica e hidr\u00e1ulica, instala\u00e7\u00e3o de pe\u00e7as sanit\u00e1rias adequadas e barras de acessibilidade, revis\u00e3o de cobertura, forro de gesso, aplica\u00e7\u00e3o de massa corrida, pintura integral da unidade, entre outros servi\u00e7os que facilitam que o pequeno Samuel possa transitar livremente dentro da sua pr\u00f3pria casa.<\/p>\n<p style=\"text-align: justify;\">\u201cEstou super feliz em participar da entrega de mais uma casa do Programa Transformar, uma casa totalmente adaptada com acessibilidade para atender a necessidade do menino Samuel. Quero parabenizar a prefeita Suzana Ramos pelo importante trabalho social que vem desenvolvendo, ofertando\u00a0 mais qualidade de vida e mais conforto a este p\u00fablico\u201d, destacou a secret\u00e1ria de Desenvolvimento Social, Mulher e Diversidade, Nadja Dias. Participaram do evento os vereadores An\u00edbal Ara\u00fajo, Anderson da Ilumina\u00e7\u00e3o, Bebeto Matias, Ben\u00e9 Marques, H\u00edtallo Marcelino, Jean Gomes, Gild\u00e1sio Bar\u00e3o, Gleidson Azevedo, Lourival Quirino, Renato Brand\u00e3o,, al\u00e9m de secret\u00e1rios municipais e l\u00edderes comunit\u00e1rios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muita alegria e emo\u00e7\u00e3o marcaram a manh\u00e3 desta ter\u00e7a-feira (28) na entrega de mais uma casa do Programa Transformar, da Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Desenvolvimento Social, Mulher e Diversidade (Sedes). O contemplado foi o pequeno Samuel Silva, de 7 anos, usu\u00e1rio de cadeira de rodas. \u201cSonhei tanto com esse momento e Deus, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59745,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[5195,1689],"class_list":["post-59744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-prefeita-suzana-ramos","tag-social"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274.jpg",500,311,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274-300x187.jpg",300,187,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274.jpg",500,311,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274.jpg",500,311,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274.jpg",500,311,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274.jpg",500,311,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274.jpg",500,311,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274-300x311.jpg",300,311,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274.jpg",500,311,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/11\/143A9274.jpg",500,311,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Muita alegria e emo\u00e7\u00e3o marcaram a manh\u00e3 desta ter\u00e7a-feira (28) na entrega de mais uma casa do Programa Transformar, da Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Desenvolvimento Social, Mulher e Diversidade (Sedes). O contemplado foi o pequeno Samuel Silva, de 7 anos, usu\u00e1rio de cadeira de rodas. \u201cSonhei tanto com esse momento e Deus,&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=59744"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59744\/revisions"}],"predecessor-version":[{"id":59746,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59744\/revisions\/59746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/59745"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=59744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=59744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=59744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}