{"id":60070,"date":"2023-12-11T10:34:00","date_gmt":"2023-12-11T13:34:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=60070"},"modified":"2023-12-10T21:35:20","modified_gmt":"2023-12-11T00:35:20","slug":"prefeitura-de-juazeiro-destaca-importancia-da-vacinacao-para-prevenir-contaminacoes-pela-covid-19","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2023\/12\/11\/prefeitura-de-juazeiro-destaca-importancia-da-vacinacao-para-prevenir-contaminacoes-pela-covid-19","title":{"rendered":"Prefeitura de Juazeiro destaca import\u00e2ncia da vacina\u00e7\u00e3o para prevenir contamina\u00e7\u00f5es pela Covid-19"},"content":{"rendered":"<p style=\"text-align: justify;\">Juazeiro vem registrando aumentos de infec\u00e7\u00e3o pela Covid-19 no munic\u00edpio. Somente entre os dias 26 de novembro a 02 de dezembro foram registrados 49 casos da doen\u00e7a. A Prefeitura Municipal, atrav\u00e9s da Secretaria de Sa\u00fade (Sesau), vem alertar a popula\u00e7\u00e3o sobre a import\u00e2ncia da vacina\u00e7\u00e3o para preven\u00e7\u00e3o da doen\u00e7a.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>De janeiro a 2 de dezembro de 2023 foram, ao todo, 549 casos e uma morte provocada pela doen\u00e7a. A superintendente de Vigil\u00e2ncia em Sa\u00fade, Caroline Morais, destaca o papel das vacinas na preven\u00e7\u00e3o da doen\u00e7a. \u201c\u00c9 fundamental que as pessoas mantenham o seu esquema vacinal completo. Desde o in\u00edcio da campanha, o munic\u00edpio aplicou 474.196 doses. O que percebemos \u00e9 uma queda na procura pelas doses bivalentes. As pessoas se preocuparam em tomar a dose da monovalente, no primeiro ano da pandemia, mas n\u00e3o conclu\u00edram a programa\u00e7\u00e3o vacinal. A cobertura vacinal da bivalente \u00e9 de apenas 10,12%, um n\u00famero baixo\u201d, afirmou.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>A vacina\u00e7\u00e3o est\u00e1 dispon\u00edvel nas Unidades B\u00e1sicas de Sa\u00fade (UBSs), de segunda a sexta-feira, das 8h \u00e0s 12h e das 13h30 \u00e0s 16h30, na zona urbana, e das 7h \u00e0s 13h, na zona rural.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/><b>Outros cuidados para preven\u00e7\u00e3o<br aria-hidden=\"true\" \/><\/b><br aria-hidden=\"true\" \/>Os cuidados para a preven\u00e7\u00e3o continuam sendo a lavagem das m\u00e3os, fazer isolamento e usar m\u00e1scara em caso de sintomas como tosse e febre, ajudam a evitar a contamina\u00e7\u00e3o por Covid-19 e outras doen\u00e7as, como gripes e resfriados.<\/p>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Texto: Marcela Cavalcanti\u00a0&#8211; Ascom Sesau &#8211; PMJ<\/div>\n<div>Sonora: Caroline Morais &#8211; superintendente da Vigil\u00e2ncia em Sa\u00fade\u00a0<br clear=\"all\" aria-hidden=\"true\" \/><\/p>\n<div style=\"text-align: justify;\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Juazeiro vem registrando aumentos de infec\u00e7\u00e3o pela Covid-19 no munic\u00edpio. Somente entre os dias 26 de novembro a 02 de dezembro foram registrados 49 casos da doen\u00e7a. A Prefeitura Municipal, atrav\u00e9s da Secretaria de Sa\u00fade (Sesau), vem alertar a popula\u00e7\u00e3o sobre a import\u00e2ncia da vacina\u00e7\u00e3o para preven\u00e7\u00e3o da doen\u00e7a.De janeiro a 2 de dezembro de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44065,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[139,2706,815,536],"class_list":["post-60070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-prevencao","tag-saude","tag-saude-publica","tag-sesau"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros.jpg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros-300x169.jpg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros.jpg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros.jpg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros.jpg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros.jpg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros.jpg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros-420x281.jpg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros-300x281.jpg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros-464x281.jpg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros.jpg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/vacina-contra-hpv-imunizacao-previne-o-cancer-de-colo-de-utero-e-outros.jpg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Juazeiro vem registrando aumentos de infec\u00e7\u00e3o pela Covid-19 no munic\u00edpio. Somente entre os dias 26 de novembro a 02 de dezembro foram registrados 49 casos da doen\u00e7a. A Prefeitura Municipal, atrav\u00e9s da Secretaria de Sa\u00fade (Sesau), vem alertar a popula\u00e7\u00e3o sobre a import\u00e2ncia da vacina\u00e7\u00e3o para preven\u00e7\u00e3o da doen\u00e7a.De janeiro a 2 de dezembro de&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=60070"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60070\/revisions"}],"predecessor-version":[{"id":60071,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60070\/revisions\/60071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/44065"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=60070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=60070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=60070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}