{"id":61007,"date":"2024-01-11T08:20:00","date_gmt":"2024-01-11T11:20:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=61007"},"modified":"2024-01-10T21:21:55","modified_gmt":"2024-01-11T00:21:55","slug":"governo-pretende-nacionalizar-producao-de-biocombustiveis","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/01\/11\/governo-pretende-nacionalizar-producao-de-biocombustiveis","title":{"rendered":"Governo pretende nacionalizar produ\u00e7\u00e3o de biocombust\u00edveis"},"content":{"rendered":"<p style=\"text-align: justify;\">O governo federal atualizar\u00e1 as regras do Selo Biocombust\u00edvel Social, de forma a garantir que metade das compras desse produto tenha como origem a agricultura familiar. Entre as mudan\u00e7as est\u00e1 a de nacionalizar a produ\u00e7\u00e3o, em especial para os estados das Regi\u00f5es Norte e Nordeste, incluindo tamb\u00e9m \u00e1reas do semi\u00e1rido, como o Vale do Jequitinhonha, em Minas Gerais.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">A reestrutura\u00e7\u00e3o do selo ser\u00e1 publicada em decreto presidencial, ap\u00f3s a vers\u00e3o final do texto a ser apresentada ao presidente Luiz In\u00e1cio Lula da Silva (PT). As informa\u00e7\u00f5es s\u00e3o da Ag\u00eancia Brasil.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Segundo o Minist\u00e9rio de Minas e Energia (MME), o novo texto traz mais transpar\u00eancia e fortalece os requisitos necess\u00e1rios \u00e0 concess\u00e3o e manuten\u00e7\u00e3o do instrumento pelos produtores do biocombust\u00edvel, bem como aproveitar a voca\u00e7\u00e3o das agriculturas locais, \u201cmelhorando a renda e a qualidade de vida do agricultor familiar em regi\u00f5es vulner\u00e1veis.\u201d<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Entre as medidas de est\u00edmulo \u00e0 produ\u00e7\u00e3o nacional est\u00e1 a antecipa\u00e7\u00e3o da mistura de biodiesel aos combust\u00edveis f\u00f3sseis para 14% a partir de abril, e 15% entre 2025 e 2026. A expectativa \u00e9 chegar a 25%, nos anos subsequentes, informou o ministro de Minas e Energia, Alexandre Silveira, nesta quarta-feira (10), em evento no qual apresentou alguns detalhes do decreto.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Com o aumento para 14% na mistura, o minist\u00e9rio projeta um crescimento de 3,05 milh\u00f5es de toneladas no processamento de soja para a produ\u00e7\u00e3o de biodiesel, o que refletir\u00e1 diretamente na demanda para pequenos agricultores. Tamb\u00e9m est\u00e3o previstos incentivos fiscais a quem produzir biocombust\u00edvel.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Al\u00e9m de reestruturar o Selo Biocombust\u00edvel Social, o decreto viabilizar\u00e1 investimentos para o agroneg\u00f3cio e setor de combust\u00edveis brasileiro. \u201cEm 2024 ser\u00e3o 740 milh\u00f5es, e em 2025, R$ 1,6 bilh\u00e3o\u201d, disse o ministro.<\/p>\n<h4 dir=\"ltr\" style=\"text-align: justify;\">Diversifica\u00e7\u00e3o<\/h4>\n<p dir=\"ltr\" style=\"text-align: justify;\">Tamb\u00e9m presente no evento, o ministro do Desenvolvimento Agr\u00e1rio e Agricultura Familiar, Paulo Teixeira, disse que entre os desafios previstos pelo governo, est\u00e1 o de diversificar os produtos que podem ser usados para a obten\u00e7\u00e3o de biodiesel, combust\u00edvel que pode ser derivado de sementes de mamona, bem como de milho, soja, girassol, cana e baba\u00e7u. O leque de op\u00e7\u00f5es pode incluir, por exemplo, a maca\u00faba, palmeira abundante na Regi\u00e3o Nordeste.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">A diretora de Inova\u00e7\u00e3o para a Produ\u00e7\u00e3o Familiar e Transi\u00e7\u00e3o Agroecol\u00f3gica do MDA, Vivian Lib\u00f3rio de Almeida, disse que o percentual de compras nas Regi\u00f5es Norte, Nordeste e no Semi\u00e1rido aumentar\u00e1 de forma escalonada at\u00e9 chegar a 20% do total. \u201cAtualmente, o programa atende 54 mil fam\u00edlias por ano. A expectativa \u00e9 ampliar para 70 mil fam\u00edlias, principalmente no Norte, Nordeste e semi\u00e1rido\u201d, explicou a diretora do MDA.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Segundo Paulo Teixeira, \u201co presidente Lula tem, neste tema, uma de suas predile\u00e7\u00f5es\u201d. O governo estuda tamb\u00e9m formas de baratear o custo da energia utilizada para irrigar as lavouras. \u201cA energia fotovoltaica pode reduzir o pre\u00e7o da energia. Precisamos pensar em modicidade tarif\u00e1ria\u201d, complementou.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><em>Fonte: Bahia Not\u00edcias<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo federal atualizar\u00e1 as regras do Selo Biocombust\u00edvel Social, de forma a garantir que metade das compras desse produto tenha como origem a agricultura familiar. Entre as mudan\u00e7as est\u00e1 a de nacionalizar a produ\u00e7\u00e3o, em especial para os estados das Regi\u00f5es Norte e Nordeste, incluindo tamb\u00e9m \u00e1reas do semi\u00e1rido, como o Vale do Jequitinhonha, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19214,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200,10110],"tags":[11297,14],"class_list":["post-61007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-desenvolvimento","tag-biocombustiveis","tag-brasil"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02.jpg",500,325,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02-300x195.jpg",300,195,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02.jpg",500,325,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02.jpg",500,325,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02.jpg",500,325,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02.jpg",500,325,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02.jpg",500,325,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02-300x325.jpg",300,325,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02.jpg",500,325,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Combustivel08.02.jpg",500,325,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O governo federal atualizar\u00e1 as regras do Selo Biocombust\u00edvel Social, de forma a garantir que metade das compras desse produto tenha como origem a agricultura familiar. Entre as mudan\u00e7as est\u00e1 a de nacionalizar a produ\u00e7\u00e3o, em especial para os estados das Regi\u00f5es Norte e Nordeste, incluindo tamb\u00e9m \u00e1reas do semi\u00e1rido, como o Vale do Jequitinhonha,&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=61007"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61007\/revisions"}],"predecessor-version":[{"id":61008,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61007\/revisions\/61008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/19214"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=61007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=61007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=61007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}