{"id":61262,"date":"2024-01-18T14:20:00","date_gmt":"2024-01-18T17:20:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=61262"},"modified":"2024-01-17T23:56:18","modified_gmt":"2024-01-18T02:56:18","slug":"nota-1000-de-candidato-pernambucano-no-enem-e-questionada","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/01\/18\/nota-1000-de-candidato-pernambucano-no-enem-e-questionada","title":{"rendered":"Nota 1000 de candidato pernambucano no Enem \u00e9 questionada"},"content":{"rendered":"<p style=\"text-align: justify;\">A\u00a0nota da reda\u00e7\u00e3o do Exame Nacional do Ensino M\u00e9dio (Enem) 2023 do estudante Igor Kleyverson da Silva, de 23 anos, est\u00e1 sendo questionada. O caso\u00a0est\u00e1 sendo apurado\u00a0pelo Instituto Nacional de Estudos e Pesquisas Educacionais (Inep).<\/p>\n<p style=\"text-align: justify;\">Em entrevista \u00e0 Folha de Pernambuco, Gabriel V\u00e9ras, diretor do curso\u00a0preparat\u00f3rio para o Enem\u00a0F\u00e1brica Concursos, localizado na\u00a0cidade de Escada, Mata Sul de Pernambuco, onde Gabriel estudou no primeiro semestre de 2023, contou que o aluno chegou a mostrar a nota no site oficial, mas n\u00e3o abriu a p\u00e1gina na frente dele.<\/p>\n<p style=\"text-align: justify;\">\u201cQuando liguei para ele e fui informado da nota, ficamos muito felizes, inclusive ele mandou um print da nota. Um resultado desses na nossa regi\u00e3o marcaria uma vit\u00f3ria n\u00e3o s\u00f3 do curso, mas da cidade. Ficamos euf\u00f3ricos. Buscamos ele e levamos para fazer fotos e divulgamos nas nossas redes sociais. Ele ficou um pouco nervoso, mas disse que n\u00e3o estava acostumado com os holofotes.\u00a0A partir da\u00ed, v\u00e1rias pessoas come\u00e7aram a compartilhar, e isso tomou uma propor\u00e7\u00e3o gigantesca\u201d, conta Gabriel.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s a repercuss\u00e3o, chegou uma\u00a0den\u00fancia que o candidato poderia ter alterado a nota na p\u00e1gina do site\u00a0porque constataram que as notas foram inferiores \u00e0s que constava no print e de quando ele havia mostrado ao diretor do curso &#8211; o gestor, por\u00e9m, n\u00e3o recorda os valores.<\/p>\n<p>De acordo com o pr\u00f3prio Igor, em v\u00eddeo publicado na internet nesta quarta, a irm\u00e3 dele contou que &#8220;um sujeito entrou em contato com ela&#8221; e informou que o candidato estava sendo investigado. Ainda segundo ele, a pessoa &#8220;tinha a senha da conta gov. dele&#8221; e que teria visto que as notas dele n\u00e3o eram altas como anteriormente divulgado.<\/p>\n<p>Segundo o aluno, o erro foi da pr\u00f3pria plataforma do Inep ou que tenha ocorrido algum ataque hacker &#8211; ele contou tamb\u00e9m que, quando entrou no sistema nesta quarta, os valores das notas eram diferentes. Igor disse\u00a0que, com um advogado, que tentou entrar em contato com o instituto para saber o que de fato aconteceu e aguarda respostas. A\u00a0Folha de Pernambuco\u00a0tentou contato com Igor na noite desta quarta, por\u00e9m sem sucesso.<\/p>\n<p style=\"text-align: justify;\">Confira o pronunciamento na \u00edntegra:<\/p>\n<div style=\"text-align: justify;\">\n<div>\n<div id=\"intext2\" class=\"div-gpt-ad\" data-sizes=\"336x280,300x250,250x250\" data-google-query-id=\"CPbVo9r35YMDFVS0lQIdnJoGPA\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\"><iframe id=\"instagram-embed-0\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/reel\/C2N96WyrmBo\/embed\/captioned\/?cr=1&amp;v=14&amp;wp=540&amp;rd=https%3A%2F%2Fwww.folhape.com.br&amp;rp=%2Fnoticias%2Fnota-1000-de-candidato-pernambucano-no-enem-esta-sendo-questionada%2F311763%2F#%7B%22ci%22%3A0%2C%22os%22%3A1393.0999999642372%2C%22ls%22%3A336.19999998807907%2C%22le%22%3A984.0999999642372%7D\" height=\"883\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-instgrm-payload-id=\"instagram-media-payload-0\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p style=\"text-align: justify;\">A den\u00fancia das notas inferiores chegou ao curso onde ele estudou, e o diretor disse agora aguardar a resposta do Inep ao aluno sobre o caso, ao mesmo tempo em que pretende, nesta quinta-feira (18), tamb\u00e9m entrar em contato com o instituto em busca de resposta sobre a situa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: revert; color: initial;\">\u201cQuando questionamos, ele nos disse que a culpa deveria ter sido do sistema. N\u00e3o podemos e n\u00e3o queremos acusar, ent\u00e3o estamos aguardando a nota oficial do Inep\u00a0sobre o caso para poder nos pronunciarmos, at\u00e9 para que possamos tomar \u00e0s medidas cab\u00edveis. Eu cheguei a ver um v\u00eddeo onde mostra que \u00e9 simples alterar a nota quando se abre o site, mas vamos aguardar\u201d, diz o diretor.<\/span><\/p>\n<p style=\"text-align: justify;\">O Inep\u00a0ainda n\u00e3o se pronunciou sobre o caso.<\/p>\n<p><em>Fonte: Folha PE<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0nota da reda\u00e7\u00e3o do Exame Nacional do Ensino M\u00e9dio (Enem) 2023 do estudante Igor Kleyverson da Silva, de 23 anos, est\u00e1 sendo questionada. O caso\u00a0est\u00e1 sendo apurado\u00a0pelo Instituto Nacional de Estudos e Pesquisas Educacionais (Inep). Em entrevista \u00e0 Folha de Pernambuco, Gabriel V\u00e9ras, diretor do curso\u00a0preparat\u00f3rio para o Enem\u00a0F\u00e1brica Concursos, localizado na\u00a0cidade de Escada, Mata [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25658,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[209,1507],"tags":[],"class_list":["post-61262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-pernambuco"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1.jpg",500,298,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1-300x179.jpg",300,179,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1.jpg",500,298,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1.jpg",500,298,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1.jpg",500,298,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1.jpg",500,298,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1.jpg",500,298,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1-420x298.jpg",420,298,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1-300x298.jpg",300,298,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1.jpg",500,298,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/taxa-do-Enem-696x416-1.jpg",500,298,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A\u00a0nota da reda\u00e7\u00e3o do Exame Nacional do Ensino M\u00e9dio (Enem) 2023 do estudante Igor Kleyverson da Silva, de 23 anos, est\u00e1 sendo questionada. O caso\u00a0est\u00e1 sendo apurado\u00a0pelo Instituto Nacional de Estudos e Pesquisas Educacionais (Inep). Em entrevista \u00e0 Folha de Pernambuco, Gabriel V\u00e9ras, diretor do curso\u00a0preparat\u00f3rio para o Enem\u00a0F\u00e1brica Concursos, localizado na\u00a0cidade de Escada, Mata&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=61262"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61262\/revisions"}],"predecessor-version":[{"id":61263,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61262\/revisions\/61263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/25658"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=61262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=61262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=61262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}