{"id":61388,"date":"2024-01-22T10:40:00","date_gmt":"2024-01-22T13:40:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=61388"},"modified":"2024-01-22T00:44:49","modified_gmt":"2024-01-22T03:44:49","slug":"ipj-comemora-13-anos-de-compromisso-com-o-futuro-dos-servidores-publicos-de-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/01\/22\/ipj-comemora-13-anos-de-compromisso-com-o-futuro-dos-servidores-publicos-de-juazeiro","title":{"rendered":"IPJ comemora 13 anos de compromisso com o futuro dos servidores p\u00fablicos de Juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\">O Instituto de Previd\u00eancia de Juazeiro (IPJ) celebra 13 anos de exist\u00eancia e compromisso com o futuro dos servidores p\u00fablicos de Juazeiro. Fundado em 21 de janeiro de 2011, o IPJ foi criado com o objetivo de garantir a seguran\u00e7a previdenci\u00e1ria para os servidores p\u00fablicos municipais.<\/p>\n<p style=\"text-align: justify;\">De acordo com o diretor-executivo do IPJ, Marcos Jorge de S\u00e1, o \u00f3rg\u00e3o tem buscado ao longo dos anos aprimorar-se e adotar as melhores pr\u00e1ticas de gest\u00e3o. \u201cO IPJ tem cumprido, com excel\u00eancia, a miss\u00e3o de gerir o processo de concess\u00e3o e pagamento de pens\u00f5es e aposentadorias dos servidores p\u00fablicos efetivos de Juazeiro e zelar pelo equil\u00edbrio financeiro do regime pr\u00f3prio de previd\u00eancia que garante estes benef\u00edcios\u201d, destacou o diretor-executivo.<\/p>\n<p style=\"text-align: justify;\">A professora, Maria Mazzarello, foi uma das primeiras aposentadas pelo IPJ e destaca a import\u00e2ncia de ter uma previd\u00eancia pr\u00f3pria para os servidores municipais. \u201cPara n\u00f3s, essa proximidade \u00e9 fundamental, acompanhar de perto e participar da gest\u00e3o. \u00c9 um reconhecimento pelos servi\u00e7os prestados \u00e0 sociedade juazeirense\u201d, disse a professora.<\/p>\n<p style=\"text-align: justify;\">Para a servidora, Maria Lucia do Vale, que se aposentou no ano passado, essa gest\u00e3o tem se notabilizado pelo acolhimento e a humaniza\u00e7\u00e3o. \u201cEm todos os processos at\u00e9 minha aposentadoria fui sempre bem atendida. \u00c9 maravilhoso ter, \u00e0 nossa disposi\u00e7\u00e3o, uma equipe sens\u00edvel e eficiente\u201d, conclui a aposentada.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Ascom\/IPJ\/PMJ<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto de Previd\u00eancia de Juazeiro (IPJ) celebra 13 anos de exist\u00eancia e compromisso com o futuro dos servidores p\u00fablicos de Juazeiro. Fundado em 21 de janeiro de 2011, o IPJ foi criado com o objetivo de garantir a seguran\u00e7a previdenci\u00e1ria para os servidores p\u00fablicos municipais. De acordo com o diretor-executivo do IPJ, Marcos Jorge [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61389,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10110,203],"tags":[11,143,340],"class_list":["post-61388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desenvolvimento","category-juazeiro","tag-bahia","tag-juazeiro-da-bahia","tag-prefeitura-de-juazeiro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1.jpg",500,292,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1-300x175.jpg",300,175,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1.jpg",500,292,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1.jpg",500,292,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1.jpg",500,292,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1.jpg",500,292,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1.jpg",500,292,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1-420x292.jpg",420,292,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1-300x292.jpg",300,292,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1.jpg",500,292,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-19-at-13.05.40-768x768-1.jpg",500,292,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O Instituto de Previd\u00eancia de Juazeiro (IPJ) celebra 13 anos de exist\u00eancia e compromisso com o futuro dos servidores p\u00fablicos de Juazeiro. Fundado em 21 de janeiro de 2011, o IPJ foi criado com o objetivo de garantir a seguran\u00e7a previdenci\u00e1ria para os servidores p\u00fablicos municipais. De acordo com o diretor-executivo do IPJ, Marcos Jorge&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=61388"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61388\/revisions"}],"predecessor-version":[{"id":61390,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61388\/revisions\/61390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/61389"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=61388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=61388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=61388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}