{"id":61434,"date":"2024-01-22T19:24:24","date_gmt":"2024-01-22T22:24:24","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=61434"},"modified":"2024-01-22T19:24:27","modified_gmt":"2024-01-22T22:24:27","slug":"em-inauguracao-de-praca-em-juremal-clesio-alexandre-elogia-servicos-realizados-por-suzana-ramos-e-reforca-seu-compromisso-com-distrito","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/01\/22\/em-inauguracao-de-praca-em-juremal-clesio-alexandre-elogia-servicos-realizados-por-suzana-ramos-e-reforca-seu-compromisso-com-distrito","title":{"rendered":"Em Inaugura\u00e7\u00e3o de pra\u00e7a em Juremal, Clesio Alexandre elogia servi\u00e7os realizados por Suzana Ramos e refor\u00e7a seu compromisso com distrito"},"content":{"rendered":"<p style=\"text-align: justify;\">Durante a cerim\u00f4nia de Inaugura\u00e7\u00e3o da Pra\u00e7a Professora Romilse Siqueira Santos, no distrito de Juremal, realizada na noite desta segunda-feira (20), o vereador Clesio Alexandre expressou seus elogios \u00e0 prefeita Suzana Ramos, agradecendo por atender sua solicita\u00e7\u00e3o de requalifica\u00e7\u00e3o da referida pra\u00e7a.<\/p>\n<p>Clesio reiterou seu compromisso com o distrito, enaltecendo as a\u00e7\u00f5es da prefeita Suzana Ramos em benef\u00edcio de toda a cidade de Juazeiro. Destacou iniciativas como o est\u00edmulo aos empreendedores locais e a oferta gratuita de refei\u00e7\u00f5es nos restaurantes populares, ressaltando o impacto positivo dessas medidas na vida da popula\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a cerim\u00f4nia de Inaugura\u00e7\u00e3o da Pra\u00e7a Professora Romilse Siqueira Santos, no distrito de Juremal, realizada na noite desta segunda-feira (20), o vereador Clesio Alexandre expressou seus elogios \u00e0 prefeita Suzana Ramos, agradecendo por atender sua solicita\u00e7\u00e3o de requalifica\u00e7\u00e3o da referida pra\u00e7a. Clesio reiterou seu compromisso com o distrito, enaltecendo as a\u00e7\u00f5es da prefeita Suzana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61435,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[1951,1115,11328,11131],"class_list":["post-61434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-camara-de-vereadores-de-juazeiro","tag-distrito-de-juremal","tag-irmao-de-suzana-ramos","tag-parlamento"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107.jpg",400,556,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107-216x300.jpg",216,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107.jpg",400,556,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107.jpg",400,556,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107.jpg",400,556,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107.jpg",400,556,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107.jpg",400,556,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107-400x307.jpg",400,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107-300x443.jpg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107-400x290.jpg",400,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107-400x500.jpg",400,500,true],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/01\/Captura-de-tela-2024-01-22-192107.jpg",400,556,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Durante a cerim\u00f4nia de Inaugura\u00e7\u00e3o da Pra\u00e7a Professora Romilse Siqueira Santos, no distrito de Juremal, realizada na noite desta segunda-feira (20), o vereador Clesio Alexandre expressou seus elogios \u00e0 prefeita Suzana Ramos, agradecendo por atender sua solicita\u00e7\u00e3o de requalifica\u00e7\u00e3o da referida pra\u00e7a. Clesio reiterou seu compromisso com o distrito, enaltecendo as a\u00e7\u00f5es da prefeita Suzana&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=61434"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61434\/revisions"}],"predecessor-version":[{"id":61436,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61434\/revisions\/61436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/61435"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=61434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=61434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=61434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}