{"id":61789,"date":"2024-02-02T13:20:00","date_gmt":"2024-02-02T16:20:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=61789"},"modified":"2024-02-01T23:48:38","modified_gmt":"2024-02-02T02:48:38","slug":"hospital-regional-de-juazeiro-realiza-processo-seletivo-para-a-contratacao-de-ajudante-de-cozinha","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/02\/02\/hospital-regional-de-juazeiro-realiza-processo-seletivo-para-a-contratacao-de-ajudante-de-cozinha","title":{"rendered":"Hospital Regional de Juazeiro realiza processo seletivo para a contrata\u00e7\u00e3o de ajudante de cozinha"},"content":{"rendered":"<p style=\"text-align: justify;\">O Hospital Regional de Juazeiro,\u00a0complexo hospitalar administrado pelas Obras Sociais Irm\u00e3 Dulce (OSID),\u00a0est\u00e1 com novo processo seletivo aberto para o cargo de ajudante de cozinha\u00a0(cadastro reserva).<\/p>\n<p style=\"text-align: justify;\">Os interessados devem enviar o curr\u00edculo anexado em formato PDF atrav\u00e9s do endere\u00e7o\u00a0<em>curriculo.hrj@irmadulce.org.br<\/em>\u00a0entre os dias\u00a01\u00ba e 09 de fevereiro. No\u00a0assunto do e-mail, deve ser informado o nome da vaga\u00a0em quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Podem participar da sele\u00e7\u00e3o candidatos com ensino m\u00e9dio completo.\u00a0Al\u00e9m disso, \u00e9 desej\u00e1vel que o candidato possua\u00a0experi\u00eancia na \u00e1rea.\u00a0Tamb\u00e9m \u00e9 desej\u00e1vel que tenha curso de boas pr\u00e1ticas na manipula\u00e7\u00e3o de alimentos.<\/p>\n<p style=\"text-align: justify;\">A vaga possui carga hor\u00e1ria de 44 horas semanais e, tamb\u00e9m, est\u00e1 dispon\u00edvel para pessoas com defici\u00eancia.<\/p>\n<p style=\"text-align: justify;\">Fonte: Blog do Waldiney Passos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Hospital Regional de Juazeiro,\u00a0complexo hospitalar administrado pelas Obras Sociais Irm\u00e3 Dulce (OSID),\u00a0est\u00e1 com novo processo seletivo aberto para o cargo de ajudante de cozinha\u00a0(cadastro reserva). Os interessados devem enviar o curr\u00edculo anexado em formato PDF atrav\u00e9s do endere\u00e7o\u00a0curriculo.hrj@irmadulce.org.br\u00a0entre os dias\u00a01\u00ba e 09 de fevereiro. No\u00a0assunto do e-mail, deve ser informado o nome da vaga\u00a0em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49475,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,1505],"tags":[2123,143],"class_list":["post-61789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-oportunidade","tag-hospital-regional-de-juazeiro","tag-juazeiro-da-bahia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/02\/Hospital_regional_juazeiro-1.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O Hospital Regional de Juazeiro,\u00a0complexo hospitalar administrado pelas Obras Sociais Irm\u00e3 Dulce (OSID),\u00a0est\u00e1 com novo processo seletivo aberto para o cargo de ajudante de cozinha\u00a0(cadastro reserva). Os interessados devem enviar o curr\u00edculo anexado em formato PDF atrav\u00e9s do endere\u00e7o\u00a0curriculo.hrj@irmadulce.org.br\u00a0entre os dias\u00a01\u00ba e 09 de fevereiro. No\u00a0assunto do e-mail, deve ser informado o nome da vaga\u00a0em&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=61789"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61789\/revisions"}],"predecessor-version":[{"id":61790,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61789\/revisions\/61790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/49475"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=61789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=61789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=61789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}