{"id":61791,"date":"2024-02-02T14:35:00","date_gmt":"2024-02-02T17:35:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=61791"},"modified":"2024-02-01T23:58:16","modified_gmt":"2024-02-02T02:58:16","slug":"justica-determina-regularizacao-de-unidade-de-saude-da-familia-em-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/02\/02\/justica-determina-regularizacao-de-unidade-de-saude-da-familia-em-juazeiro","title":{"rendered":"Justi\u00e7a determina regulariza\u00e7\u00e3o de unidade de sa\u00fade da fam\u00edlia em Juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\">Atendendo \u00e0 solicita\u00e7\u00e3o do Minist\u00e9rio P\u00fablico estadual, atrav\u00e9s de uma a\u00e7\u00e3o civil p\u00fablica em car\u00e1ter liminar, a Justi\u00e7a determinou que o Munic\u00edpio de Juazeiro regularize a Unidade B\u00e1sica de Sa\u00fade (UBS) Ad\u00e1lia Joana de Oliveira\/Jardim Fl\u00f3rida, no Munic\u00edpio de Juazeiro, em um prazo de 60 dias.<\/p>\n<p style=\"text-align: justify;\">As irregularidades abrangem desde o desvio de fun\u00e7\u00e3o dos servidores at\u00e9 quest\u00f5es estruturais, como reparos em paredes danificadas e \u00e1reas descobertas.<\/p>\n<p style=\"text-align: justify;\">O Munic\u00edpio deve providenciar a adequa\u00e7\u00e3o do espa\u00e7o destinado ao departamento de material de limpeza, armazenamento e descarte de lixo; implementar um programa de sa\u00fade com atendimento de qualidade; aderir ao suporte para telesa\u00fade; e garantir a entrega pontual dos resultados de triagem pr\u00e9 natal.<\/p>\n<p style=\"text-align: justify;\">O inqu\u00e9rito civil foi instaurado pelo MP para investigar as condi\u00e7\u00f5es da UBS, quando foram identificadas irregularidades que demandam interven\u00e7\u00f5es imediatas. \u201cEsse conjunto de medidas visa n\u00e3o apenas corrigir as defici\u00eancias presentes na unidade, mas tamb\u00e9m assegurar que ela atenda aos padr\u00f5es adequados de funcionamento\u201d, destacou a promotora de Justi\u00e7a Rita de C\u00e1ssia Rodrigues, autora da a\u00e7\u00e3o.<\/p>\n<div style=\"text-align: justify;\"><em>Fonte: Cecom MP-BA<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Atendendo \u00e0 solicita\u00e7\u00e3o do Minist\u00e9rio P\u00fablico estadual, atrav\u00e9s de uma a\u00e7\u00e3o civil p\u00fablica em car\u00e1ter liminar, a Justi\u00e7a determinou que o Munic\u00edpio de Juazeiro regularize a Unidade B\u00e1sica de Sa\u00fade (UBS) Ad\u00e1lia Joana de Oliveira\/Jardim Fl\u00f3rida, no Munic\u00edpio de Juazeiro, em um prazo de 60 dias. As irregularidades abrangem desde o desvio de fun\u00e7\u00e3o dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61792,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,210],"tags":[143],"class_list":["post-61791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-justica","tag-juazeiro-da-bahia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24.jpg",500,375,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24-300x225.jpg",300,225,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24.jpg",500,375,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24.jpg",500,375,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24.jpg",500,375,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24.jpg",500,375,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24.jpg",500,375,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24-300x375.jpg",300,375,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24.jpg",500,375,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/2017-09-24.jpg",500,375,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Atendendo \u00e0 solicita\u00e7\u00e3o do Minist\u00e9rio P\u00fablico estadual, atrav\u00e9s de uma a\u00e7\u00e3o civil p\u00fablica em car\u00e1ter liminar, a Justi\u00e7a determinou que o Munic\u00edpio de Juazeiro regularize a Unidade B\u00e1sica de Sa\u00fade (UBS) Ad\u00e1lia Joana de Oliveira\/Jardim Fl\u00f3rida, no Munic\u00edpio de Juazeiro, em um prazo de 60 dias. As irregularidades abrangem desde o desvio de fun\u00e7\u00e3o dos&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=61791"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61791\/revisions"}],"predecessor-version":[{"id":61794,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61791\/revisions\/61794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/61792"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=61791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=61791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=61791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}