{"id":61917,"date":"2024-02-06T18:52:13","date_gmt":"2024-02-06T21:52:13","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=61917"},"modified":"2024-02-06T18:52:15","modified_gmt":"2024-02-06T21:52:15","slug":"vereador-lourival-quirino-anuncia-revitalizacao-da-praca-da-paz-no-bairro-santo-antonio","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/02\/06\/vereador-lourival-quirino-anuncia-revitalizacao-da-praca-da-paz-no-bairro-santo-antonio","title":{"rendered":"Vereador Lourival Quirino anuncia revitaliza\u00e7\u00e3o da pra\u00e7a da Paz no bairro Santo Antonio"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: justify;\">O vereador Lourival Quirino anunciou nesta segunda-feira (5), que mais uma revitaliza\u00e7\u00e3o que indicada por ele foi atendida pela prefeita Suzana Ramos, desta feita a pra\u00e7a da Paz foi a contemplada.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">\u201cNo dia 15 de fevereiro vai ser realizada a licita\u00e7\u00e3o de revitaliza\u00e7\u00e3o da pra\u00e7a da Paz no bairro Santo Ant\u00f4nio, um pedido realizado pela gente e que foi atendido por nossa prefeita Suzana Ramos.\u201d<\/p>\n<p>O projeto de revitaliza\u00e7\u00e3o vai contar com academia da sa\u00fade, parque infantil, ilumina\u00e7\u00e3o de LED e muitas outras coisas que ir\u00e3o beneficiar os moradores do Bairro Santo Ant\u00f4nio.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Agradecemos a nossa prefeita Suzana Ramos e vamos continuar trabalhando em prol da nossa popula\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vereador Lourival Quirino anunciou nesta segunda-feira (5), que mais uma revitaliza\u00e7\u00e3o que indicada por ele foi atendida pela prefeita Suzana Ramos, desta feita a pra\u00e7a da Paz foi a contemplada. \u201cNo dia 15 de fevereiro vai ser realizada a licita\u00e7\u00e3o de revitaliza\u00e7\u00e3o da pra\u00e7a da Paz no bairro Santo Ant\u00f4nio, um pedido realizado pela [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61918,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[83,11131,4887],"class_list":["post-61917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-comunidade","tag-parlamento","tag-vereador-lourival-quirino"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13.jpg",500,304,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13-300x182.jpg",300,182,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13.jpg",500,304,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13.jpg",500,304,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13.jpg",500,304,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13.jpg",500,304,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13.jpg",500,304,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13-420x304.jpg",420,304,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13-300x304.jpg",300,304,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13.jpg",500,304,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Whats-App-Image-2024-02-05-at-23-43-13.jpg",500,304,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O vereador Lourival Quirino anunciou nesta segunda-feira (5), que mais uma revitaliza\u00e7\u00e3o que indicada por ele foi atendida pela prefeita Suzana Ramos, desta feita a pra\u00e7a da Paz foi a contemplada. \u201cNo dia 15 de fevereiro vai ser realizada a licita\u00e7\u00e3o de revitaliza\u00e7\u00e3o da pra\u00e7a da Paz no bairro Santo Ant\u00f4nio, um pedido realizado pela&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=61917"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61917\/revisions"}],"predecessor-version":[{"id":61919,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/61917\/revisions\/61919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/61918"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=61917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=61917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=61917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}