{"id":62024,"date":"2024-02-10T11:29:00","date_gmt":"2024-02-10T14:29:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=62024"},"modified":"2024-02-09T22:31:59","modified_gmt":"2024-02-10T01:31:59","slug":"ammpla-informa-horario-dos-corujoes-durante-o-carnaval-de-petrolina","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/02\/10\/ammpla-informa-horario-dos-corujoes-durante-o-carnaval-de-petrolina","title":{"rendered":"AMMPLA informa hor\u00e1rio dos \u201ccoruj\u00f5es\u201d durante o Carnaval de Petrolina"},"content":{"rendered":"<p style=\"text-align: justify;\">A Prefeitura de Petrolina, atrav\u00e9s da Autarquia Municipal de Mobilidade de Petrolina (AMMPLA), informa aos foli\u00f5es que v\u00e3o curtir o Carnaval na cidade o hor\u00e1rio dos \u201ccoruj\u00f5es\u201d (transporte coletivo) e os locais de t\u00e1xi, motot\u00e1xis e motoristas por aplicativos pr\u00f3ximos aos polos.<\/p>\n<p style=\"text-align: justify;\">A folia come\u00e7a neste s\u00e1bado (10) e segue at\u00e9 a ter\u00e7a-feira (13). Durante os quatro dias de festa carnavalesca, os \u201ccoruj\u00f5es\u201d ir\u00e3o trafegar de meia-noite at\u00e9 \u00e0s 4h da manh\u00e3.<\/p>\n<p style=\"text-align: justify;\">Quatro \u00f4nibus estar\u00e3o \u00e0 disposi\u00e7\u00e3o dos foli\u00f5es, sendo dois \u00f4nibus para a Zona Leste da cidade e dois para a Zona Oeste (todos os bairros ser\u00e3o atendidos). Os locais de embarque e desembarque ser\u00e3o no Banco Ita\u00fa e no Col\u00e9gio Nossa Senhora Auxiliadora. Ser\u00e1 cobrado o valor da tarifa atual R$ 5.<\/p>\n<p style=\"text-align: justify;\">Os pontos de t\u00e1xi ser\u00e3o localizados na Avenida Cardoso de S\u00e1 (em frente ao ponto das barquinhas) e na Rua Joaquim Nabuco (na Pra\u00e7a Maria Auxiliadora). Os mototaxistas estar\u00e3o em frente do Posto Orla e na Rua Joaquim Nabuco (na lateral do Banco Ita\u00fa).\u00a0 J\u00e1 os motoristas por aplicativo ficar\u00e3o na Rua Jo\u00e3o Clementino (lateral da Pra\u00e7a Maria Auxiliadora).<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Blog do Waldiney Passos<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Petrolina, atrav\u00e9s da Autarquia Municipal de Mobilidade de Petrolina (AMMPLA), informa aos foli\u00f5es que v\u00e3o curtir o Carnaval na cidade o hor\u00e1rio dos \u201ccoruj\u00f5es\u201d (transporte coletivo) e os locais de t\u00e1xi, motot\u00e1xis e motoristas por aplicativos pr\u00f3ximos aos polos. A folia come\u00e7a neste s\u00e1bado (10) e segue at\u00e9 a ter\u00e7a-feira (13). Durante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":62025,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1504,851],"tags":[11359,58],"class_list":["post-62024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidade","category-petrolina","tag-carnaval-petrolina-2024","tag-petrolina"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157.png","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157.png",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157-150x150.png",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157-300x169.png",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157.png",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157.png",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157.png",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157.png",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157.png",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157-420x281.png",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157-300x281.png",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157-464x281.png",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157.png",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157-322x230.png",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/Sem-titulo-157.png",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A Prefeitura de Petrolina, atrav\u00e9s da Autarquia Municipal de Mobilidade de Petrolina (AMMPLA), informa aos foli\u00f5es que v\u00e3o curtir o Carnaval na cidade o hor\u00e1rio dos \u201ccoruj\u00f5es\u201d (transporte coletivo) e os locais de t\u00e1xi, motot\u00e1xis e motoristas por aplicativos pr\u00f3ximos aos polos. A folia come\u00e7a neste s\u00e1bado (10) e segue at\u00e9 a ter\u00e7a-feira (13). Durante&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=62024"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62024\/revisions"}],"predecessor-version":[{"id":62026,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62024\/revisions\/62026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/62025"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=62024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=62024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=62024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}