{"id":62168,"date":"2024-02-18T07:21:00","date_gmt":"2024-02-18T10:21:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=62168"},"modified":"2024-02-17T20:23:38","modified_gmt":"2024-02-17T23:23:38","slug":"prefeita-suzana-ramos-visita-obra-em-andamento-do-colegio-paulo-vi-em-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/02\/18\/prefeita-suzana-ramos-visita-obra-em-andamento-do-colegio-paulo-vi-em-juazeiro","title":{"rendered":"Prefeita Suzana Ramos visita obra em andamento do Col\u00e9gio Paulo VI em Juazeiro"},"content":{"rendered":"<div style=\"text-align: justify;\">A prefeita, Suzana Ramos, visitou na tarde desta sexta-feira (16), as obras da Escola Municipal de Tempo Integral Paulo VI. A gestora avalia o andamento da obra de requalifica\u00e7\u00e3o e amplia\u00e7\u00e3o da unidade de ensino, que conta com um investimento de mais de R$ 7 milh\u00f5es, realizado com recursos pr\u00f3prios.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Acompanhada da equipe de engenharia da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc), da chefe de gabinete, Fernanda Barros, e da superintendente Administrativo e Financeiro da Seduc, Marileide Jeric\u00f3, a prefeita Suzana Ramos, se mostrou satisfeita em realizar a reforma de requalifica\u00e7\u00e3o e amplia\u00e7\u00e3o da unidade de ensino mais antiga do munic\u00edpio, al\u00e9m de contemplar mais de 60 outras escolas com obras de reestrutura\u00e7\u00e3o e construir uma creche nova.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u201cA Escola Paulo VI recebeu o investimento mais alto entre as mais de 60 obras de requalifica\u00e7\u00e3o j\u00e1 realizadas ou em execu\u00e7\u00e3o na Educa\u00e7\u00e3o, isso porque, o projeto arquitet\u00f4nico de reforma da escola contempla uma proposta estrutural totalmente inovadora, com ambiente educacional favor\u00e1vel \u00e0 pr\u00e1tica de esportes, acesso \u00e0 cultura, incentivo \u00e0 ci\u00eancia, acolhimento psicol\u00f3gico e muito mais. O Paulo VI j\u00e1 \u00e9 sin\u00f4nimo de tradi\u00e7\u00e3o, reconhecida como a unidade de ensino mais antiga do munic\u00edpio e agora deve se consolidar como uma refer\u00eancia em desenvolvimento e \u00eaxitos no ensino p\u00fablico da nossa Juazeiro\u201d, destacou Suzana Ramos.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">O projeto<\/div>\n<div style=\"text-align: justify;\">O projeto arquitet\u00f4nico de reforma da Escola Paulo VI ir\u00e1 contemplar sistema fotovoltaico, sala de pilates, pista de salto, anfiteatro com cobertura, salas poliesportivas, jogos, produ\u00e7\u00e3o, Psicologia, rob\u00f3tica, m\u00fasica, laborat\u00f3rios de ci\u00eancias e matem\u00e1ticas, sala de aula multiuso com lousa interativa, escov\u00f3dromo, audit\u00f3rio independente, padaria, mobili\u00e1rio paisag\u00edstico, climatiza\u00e7\u00e3o, acessibilidade, entre outras benfeitorias e inova\u00e7\u00f5es.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">A Obra<\/div>\n<div style=\"text-align: justify;\">Atualmente, a obra de reforma da Escola Paulo VI encontra-se em fase de execu\u00e7\u00e3o da aplica\u00e7\u00e3o do revestimento cer\u00e2mico nas paredes das salas de aulas e nas \u00e1reas administrativas, al\u00e9m da implanta\u00e7\u00e3o da nova estrutura met\u00e1lica da cobertura da \u00e1rea administrativa, fixa\u00e7\u00e3o da calha de concreto para frenagem e da nova instala\u00e7\u00e3o el\u00e9trica.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Texto: Camila Santana \u2013 Ascom Seduc\/PMJ<\/div>\n<div style=\"text-align: justify;\">Fotos: Ayrton Latapiat \u2013 Ascom\/PMJ<\/div>\n<div style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A prefeita, Suzana Ramos, visitou na tarde desta sexta-feira (16), as obras da Escola Municipal de Tempo Integral Paulo VI. A gestora avalia o andamento da obra de requalifica\u00e7\u00e3o e amplia\u00e7\u00e3o da unidade de ensino, que conta com um investimento de mais de R$ 7 milh\u00f5es, realizado com recursos pr\u00f3prios. Acompanhada da equipe de engenharia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":62169,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[902,1508,10266],"class_list":["post-62168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-seduc","tag-suzana-ramos","tag-wank-medrado"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03.jpg",500,312,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03-300x187.jpg",300,187,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03.jpg",500,312,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03.jpg",500,312,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03.jpg",500,312,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03.jpg",500,312,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03.jpg",500,312,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03-300x312.jpg",300,312,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03.jpg",500,312,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/02\/thumbnail_WhatsApp-Image-2024-02-16-at-17.51.03.jpg",500,312,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A prefeita, Suzana Ramos, visitou na tarde desta sexta-feira (16), as obras da Escola Municipal de Tempo Integral Paulo VI. A gestora avalia o andamento da obra de requalifica\u00e7\u00e3o e amplia\u00e7\u00e3o da unidade de ensino, que conta com um investimento de mais de R$ 7 milh\u00f5es, realizado com recursos pr\u00f3prios. Acompanhada da equipe de engenharia&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=62168"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62168\/revisions"}],"predecessor-version":[{"id":62170,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/62168\/revisions\/62170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/62169"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=62168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=62168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=62168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}