{"id":63020,"date":"2024-03-14T22:11:18","date_gmt":"2024-03-15T01:11:18","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=63020"},"modified":"2024-03-15T08:15:21","modified_gmt":"2024-03-15T11:15:21","slug":"sete-anos-do-assassinato-covarde-do-adalberto-gonzaga-ex-coordenador-da-defesa-civil-de-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/03\/14\/sete-anos-do-assassinato-covarde-do-adalberto-gonzaga-ex-coordenador-da-defesa-civil-de-juazeiro","title":{"rendered":"Sete anos do assassinato covarde do Adalberto Gonzaga, ex-Coordenador da Defesa Civil de Juazeiro"},"content":{"rendered":"<header class=\"entry-header\">\n<p class=\"entry-title\" style=\"text-align: justify;\"><span style=\"font-size: revert; color: initial;\">Passados sete que assassinaram Adalberto de Carvalho Gonzaga, de 54 anos, pai de fam\u00edlia e exemplo de comprometimento com as suas obriga\u00e7\u00f5es profissionais, o mesmo foi morto no come\u00e7o da noite do dia 23 de fevereiro de 2017, at\u00e9 hoje n\u00e3o se sabe quem mandou matar e por que. Nenhum acusado estar preso.<\/span><\/p>\n<\/header>\n<div class=\"entry-content\">\n<p style=\"text-align: justify;\">Em outubro de 2017, a Pol\u00edcia Civil (PC) havia anunciado os poss\u00edveis suspeitos do assassinato do ex-coordenador da Defesa Civil de Juazeiro, que exerceu a fun\u00e7\u00e3o durante o governo Isaac Carvalho, e&nbsp; tamb\u00e9m era conselheiro do Conselho Municipal da Defesa Civil, que tem como atribui\u00e7\u00e3o fiscalizar as aplica\u00e7\u00f5es dos recursos.<\/p>\n<p style=\"text-align: justify;\">Na \u00e9poca a titular da 17\u00aa Coordenadoria de Pol\u00edcia do Interior&nbsp;<strong>(Coorpin<\/strong>), a Delegada Regional L\u00edgia Nunes, havia afirmado que o caso continuava sendo apurado, inclusive com a identifica\u00e7\u00e3o dos suspeitos de terem praticado o crime. Segundo a delegada, as investiga\u00e7\u00f5es estavam avan\u00e7adas, \u201cfaltando alguns dados para confirmar e pedir a pris\u00e3o \u201c.<\/p>\n<p style=\"text-align: justify;\">As perguntas que se fazem s\u00e3o:&nbsp; Quem mandou matar? Quem executou? Por qu\u00ea? A sociedade, os amigos e familiares de Adalberto Gonzaga aguardam uma resposta!<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Passados sete que assassinaram Adalberto de Carvalho Gonzaga, de 54 anos, pai de fam\u00edlia e exemplo de comprometimento com as suas obriga\u00e7\u00f5es profissionais, o mesmo foi morto no come\u00e7o da noite do dia 23 de fevereiro de 2017, at\u00e9 hoje n\u00e3o se sabe quem mandou matar e por que. Nenhum acusado estar preso. Em outubro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":63023,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[1448,170,1217,12],"class_list":["post-63020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-impunidade","tag-justica","tag-recursos-publicos","tag-saae"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA.jpeg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA-300x169.jpeg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA.jpeg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA.jpeg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA.jpeg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA.jpeg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA.jpeg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA-420x281.jpeg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA-300x281.jpeg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA-464x281.jpeg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA.jpeg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/ADALBERTO-GONZAGA.jpeg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Passados sete que assassinaram Adalberto de Carvalho Gonzaga, de 54 anos, pai de fam\u00edlia e exemplo de comprometimento com as suas obriga\u00e7\u00f5es profissionais, o mesmo foi morto no come\u00e7o da noite do dia 23 de fevereiro de 2017, at\u00e9 hoje n\u00e3o se sabe quem mandou matar e por que. Nenhum acusado estar preso. Em outubro&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=63020"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63020\/revisions"}],"predecessor-version":[{"id":63024,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63020\/revisions\/63024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/63023"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=63020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=63020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=63020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}