{"id":63159,"date":"2024-03-19T14:35:00","date_gmt":"2024-03-19T17:35:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=63159"},"modified":"2024-03-18T20:37:23","modified_gmt":"2024-03-18T23:37:23","slug":"juazeiro-transito-no-entorno-do-mercado-do-produtor-e-um-caos","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/03\/19\/juazeiro-transito-no-entorno-do-mercado-do-produtor-e-um-caos","title":{"rendered":"Juazeiro : Tr\u00e2nsito no entorno do Mercado do Produtor \u00e9 um caos\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\">Comerciantes e usu\u00e1rios do Mercado do Produtor de Juazeiro (BA) cobram uma solu\u00e7\u00e3o do \u00f3rg\u00e3o de tr\u00e2nsito sobre caminh\u00f5es que estacionam na via e atrapalham quem vende mercadoria na \u00e1rea externa do Ceasa.<\/p>\n<p style=\"text-align: justify;\">\u201cEles pegam estacionam os ve\u00edculos um do lado do outro sem garantia de passagem pela rua, o tr\u00e2nsito fica complicado, a gene n\u00e3o consegue passar, n\u00e3o tem uma fiscaliza\u00e7\u00e3o\u201d, ressalta o leitor.<\/p>\n<p style=\"text-align: justify;\">De acordo com informa\u00e7\u00f5es, \u201cessa situa\u00e7\u00e3o ocorre de segunda-feira a s\u00e1bado, ve\u00edculos encostando um ao lado do outro para descarregar com risco at\u00e9 de ocorrer uma briga, isso acontece principalmente na parte da manh\u00e3, um caos\u201d, completa.<\/p>\n<p style=\"text-align: justify;\">Fonte de informa\u00e7\u00f5es: Edenevaldo Alves<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comerciantes e usu\u00e1rios do Mercado do Produtor de Juazeiro (BA) cobram uma solu\u00e7\u00e3o do \u00f3rg\u00e3o de tr\u00e2nsito sobre caminh\u00f5es que estacionam na via e atrapalham quem vende mercadoria na \u00e1rea externa do Ceasa. \u201cEles pegam estacionam os ve\u00edculos um do lado do outro sem garantia de passagem pela rua, o tr\u00e2nsito fica complicado, a gene [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":63160,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10069],"tags":[11456,1804],"class_list":["post-63159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado-do-produtor","tag-desordem","tag-mobilidade-urbana"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos.jpeg",500,419,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos-300x251.jpeg",300,251,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos.jpeg",500,419,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos.jpeg",500,419,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos.jpeg",500,419,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos.jpeg",500,419,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos.jpeg",500,419,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos-300x419.jpeg",300,419,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos.jpeg",500,419,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/03\/caos.jpeg",500,419,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Comerciantes e usu\u00e1rios do Mercado do Produtor de Juazeiro (BA) cobram uma solu\u00e7\u00e3o do \u00f3rg\u00e3o de tr\u00e2nsito sobre caminh\u00f5es que estacionam na via e atrapalham quem vende mercadoria na \u00e1rea externa do Ceasa. \u201cEles pegam estacionam os ve\u00edculos um do lado do outro sem garantia de passagem pela rua, o tr\u00e2nsito fica complicado, a gene&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=63159"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63159\/revisions"}],"predecessor-version":[{"id":63161,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63159\/revisions\/63161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/63160"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=63159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=63159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=63159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}