{"id":63354,"date":"2024-03-24T18:58:00","date_gmt":"2024-03-24T21:58:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=63354"},"modified":"2024-03-23T20:59:09","modified_gmt":"2024-03-23T23:59:09","slug":"prefeitura-de-juazeiro-convoca-candidatos-aprovados-em-processo-seletivo-da-educacao","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/03\/24\/prefeitura-de-juazeiro-convoca-candidatos-aprovados-em-processo-seletivo-da-educacao","title":{"rendered":"Prefeitura de Juazeiro convoca candidatos aprovados em Processo Seletivo da Educa\u00e7\u00e3o"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\">A Prefeitura de Juazeiro, por meio da Secretaria de Gest\u00e3o de Pessoas (Segesp), divulgou, nesta quarta-feira (20), uma s\u00e9rie de convoca\u00e7\u00f5es para os aprovados em Processos Seletivos realizados para o preenchimento de vagas da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc). As listas, assim como a documenta\u00e7\u00e3o necess\u00e1ria para a posse dos candidatos, est\u00e3o dispon\u00edveis no Di\u00e1rio Oficial do Munic\u00edpio. A entrega dos documentos ser\u00e1 realizada nos dias 22 e 25 de mar\u00e7o de 2024, na Segesp, localizada na Rua 15 de Julho, n\u00ba 32, 2\u00ba andar, Centro, das 8h \u00e0s 14h.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">A admiss\u00e3o dos candidatos est\u00e1 sujeita ao cumprimento das condi\u00e7\u00f5es estabelecidas no edital. Candidatos que tenham mantido v\u00ednculo contratual em Regime Especial de Direito Administrativo com o Munic\u00edpio de Juazeiro, Estado da Bahia, nos \u00faltimos tr\u00eas meses a contar do t\u00e9rmino de seu contrato anterior, n\u00e3o poder\u00e3o ser contratados, conforme o disposto no art. 10, inciso III, da Lei Municipal n\u00ba 2.017\/2009, alterada pela Lei Municipal n\u00ba 2.321\/2012.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Para esclarecimento de d\u00favidas, os candidatos podem contatar diretamente a Segesp pelo telefone (74) 3612-3620 ou pelo e-mail:\u00a0<a id=\"LPlnk886024\" href=\"mailto:recepcao.segesp.pmj@gmail.com\" data-linkindex=\"0\">recepcao.segesp.pmj@gmail.com<\/a>.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Ascom\/PMJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Juazeiro, por meio da Secretaria de Gest\u00e3o de Pessoas (Segesp), divulgou, nesta quarta-feira (20), uma s\u00e9rie de convoca\u00e7\u00f5es para os aprovados em Processos Seletivos realizados para o preenchimento de vagas da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc). As listas, assim como a documenta\u00e7\u00e3o necess\u00e1ria para a posse dos candidatos, est\u00e3o dispon\u00edveis no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54872,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[],"class_list":["post-63354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/07\/Prefeitura-de-Juazeiro-Paco-Municipal.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A Prefeitura de Juazeiro, por meio da Secretaria de Gest\u00e3o de Pessoas (Segesp), divulgou, nesta quarta-feira (20), uma s\u00e9rie de convoca\u00e7\u00f5es para os aprovados em Processos Seletivos realizados para o preenchimento de vagas da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc). As listas, assim como a documenta\u00e7\u00e3o necess\u00e1ria para a posse dos candidatos, est\u00e3o dispon\u00edveis no&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=63354"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63354\/revisions"}],"predecessor-version":[{"id":63355,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63354\/revisions\/63355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/54872"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=63354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=63354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=63354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}