{"id":63850,"date":"2024-04-08T18:10:00","date_gmt":"2024-04-08T21:10:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=63850"},"modified":"2024-04-07T18:13:21","modified_gmt":"2024-04-07T21:13:21","slug":"nas-entrelinhas-esqueletos-da-bahia-assombram-o-palacio","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/04\/08\/nas-entrelinhas-esqueletos-da-bahia-assombram-o-palacio","title":{"rendered":"Nas Entrelinhas: Esqueletos da Bahia assombram o Pal\u00e1cio"},"content":{"rendered":"<p class=\"texto\" style=\"text-align: justify;\">Tudo que o\u00a0presidente Luiz In\u00e1cio Lula da Silva n\u00e3o precisava era de uma den\u00fancia de corrup\u00e7\u00e3o no governo da Bahia na gest\u00e3o do hoje ministro-chefe da Casa Civil, Rui Costa. A empres\u00e1ria Cristiana Prestes Tadeo, da empresa Hempcare, citou o ministro em dela\u00e7\u00e3o premiada, na investiga\u00e7\u00e3o da Pol\u00edcia Federal (PF) que apura fraude na compra de respiradores durante crise provocada pela pandemia de covid-19, em 2020. O ministro nega, mas o assunto \u00e9 nitroglicerina para o Pal\u00e1cio do Planalto.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">O caso foi revelado pelo rep\u00f3rter Hugo Marques, da revista\u00a0<em>Veja<\/em>. A empres\u00e1ria devolveu R$ 10 milh\u00f5es aos cofres p\u00fablicos, como contrapartida para ter benef\u00edcios processuais, al\u00e9m de dar detalhes e entregar documentos que comprovariam as irregularidades, como extratos banc\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">A Hempcare recebeu R$ 48 milh\u00f5es do governo da Bahia, mas n\u00e3o entregou nenhum respirador pulmonar. A ent\u00e3o vice-procuradora-geral da Rep\u00fablica, Lind\u00f4ra Ara\u00fajo, que foi o bra\u00e7o direito do ex-procurador-geral da Rep\u00fablica Augusto Aras, que \u00e9 baiano, negociou a dela\u00e7\u00e3o.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Segundo a\u00a0<em>Veja<\/em>, Cristiana admitiu que o contrato com a empresa Hempcare era desfavor\u00e1vel ao governo da Bahia. Uma das cl\u00e1usulas previa pagamento adiantado. Al\u00e9m disso, a empresa n\u00e3o possu\u00eda as documenta\u00e7\u00f5es necess\u00e1rias para importar equipamentos hospitalares e que nenhum agente p\u00fablico solicitou o certificado e registro da Anvisa.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Cristina teria recebido informa\u00e7\u00f5es privilegiadas e, por causa disso, apresentou proposta de pre\u00e7o de US$ 28.900 por respirador. O contrato para venda de 300 aparelhos respiradores totalizou R$ 48 milh\u00f5es, conforme cota\u00e7\u00e3o do d\u00f3lar \u00e0 \u00e9poca.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Rui era tamb\u00e9m presidente do Cons\u00f3rcio Nordeste, cujos estados receberiam os respiradores. A empres\u00e1ria disse que a contra\u00e7\u00e3o da empresa foi intermediada por um empres\u00e1rio que se apresentou como &#8220;amigo&#8221; do ent\u00e3o governador da Bahia e da mulher dele, Aline Peixoto.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">A situa\u00e7\u00e3o do hoje ministro se complicou porque o ex-secret\u00e1rio da Casa Civil do governo baiano, Bruno Dauster, disse em depoimento \u00e0 PF que recebeu sinal positivo de Rui para avan\u00e7ar nas tratativas com a Hempcare. O ent\u00e3o governador, segundo disse aos investigadores, foi o respons\u00e1vel por passar o contato de Dauster \u00e0 empresa.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">A Hempcare distribu\u00eda medicamentos \u00e0 base de canabidiol e tinha capital social de R$ 100 mil. Conforme os registros, a empresa s\u00f3 contava com dois funcion\u00e1rios. Como o contrato foi assinado, e o valor de R$ 48 milh\u00f5es adiantado, a empresa n\u00e3o conseguiu fazer a compra dos equipamentos na China nem no mercado nacional.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Diante do atraso, Rui determinou a abertura de inqu\u00e9rito na Pol\u00edcia Civil, mas a PF entrou no caso quando chegou ao Superior Tribunal de Justi\u00e7a (STJ), porque desvio de recursos do SUS s\u00e3o casos da esfera federal. \u00c0 \u00e9poca, havia uma grande pol\u00eamica entre o presidente Jair Bolsonaro, que denunciava irregularidades na compra de respiradores, e os governadores, que conseguiram na Justi\u00e7a que o SUS obtivesse as vacinas contra a covid-19. Bolsonaro \u00e9 negacionista e se recusou a tomar o imunizante, embora tenha conseguido um atestado falso de vacina\u00e7\u00e3o.<\/p>\n<div class=\"pub-ret pub-retangulo-interna--3\" style=\"text-align: justify;\">\n<div id=\"cb-publicidade-retangulo-interna-3-a\">\n<div id=\"google_ads_iframe_\/6887\/portal-correioweb\/correiobraziliense-com-br\/brasil-politica\/capa_15__container__\"><\/div>\n<\/div>\n<div id=\"cb-publicidade-retangulo-interna-3-b\">\n<h4 id=\"google_ads_iframe_\/6887\/portal-correioweb\/correiobraziliense-com-br\/brasil-politica\/capa_16__container__\"><span style=\"color: revert; font-size: revert; font-weight: revert;\">Danos de imagem<\/span><\/h4>\n<\/div>\n<\/div>\n<p class=\"texto\" style=\"text-align: justify;\">Por causa do inqu\u00e9rito, cresce o estresse entre Rui Costa e o diretor-geral da PF, Andrei Rodrigues, mantido no cargo pelo ministro da Justi\u00e7a, Ricardo Lewandowski. O vazamento da informa\u00e7\u00e3o aumentou a tens\u00e3o.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Os esqueletos nos arm\u00e1rios do governo da Bahia vieram bater \u00e0 porta do Pal\u00e1cio do Planalto num momento de queda de popularidade de Lula por conta do desempenho insatisfat\u00f3rio do governo. Tamb\u00e9m h\u00e1 muitas reclama\u00e7\u00f5es contra o ministro da Casa Civil de parte de seus colegas da Esplanada.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Por sorte, o Congresso est\u00e1 desmobilizado, com as sess\u00f5es suspensas na C\u00e2mara e baix\u00edssima frequ\u00eancia no Senado. Entretanto, a oposi\u00e7\u00e3o far\u00e1 muito barulho na pr\u00f3xima semana e os aliados &#8220;mui amigos&#8221; de Lula se aproveitar\u00e3o para aumentar o poder de barganha junto ao governo.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">O presidente \u00e9 muito grato a Rui pelo apoio eleitoral que teve na Bahia, decisivo para sua volta ao poder nas elei\u00e7\u00f5es de 2022. Tamb\u00e9m n\u00e3o \u00e9 de jogar ao mar os companheiros leais, sobretudo os que permaneceram ao seu lado no per\u00edodo em que esteve preso em Curitiba.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Mas tem que realizar um governo sem esc\u00e2ndalos, para exercer n\u00e3o s\u00f3 o poder pol\u00edtico, como tamb\u00e9m a lideran\u00e7a da sociedade. Sua elei\u00e7\u00e3o foi um cr\u00e9dito de confian\u00e7a que precisa ser honrado. Por isso, Rui n\u00e3o depende apenas da gratid\u00e3o de Lula para permanecer na\u00a0Casa Civil. O presidente precisa sobreviver ao desgaste da imagem.<\/p>\n<p>Fonte: Correio Braziliense<\/p>\n<div class=\"read-more\" style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tudo que o\u00a0presidente Luiz In\u00e1cio Lula da Silva n\u00e3o precisava era de uma den\u00fancia de corrup\u00e7\u00e3o no governo da Bahia na gest\u00e3o do hoje ministro-chefe da Casa Civil, Rui Costa. A empres\u00e1ria Cristiana Prestes Tadeo, da empresa Hempcare, citou o ministro em dela\u00e7\u00e3o premiada, na investiga\u00e7\u00e3o da Pol\u00edcia Federal (PF) que apura fraude na compra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46631,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199],"tags":[10136],"class_list":["post-63850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","tag-pt-da-bahia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1.png","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1.png",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1-150x150.png",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1-300x169.png",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1.png",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1.png",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1.png",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1.png",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1.png",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1-420x281.png",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1-300x281.png",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1-464x281.png",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1.png",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1-322x230.png",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/12\/ruicosta-lula-ricardoStuckert-InstLula-11jul2016-juazeiro-viaFotPub-848x477-1.png",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Tudo que o\u00a0presidente Luiz In\u00e1cio Lula da Silva n\u00e3o precisava era de uma den\u00fancia de corrup\u00e7\u00e3o no governo da Bahia na gest\u00e3o do hoje ministro-chefe da Casa Civil, Rui Costa. A empres\u00e1ria Cristiana Prestes Tadeo, da empresa Hempcare, citou o ministro em dela\u00e7\u00e3o premiada, na investiga\u00e7\u00e3o da Pol\u00edcia Federal (PF) que apura fraude na compra&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=63850"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63850\/revisions"}],"predecessor-version":[{"id":63851,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63850\/revisions\/63851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/46631"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=63850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=63850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=63850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}