{"id":64520,"date":"2024-04-29T10:39:00","date_gmt":"2024-04-29T13:39:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=64520"},"modified":"2024-04-28T18:57:03","modified_gmt":"2024-04-28T21:57:03","slug":"pdt-planeja-leo-prates-candidato-a-prefeito-em-2028-quer-manter-ana-paula-como-vice-de-bruno-reis","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/04\/29\/pdt-planeja-leo-prates-candidato-a-prefeito-em-2028-quer-manter-ana-paula-como-vice-de-bruno-reis","title":{"rendered":"PDT planeja Leo Prates candidato a prefeito em 2028, quer manter Ana Paula como vice de Bruno Reis"},"content":{"rendered":"<p style=\"text-align: justify;\">O presidente nacional licenciado do PDT e ministro da Previd\u00eancia, Carlos Lupi, disse que a vice-prefeita Ana Paula Matos, filiada ao partido, \u00e9 o \u00fanico nome indicado pela legenda para seguir na chapa do prefeito Bruno Reis (Uni\u00e3o) na disputa pela reelei\u00e7\u00e3o. Ele admitiu que o deputado federal Leo Prates, comandante municipal da sigla, nunca esteve cotado pelos pedetistas para ocupar o cargo. \u201cLeo sempre me disse que quer disputar a Prefeitura em 2028, e vamos trabalhar para que isso aconte\u00e7a\u201d, disse Lupi.<\/p>\n<p style=\"text-align: justify;\">O dirigente participou de uma coletiva nesta sexta-feira (26) em Salvador, ocorrida na sede estadual do partido, no bairro da Mouraria. Antes, ele almo\u00e7ou com Bruno Reis, no Pal\u00e1cio Thom\u00e9 de Souza, ao lado de mais de 20 lideran\u00e7as pedetistas baianas, entre as quais Leo Prates, Ana Paula, o presidente da sigla na Bahia, deputado federal F\u00e9lix Mendon\u00e7a J\u00fanior, o deputado estadual Emerson Penalva e os vereadores de Salvador Anderson Ninho, Roberta Ca\u00edres e D\u00e9bora Santana.<\/p>\n<p style=\"text-align: justify;\">No encontro com Bruno Reis, Lupi indicou oficialmente Ana Paula para permanecer na chapa. \u201cAgora a decis\u00e3o cabe ao prefeito, que tem at\u00e9 o prazo das conven\u00e7\u00f5es para decidir. Vamos aguardar, at\u00e9 porque isso passa tamb\u00e9m pela vontade dele e tamb\u00e9m dos demais partidos da base. Estamos esperan\u00e7osos porque Ana Paula tem feito um grande trabalho. \u00c9 o nosso nome natural. Mas n\u00e3o faremos exig\u00eancia e nem colocaremos faca no pesco\u00e7o de ningu\u00e9m\u201d, frisou o ministro.<\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s a coletiva, Lupi se reuniu com pr\u00e9-candidatos do PDT, tamb\u00e9m na Mouraria, em evento que acabou por se tornar um ato de apoio a Ana Paula para seguir na vice de Bruno Reis. A claque da vice-prefeita ocupava tanto a sede do partido quando a rua. A reuni\u00e3o acabou do lado de fora do pr\u00e9dio, que passa por reforma.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><span class=\"assinatura_exclusiva\">Pol\u00edtica Livre<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente nacional licenciado do PDT e ministro da Previd\u00eancia, Carlos Lupi, disse que a vice-prefeita Ana Paula Matos, filiada ao partido, \u00e9 o \u00fanico nome indicado pela legenda para seguir na chapa do prefeito Bruno Reis (Uni\u00e3o) na disputa pela reelei\u00e7\u00e3o. Ele admitiu que o deputado federal Leo Prates, comandante municipal da sigla, nunca [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64522,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199],"tags":[11523,3888,10113],"class_list":["post-64520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","tag-deputado-leo-prates","tag-eleicoes-2024","tag-leo-prates-2"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos.jpg",500,350,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos-300x210.jpg",300,210,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos.jpg",500,350,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos.jpg",500,350,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos.jpg",500,350,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos.jpg",500,350,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos.jpg",500,350,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos-300x350.jpg",300,350,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos.jpg",500,350,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/04\/Leo-Prates-Carlos-Lupi-Bruno-Reis-e-Ana-Paula-Matos.jpg",500,350,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O presidente nacional licenciado do PDT e ministro da Previd\u00eancia, Carlos Lupi, disse que a vice-prefeita Ana Paula Matos, filiada ao partido, \u00e9 o \u00fanico nome indicado pela legenda para seguir na chapa do prefeito Bruno Reis (Uni\u00e3o) na disputa pela reelei\u00e7\u00e3o. Ele admitiu que o deputado federal Leo Prates, comandante municipal da sigla, nunca&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/64520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=64520"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/64520\/revisions"}],"predecessor-version":[{"id":64523,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/64520\/revisions\/64523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/64522"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=64520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=64520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=64520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}