{"id":67169,"date":"2024-08-01T08:49:59","date_gmt":"2024-08-01T11:49:59","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=67169"},"modified":"2024-08-01T08:50:02","modified_gmt":"2024-08-01T11:50:02","slug":"petrolina-pl-oficializa-lara-cavalcanti-como-candidata-a-prefeita-e-professor-weliton-da-silva-como-vice","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2024\/08\/01\/petrolina-pl-oficializa-lara-cavalcanti-como-candidata-a-prefeita-e-professor-weliton-da-silva-como-vice","title":{"rendered":"Petrolina: PL oficializa Lara Cavalcanti como candidata a prefeita e professor Weliton da Silva como vice"},"content":{"rendered":"<p style=\"text-align: justify;\">A conven\u00e7\u00e3o do Partido Liberal (PL) realizada na tarde desta quarta-feira (31), no Palace Hotel, em Petrolina (PE), oficializou Lara Cavalcanti como candidata a prefeita de Petrolina e o professor Weliton da Silva como vice.<\/p>\n<p style=\"text-align: justify;\">Participaram da conven\u00e7\u00e3o o presidente do PL em Pernambuco, Anderson Ferreira, o deputado federal, Coronel Meira, o deputado federal, Andr\u00e9 Ferreira e o deputado estadual, Abimael Santos. O PL Mulher foi representado pelapresidente, Izabel Urquiza, que \u00e9 pr\u00e9-candidata \u00e0 prefeitura de Olinda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A conven\u00e7\u00e3o do Partido Liberal (PL) realizada na tarde desta quarta-feira (31), no Palace Hotel, em Petrolina (PE), oficializou Lara Cavalcanti como candidata a prefeita de Petrolina e o professor Weliton da Silva como vice. Participaram da conven\u00e7\u00e3o o presidente do PL em Pernambuco, Anderson Ferreira, o deputado federal, Coronel Meira, o deputado federal, Andr\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[851],"tags":[1943,3888],"class_list":["post-67169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-petrolina","tag-bolsonaristas","tag-eleicoes-2024"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2024\/08\/IMG-20240731-WA00491-2.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A conven\u00e7\u00e3o do Partido Liberal (PL) realizada na tarde desta quarta-feira (31), no Palace Hotel, em Petrolina (PE), oficializou Lara Cavalcanti como candidata a prefeita de Petrolina e o professor Weliton da Silva como vice. Participaram da conven\u00e7\u00e3o o presidente do PL em Pernambuco, Anderson Ferreira, o deputado federal, Coronel Meira, o deputado federal, Andr\u00e9&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67169"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67169\/revisions"}],"predecessor-version":[{"id":67171,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67169\/revisions\/67171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/67170"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}