{"id":71496,"date":"2025-01-15T17:55:30","date_gmt":"2025-01-15T20:55:30","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=71496"},"modified":"2025-01-15T17:55:30","modified_gmt":"2025-01-15T20:55:30","slug":"governo-revoga-medida-de-monitoramento-do-pix-apos-onda-de-fake-news","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2025\/01\/15\/governo-revoga-medida-de-monitoramento-do-pix-apos-onda-de-fake-news","title":{"rendered":"Governo revoga medida de monitoramento do Pix ap\u00f3s onda de fake news"},"content":{"rendered":"<div class=\"template--materia-comum\">\n<div class=\"grid-column-container center\">\n<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-nmew8s9xq4\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">Em coletiva de imprensa na tarde desta quarta-feira (15), o secret\u00e1rio da Receita Federal, Robinson Barreirinhas, anunciou que a regra de monitoramento do Pix ser\u00e1 revogada, ap\u00f3s dissemina\u00e7\u00e3o de not\u00edcias falsas de que o Executivo taxaria as transa\u00e7\u00f5es.<\/p>\n<\/div>\n<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-rkwoiu4zt6\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\u201cVamos revogar ato da Receita que mudou valores para monitoramento de movimenta\u00e7\u00f5es financeiras. Pessoas inescrupulosas distorceram e manipularam o ato normativo da Receita Federal prejudicando milh\u00f5es de pessoas, causando p\u00e2nico principalmente na popula\u00e7\u00e3o mais humilde\u201d, afirmou Barreirinhas.<\/p>\n<\/div>\n<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-4d9gyw3wfl\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">O secret\u00e1rio explicou que o recuo do Governo se deu por 2 motivos: \u201c Um deles \u00e9 tirar isso que virou uma arma na m\u00e3o desses criminosos. A segunda raz\u00e3o \u00e9 n\u00e3o prejudicar o debate e a tramita\u00e7\u00e3o do ato que vai ser anunciado pelos ministros\u201d.<\/p>\n<\/div>\n<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-jcnwgybfmg\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">O pronunciamento foi realizado ao lado do ministro da Fazenda, Fernando Haddad. Em seguida, Haddad\u00a0afirmou que o governo editar\u00e1 uma Medida Provis\u00f3ria (MP) que garantir\u00e1 a n\u00e3o taxa\u00e7\u00e3o do Pix.<\/p>\n<\/div>\n<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-bkjwaf1h5x\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\u201c\u00c9 para evitar judicializa\u00e7\u00e3o e mentiras que a Receita Federal est\u00e1 tomando a atitude de revogar. O advogado-geral da Uni\u00e3o, Jorge Messias, vai falar como vamos chegar nos autores das \u2018fake news\u2019. Tudo isso para resguardar as pessoas\u201d, completou.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Em coletiva de imprensa na tarde desta quarta-feira (15), o secret\u00e1rio da Receita Federal, Robinson Barreirinhas, anunciou que a regra de monitoramento do Pix ser\u00e1 revogada, ap\u00f3s dissemina\u00e7\u00e3o de not\u00edcias falsas de que o Executivo taxaria as transa\u00e7\u00f5es. \u201cVamos revogar ato da Receita que mudou valores para monitoramento de movimenta\u00e7\u00f5es financeiras. Pessoas inescrupulosas distorceram e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200],"tags":[],"class_list":["post-71496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1.jpg",500,326,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1-300x196.jpg",300,196,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1.jpg",500,326,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1.jpg",500,326,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1.jpg",500,326,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1.jpg",500,326,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1.jpg",500,326,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1-300x326.jpg",300,326,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1.jpg",500,326,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2023\/05\/pix_0411202554-689x450-1.jpg",500,326,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Em coletiva de imprensa na tarde desta quarta-feira (15), o secret\u00e1rio da Receita Federal, Robinson Barreirinhas, anunciou que a regra de monitoramento do Pix ser\u00e1 revogada, ap\u00f3s dissemina\u00e7\u00e3o de not\u00edcias falsas de que o Executivo taxaria as transa\u00e7\u00f5es. \u201cVamos revogar ato da Receita que mudou valores para monitoramento de movimenta\u00e7\u00f5es financeiras. Pessoas inescrupulosas distorceram e&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=71496"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71496\/revisions"}],"predecessor-version":[{"id":71498,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71496\/revisions\/71498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/52207"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=71496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=71496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=71496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}