{"id":71582,"date":"2025-01-17T10:35:11","date_gmt":"2025-01-17T13:35:11","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=71582"},"modified":"2025-01-17T10:35:11","modified_gmt":"2025-01-17T13:35:11","slug":"pais-de-alunos-fazem-manifestacao-no-nte-para-cobrar-vagas-no-colegio-hildete-lomanto","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2025\/01\/17\/pais-de-alunos-fazem-manifestacao-no-nte-para-cobrar-vagas-no-colegio-hildete-lomanto","title":{"rendered":"Pais de alunos fazem manifesta\u00e7\u00e3o no NTE para cobrar vagas no Col\u00e9gio Hildete Lomanto."},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Em den\u00fancia encaminhada \u00e0 nossa reda\u00e7\u00e3o, m\u00e3es questionam a desorganiza\u00e7\u00e3o e a suposta m\u00e1-f\u00e9 dos funcion\u00e1rios do N\u00facleo Territorial de Educa\u00e7\u00e3o (NTE-10).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seguindo o calend\u00e1rio de matr\u00edculas da Secretaria de Educa\u00e7\u00e3o do Estado, hoje, 17, seria o dia destinado \u00e0 matr\u00edcula de alunos do ensino fundamental. No entanto, no sistema disponibilizado, as vagas est\u00e3o indispon\u00edveis. A m\u00e3e de um aluno relatou: <\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cAs vagas do 7\u00ba ano do Hildete Lomanto deveriam estar abertas hoje. Quando fui cadastrar minha filha, apareceu que estava sem vaga\u201d.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Dezenas de pais enfrentaram o mesmo problema e foram reivindicar diretamente no NTE, mas se sentiram frustrados pelo atendimento recebido. <\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cEles [funcion\u00e1rios] entram l\u00e1 para dentro e n\u00e3o dizem nada. Simplesmente, de vez em quando, voltam e dizem: \u2018N\u00e3o tem vaga\u2019\u201d, afirmou uma das m\u00e3es.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">At\u00e9 o fechamento desta mat\u00e9ria, n\u00e3o houve posicionamento oficial do NTE-10. Vale lembrar que esta n\u00e3o \u00e9 a primeira vez que surgem problemas relacionados \u00e0s matr\u00edculas da rede estadual.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-71583\" src=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-17-at-09.41.53-169x300.jpeg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-17-at-09.41.53-169x300.jpeg 169w, https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-17-at-09.41.53-576x1024.jpeg 576w, https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-17-at-09.41.53.jpeg 720w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em den\u00fancia encaminhada \u00e0 nossa reda\u00e7\u00e3o, m\u00e3es questionam a desorganiza\u00e7\u00e3o e a suposta m\u00e1-f\u00e9 dos funcion\u00e1rios do N\u00facleo Territorial de Educa\u00e7\u00e3o (NTE-10). Seguindo o calend\u00e1rio de matr\u00edculas da Secretaria de Educa\u00e7\u00e3o do Estado, hoje, 17, seria o dia destinado \u00e0 matr\u00edcula de alunos do ensino fundamental. No entanto, no sistema disponibilizado, as vagas est\u00e3o indispon\u00edveis. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":71584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[207],"tags":[10344,1012,676],"class_list":["post-71582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-denuncia","tag-jeronimo","tag-sec","tag-zo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC-300x235.jpg",300,235,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC-300x287.jpg",300,287,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/SEC.jpg",366,287,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Em den\u00fancia encaminhada \u00e0 nossa reda\u00e7\u00e3o, m\u00e3es questionam a desorganiza\u00e7\u00e3o e a suposta m\u00e1-f\u00e9 dos funcion\u00e1rios do N\u00facleo Territorial de Educa\u00e7\u00e3o (NTE-10). Seguindo o calend\u00e1rio de matr\u00edculas da Secretaria de Educa\u00e7\u00e3o do Estado, hoje, 17, seria o dia destinado \u00e0 matr\u00edcula de alunos do ensino fundamental. No entanto, no sistema disponibilizado, as vagas est\u00e3o indispon\u00edveis.&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=71582"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71582\/revisions"}],"predecessor-version":[{"id":71585,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71582\/revisions\/71585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/71584"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=71582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=71582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=71582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}