{"id":71604,"date":"2025-01-17T13:37:54","date_gmt":"2025-01-17T16:37:54","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=71604"},"modified":"2025-01-17T13:37:54","modified_gmt":"2025-01-17T16:37:54","slug":"taxista-e-passageiro-sao-mortos-a-tiros-perto-do-ferry-boat-em-itaparica","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2025\/01\/17\/taxista-e-passageiro-sao-mortos-a-tiros-perto-do-ferry-boat-em-itaparica","title":{"rendered":"Taxista e passageiro s\u00e3o mortos a tiros perto do Ferry-boat em Itaparica"},"content":{"rendered":"<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-vm3zeo6svx\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">Um taxista e um passageiro foram mortos a tiros na rodovia BA-001, perto do Terminal Mar\u00edtimo de Bom Despacho, na Ilha de Itaparica, na noite de quinta-feira (16). Mais duas pessoas estavam no carro, mas conseguiram fugir e foram socorridas para uma unidade hospitalar da regi\u00e3o.<\/p>\n<\/div>\n<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-8za0g6fg5x\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">As v\u00edtimas que morreram foram identificadas como\u00a0Jonathan dos Santos Lopes, de 25 anos, e Rog\u00e9rio Borges de Santana, de 60 anos. Segundo a Pol\u00edcia Civil,\u00a0Rog\u00e9rio dirigia um t\u00e1xi quando o carro foi alvo de disparos de arma de fogo. A autoria e a motiva\u00e7\u00e3o do crime ainda est\u00e3o sendo apuradas pela corpora\u00e7\u00e3o.<\/p>\n<\/div>\n<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-y0pe4s8fqm\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">De acordo com a reportagem da TV Bahia, o grupo atacado teria se envolvido em uma briga ap\u00f3s desembarcar da \u00e1rea do Ferry-boat. Depois da discuss\u00e3o, eles sa\u00edram do local e pegaram o t\u00e1xi. O ataque aconteceu nos minutos seguintes.<\/p>\n<\/div>\n<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-e6sd1kam4u\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">Em nota, a Internacional Travessias Salvador (ITS) informou que o ocorrido n\u00e3o tem rela\u00e7\u00e3o com o servi\u00e7o e n\u00e3o houve registro de incidente dentro das opera\u00e7\u00f5es.<\/p>\n<\/div>\n<div class=\"flex flex-col p-2 px-0 w-full\">\n<p id=\"paragrafo-zpd8j64pt3\" class=\"font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">Policiais militares do 23\u00ba Batalh\u00e3o (BPM\/Ilha de Vera Cruz) foram acionados para verificar a ocorr\u00eancia de duplo homic\u00eddio e a\u00a019\u00aa Delegacia Territorial (DT\/Itaparica) instaurou um inqu\u00e9rito policial para investigar o caso. O Departamento de Pol\u00edcia T\u00e9cnica (DPT) foi acionado para realizar as per\u00edcias e a remo\u00e7\u00e3o dos corpos por meio da expedi\u00e7\u00e3o de guias.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um taxista e um passageiro foram mortos a tiros na rodovia BA-001, perto do Terminal Mar\u00edtimo de Bom Despacho, na Ilha de Itaparica, na noite de quinta-feira (16). Mais duas pessoas estavam no carro, mas conseguiram fugir e foram socorridas para uma unidade hospitalar da regi\u00e3o. As v\u00edtimas que morreram foram identificadas como\u00a0Jonathan dos Santos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":71605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[202],"tags":[],"class_list":["post-71604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll.jpg",500,331,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll-300x199.jpg",300,199,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll.jpg",500,331,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll.jpg",500,331,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll.jpg",500,331,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll.jpg",500,331,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll.jpg",500,331,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll-300x331.jpg",300,331,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll.jpg",500,331,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/llllllllllllllllllllllllllllllllllllllllllllllllllllll.jpg",500,331,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Um taxista e um passageiro foram mortos a tiros na rodovia BA-001, perto do Terminal Mar\u00edtimo de Bom Despacho, na Ilha de Itaparica, na noite de quinta-feira (16). Mais duas pessoas estavam no carro, mas conseguiram fugir e foram socorridas para uma unidade hospitalar da regi\u00e3o. As v\u00edtimas que morreram foram identificadas como\u00a0Jonathan dos Santos&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=71604"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71604\/revisions"}],"predecessor-version":[{"id":71606,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71604\/revisions\/71606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/71605"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=71604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=71604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=71604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}