{"id":71988,"date":"2025-01-28T07:43:31","date_gmt":"2025-01-28T10:43:31","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=71988"},"modified":"2025-01-28T19:55:36","modified_gmt":"2025-01-28T22:55:36","slug":"juazeiro-prefeito-andrei-minimiza-o-protagonismo-do-deputado-zo-no-festival-de-verao-velho-chico","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2025\/01\/28\/juazeiro-prefeito-andrei-minimiza-o-protagonismo-do-deputado-zo-no-festival-de-verao-velho-chico","title":{"rendered":"Juazeiro: Prefeito Andrei minimiza o protagonismo do deputado Z\u00f3 no Festival de Ver\u00e3o Velho Chico"},"content":{"rendered":"<p>\u00c9 evidente a movimenta\u00e7\u00e3o excessiva de marketing e o personalismo do prefeito Andrei. Para ele, a m\u00e1xima \u201ctudo tem limite\u201d n\u00e3o se aplica quando se trata de autopromo\u00e7\u00e3o. O evento do \u00faltimo final de semana deixa isso claro.<\/p>\n<p>O Festival de Ver\u00e3o Velho Chico, idealizado por Rodrigo da Arca Sport e viabilizado pela emenda do deputado Z\u00f3, al\u00e9m do prest\u00edgio dele com o governador Jer\u00f4nimo e o controle do PCdoB na Secretaria de Estado da SETRE, s\u00f3 aconteceu devido \u00e0 iniciativa de Rodrigo e ao apoio fundamental do deputado Z\u00f3.<\/p>\n<p>No entanto, o prefeito Andrei tentou, de forma oportunista, minimizar a participa\u00e7\u00e3o desses atores essenciais no evento, colocando seu pr\u00f3prio nome e da sua administra\u00e7\u00e3o acima do trabalho coletivo. Ficou evidente a tentativa de ocultar a contribui\u00e7\u00e3o decisiva de Rodrigo e Z\u00f3 na concep\u00e7\u00e3o e realiza\u00e7\u00e3o do festival.<\/p>\n<p>Fica a pergunta: at\u00e9 onde esse comportamento inadequado e personalista do prefeito Andrei ir\u00e1 lev\u00e1-lo? Vamos aguardar os pr\u00f3ximos cap\u00edtulos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 evidente a movimenta\u00e7\u00e3o excessiva de marketing e o personalismo do prefeito Andrei. Para ele, a m\u00e1xima \u201ctudo tem limite\u201d n\u00e3o se aplica quando se trata de autopromo\u00e7\u00e3o. O evento do \u00faltimo final de semana deixa isso claro. O Festival de Ver\u00e3o Velho Chico, idealizado por Rodrigo da Arca Sport e viabilizado pela emenda do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":71994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,197],"tags":[11647,11775,798,11256,11783,2639],"class_list":["post-71988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-politica","tag-andrei-goncalves","tag-andrei-goncalves-mdb","tag-deputado-zo","tag-federacao-pt-pcdob-pv","tag-gestao-de-andrei-da-caixa","tag-mdb"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3.jpg",500,419,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3-300x251.jpg",300,251,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3.jpg",500,419,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3.jpg",500,419,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3.jpg",500,419,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3.jpg",500,419,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3.jpg",500,419,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3-300x419.jpg",300,419,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3.jpg",500,419,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/01\/FAKE-NEWS-3.jpg",500,419,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"\u00c9 evidente a movimenta\u00e7\u00e3o excessiva de marketing e o personalismo do prefeito Andrei. Para ele, a m\u00e1xima \u201ctudo tem limite\u201d n\u00e3o se aplica quando se trata de autopromo\u00e7\u00e3o. O evento do \u00faltimo final de semana deixa isso claro. O Festival de Ver\u00e3o Velho Chico, idealizado por Rodrigo da Arca Sport e viabilizado pela emenda do&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=71988"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71988\/revisions"}],"predecessor-version":[{"id":72003,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71988\/revisions\/72003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/71994"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=71988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=71988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=71988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}