{"id":74039,"date":"2025-03-22T19:27:14","date_gmt":"2025-03-22T22:27:14","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=74039"},"modified":"2025-03-22T19:33:38","modified_gmt":"2025-03-22T22:33:38","slug":"petrolina-motociclista-perde-a-perna-em-acidente-no-acesso-ao-cosme-e-damiao-video","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2025\/03\/22\/petrolina-motociclista-perde-a-perna-em-acidente-no-acesso-ao-cosme-e-damiao-video","title":{"rendered":"Petrolina: Motociclista perde a perna em acidente no acesso ao Cosme e Dami\u00e3o. [V\u00eddeo]"},"content":{"rendered":"<p>Um motociclista ficou gravemente ferido num acidente ocorrido neste s\u00e1bado (22), na entrada de acesso ao Bairro Cosme e Dami\u00e3o, em Petrolina. At\u00e9 o momento n\u00e3o h\u00e1 detalhes do acidente.<\/p>\n<p>O impacto foi t\u00e3o forte que a v\u00edtima teve uma das pernas decepada. Uma equipe do Samu foi acionada ao local e prestou os primeiros socorros ao condutor da moto, que foi levado em seguida ao Hospital Universit\u00e1rio (HU). No entanto, seu estado de sa\u00fade \u00e9 desconhecido.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-74039-1\" width=\"640\" height=\"640\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/Snapinst.app_video_AQM_6qQ4T8NOIKJtWTf3gyfhlwxkx84RdKRkzVsBn1qAgrbuds1PXU5rwbU70bk9EwP1Dt26Sn9FJjkgZ66DfbEkOSAB7sTNQbPPfSI.mp4?_=1\" \/><a href=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/Snapinst.app_video_AQM_6qQ4T8NOIKJtWTf3gyfhlwxkx84RdKRkzVsBn1qAgrbuds1PXU5rwbU70bk9EwP1Dt26Sn9FJjkgZ66DfbEkOSAB7sTNQbPPfSI.mp4\">https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/Snapinst.app_video_AQM_6qQ4T8NOIKJtWTf3gyfhlwxkx84RdKRkzVsBn1qAgrbuds1PXU5rwbU70bk9EwP1Dt26Sn9FJjkgZ66DfbEkOSAB7sTNQbPPfSI.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um motociclista ficou gravemente ferido num acidente ocorrido neste s\u00e1bado (22), na entrada de acesso ao Bairro Cosme e Dami\u00e3o, em Petrolina. At\u00e9 o momento n\u00e3o h\u00e1 detalhes do acidente. O impacto foi t\u00e3o forte que a v\u00edtima teve uma das pernas decepada. Uma equipe do Samu foi acionada ao local e prestou os primeiros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":74042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[851],"tags":[],"class_list":["post-74039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-petrolina"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente.jpg",497,396,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente-300x239.jpg",300,239,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente.jpg",497,396,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente.jpg",497,396,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente.jpg",497,396,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente.jpg",497,396,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente.jpg",497,396,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente-300x396.jpg",300,396,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente.jpg",497,396,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/03\/motociclista-ferido-em-acidente.jpg",497,396,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Um motociclista ficou gravemente ferido num acidente ocorrido neste s\u00e1bado (22), na entrada de acesso ao Bairro Cosme e Dami\u00e3o, em Petrolina. At\u00e9 o momento n\u00e3o h\u00e1 detalhes do acidente. O impacto foi t\u00e3o forte que a v\u00edtima teve uma das pernas decepada. Uma equipe do Samu foi acionada ao local e prestou os primeiros&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=74039"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74039\/revisions"}],"predecessor-version":[{"id":74041,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74039\/revisions\/74041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/74042"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=74039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=74039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=74039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}