{"id":75392,"date":"2025-04-29T12:29:16","date_gmt":"2025-04-29T15:29:16","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=75392"},"modified":"2025-04-29T12:29:16","modified_gmt":"2025-04-29T15:29:16","slug":"gestao-municipal-de-sento-se-investe-na-formacao-continuada-de-professores-com-mais-uma-capacitacao-do-leei","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2025\/04\/29\/gestao-municipal-de-sento-se-investe-na-formacao-continuada-de-professores-com-mais-uma-capacitacao-do-leei","title":{"rendered":"Gest\u00e3o municipal de Sento S\u00e9 investe na forma\u00e7\u00e3o continuada de professores com mais uma capacita\u00e7\u00e3o do LEEI"},"content":{"rendered":"<p class=\"x_MsoNormal\">A Prefeitura de Sento S\u00e9, por meio da Secretaria Municipal de Educa\u00e7\u00e3o, realizou nesta quinta (24) e sexta-feira (25), na Igreja Evang\u00e9lica Congregacional, a 3\u00aa Forma\u00e7\u00e3o de Leitura e Escrita na Educa\u00e7\u00e3o Infantil (LEEI). O encontro reuniu professores dos 1\u00ba e 2\u00ba per\u00edodos da Educa\u00e7\u00e3o Infantil da rede municipal, com o objetivo de refletir sobre os avan\u00e7os e desafios do letramento a partir da brincadeira e do papel do professor na sala de aula.<\/p>\n<p class=\"x_MsoNormal\">\u201cAcreditamos que o fortalecimento da Educa\u00e7\u00e3o Infantil passa pela valoriza\u00e7\u00e3o e forma\u00e7\u00e3o dos nossos profissionais. O LEEI tem nos permitido qualificar pr\u00e1ticas pedag\u00f3gicas, respeitando o tempo da crian\u00e7a, promovendo o letramento desde os primeiros anos e garantindo que a educa\u00e7\u00e3o do munic\u00edpio avance com base na realidade das nossas escolas\u201d, refor\u00e7ou o secret\u00e1rio de Educa\u00e7\u00e3o, Jeorge Ribeiro.<\/p>\n<p class=\"x_MsoNormal\">Com o tema \u201cO brincar, o letramento e o papel do professor na Educa\u00e7\u00e3o Infantil\u201d, a forma\u00e7\u00e3o foi conduzida por Lindiane Ribeiro, coordenadora da Educa\u00e7\u00e3o Infantil no munic\u00edpio e formadora do LEEI. \u201cFoi um momento de grande relev\u00e2ncia, de partilha e reflex\u00e3o sobre pr\u00e1ticas que precisam ser desconstru\u00eddas e reconstru\u00eddas para atender \u00e0s crian\u00e7as de hoje\u201d, destacou.<\/p>\n<p class=\"x_MsoNormal\">A professora Jackeline Feitosa Alves, coordenadora pedag\u00f3gica da Escola Sala Avan\u00e7ada Jorge Jos\u00e9 de Castro, em Riacho dos Paes, tamb\u00e9m avaliou positivamente a forma\u00e7\u00e3o. \u201cFoi um momento gratificante, que nos ajuda a alinhar teoria e pr\u00e1tica, conforme o DCRM nas escolas de Sento S\u00e9.\u201d<\/p>\n<p class=\"x_MsoNormal\">\nTexto: Gardennia Garibalde \u2013 Ascom PMSSE<\/p>\n<p class=\"x_MsoNormal\">\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Sento S\u00e9, por meio da Secretaria Municipal de Educa\u00e7\u00e3o, realizou nesta quinta (24) e sexta-feira (25), na Igreja Evang\u00e9lica Congregacional, a 3\u00aa Forma\u00e7\u00e3o de Leitura e Escrita na Educa\u00e7\u00e3o Infantil (LEEI). O encontro reuniu professores dos 1\u00ba e 2\u00ba per\u00edodos da Educa\u00e7\u00e3o Infantil da rede municipal, com o objetivo de refletir sobre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[209],"tags":[9532,11115],"class_list":["post-75392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-infantojuvenil","tag-juvenilson-passos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4.jpg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4-300x169.jpg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4.jpg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4.jpg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4.jpg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4.jpg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4.jpg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4-420x281.jpg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4-300x281.jpg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4-464x281.jpg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4.jpg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/04\/thumbnail_WhatsApp-Image-2025-04-25-at-15.23.05-4.jpg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A Prefeitura de Sento S\u00e9, por meio da Secretaria Municipal de Educa\u00e7\u00e3o, realizou nesta quinta (24) e sexta-feira (25), na Igreja Evang\u00e9lica Congregacional, a 3\u00aa Forma\u00e7\u00e3o de Leitura e Escrita na Educa\u00e7\u00e3o Infantil (LEEI). O encontro reuniu professores dos 1\u00ba e 2\u00ba per\u00edodos da Educa\u00e7\u00e3o Infantil da rede municipal, com o objetivo de refletir sobre&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/75392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=75392"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/75392\/revisions"}],"predecessor-version":[{"id":75396,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/75392\/revisions\/75396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/75393"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=75392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=75392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=75392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}