{"id":75535,"date":"2025-05-02T16:24:56","date_gmt":"2025-05-02T19:24:56","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=75535"},"modified":"2025-05-02T16:24:56","modified_gmt":"2025-05-02T19:24:56","slug":"reuniao-entre-representantes-do-saae-cerb-e-comunidade-de-carnaiba-sinaliza-melhorias-no-sistema-de-abastecimento-de-agua","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2025\/05\/02\/reuniao-entre-representantes-do-saae-cerb-e-comunidade-de-carnaiba-sinaliza-melhorias-no-sistema-de-abastecimento-de-agua","title":{"rendered":"Reuni\u00e3o entre representantes do SAAE, CERB e Comunidade de Carna\u00edba sinaliza melhorias no sistema de abastecimento de \u00e1gua"},"content":{"rendered":"<p>A diretora-presidente do Servi\u00e7o de \u00c1gua e Saneamento Ambiental\/SAAE -Juazeiro, Fabiana de Poss\u00eddio, e representantes da Companhia de Engenharia H\u00eddrica e de Saneamento da Bahia \u2013 CERB, estiveram reunidos na quarta-feira (30) com moradores e lideran\u00e7as do Distrito de Carna\u00edba em busca de alternativas para melhorar o sistema de abastecimento de \u00e1gua na comunidade, agravado nos \u00faltimos dias pelas constantes quedas de energia.<\/p>\n<p>Fabiana adiantou que estava ali para ouvir os moradores e encontrar uma solu\u00e7\u00e3o de um problema que \u00e9 antigo e vem gerando toda essa demanda reprimida. A reuni\u00e3o foi iniciada com uma ora\u00e7\u00e3o, onde o produtor rural, Robson Ferreira pediu que Deus iluminasse a todos e o encontro fosse produtivo. Outro morador, Luan Rodrigues, revelou que j\u00e1 havia ouvido outras propostas em governos anteriores que n\u00e3o sa\u00edram do papel, mas que agora estava confiante na resolu\u00e7\u00e3o do problema.<\/p>\n<p>\u201cN\u00e3o quero culpar ningu\u00e9m pela situa\u00e7\u00e3o que vivemos hoje, mas s\u00f3 o fato de voc\u00eas virem aqui ouvir a comunidade j\u00e1 significa um avan\u00e7o. Sei que o tempo ainda \u00e9 curto para solu\u00e7\u00f5es definitivas, mas estamos confiantes de que desse encontro sair\u00e1 compromissos que ser\u00e3o honrados\u201d, pontuou.<\/p>\n<p>J\u00e1 o morador Fl\u00e1vio de Cristo defendeu a constru\u00e7\u00e3o de um novo reservat\u00f3rio e melhorias em todo o sistema. \u201cOs problemas existem e n\u00e3o s\u00e3o de agora. S\u00f3 queremos o direito de ter \u00e1gua nas nossas casas\u201d, resumiu. E Marcia F\u00e9lix reconheceu que o problema \u00e9 antigo, n\u00e3o se resolve na rapidez desejada, por\u00e9m vem se agravando nos \u00faltimos meses. \u201cEstamos comprando \u00e1gua mineral para beber porque n\u00e3o confiamos na \u00e1gua que \u00e0s vezes \u00e8 fornecida pelo SAAE. N\u00e3o tenho bandeira politica e estamos aqui para buscar solu\u00e7\u00f5es e a\u00e7\u00f5es p\u00fablicas que venham atender os nossos direitos\u201d, afirmou.<\/p>\n<p>Para o vereador Berg da Carna\u00edba, \u00e9 hora de desarmar palanques e todos se unirem na busca de solu\u00e7\u00f5es. \u201cSabemos que o problema n\u00e3o \u00e9 de hoje e que piorou com o tempo. Pela primeira vez vimos uma gest\u00e3o do SAAE vir duas vezes no mesmo dia \u00e0 nossa comunidade, demostrando que tamb\u00e9m est\u00e1 preocupada com essa situa\u00e7\u00e3o. Carna\u00edba cresceu nos \u00faltimos anos, os problemas se agravaram e precisamos, juntos, buscar as solu\u00e7\u00f5es\u201d, refor\u00e7ou.<\/p>\n<p>Morador antigo de Carna\u00edba, seu Emanuel Jos\u00e9 de Oliveira assegurou que o sistema de abastecimento da comunidade tem mais de 30 anos e que nesse per\u00edodo pouco foi feito na sua melhoria. \u201cMoro aqui bem pertinho da ETA e, gra\u00e7as a Deus, na minha casa nunca faltou \u00e1gua, mas \u00e9 preciso investimentos desde a rede at\u00e9 os filtros para melhorar a oferta de \u00e1gua\u201d, disse seu Emanuel que tamb\u00e9m elogiou o trabalho dos servidores do SAAE respons\u00e1veis pela distribui\u00e7\u00e3o de \u00e1gua no distrito.<\/p>\n<p>Ciente do todo esse cen\u00e1rio, a diretora-presidente do SAAE, Fabiana de Poss\u00eddio, ouviu a todos e se comprometeu em continuar empenhando todo o esfor\u00e7o necess\u00e1rio na busca de solu\u00e7\u00f5es, n\u00e3o apenas para Carna\u00edba, mas tamb\u00e9m para os outros 24 sistemas no interior do munic\u00edpio que se encontram na mesma situa\u00e7\u00e3o.<\/p>\n<p>\u201cInfelizmente n\u00e3o podemos, neste momento, fazer tudo acontecer na dimens\u00e3o e velocidade que gostar\u00edamos por conta do quadro ca\u00f3tico\u00a0 que encontramos o SAAE, mas com o apoio de todos vamos virar essa p\u00e1gina. Quero agradecer aos representantes da CERB por estarem juntos conosco nessa caminhada, \u00e0 nossa equipe que n\u00e3o mede esfor\u00e7o na execu\u00e7\u00e3o dos servi\u00e7os e a todos voc\u00eas que est\u00e3o acreditando e confiantes que, em breve, teremos dias melhores\u201d, finalizou.<\/p>\n<p>Para a gestora da Divis\u00e3o de Interior do SAAE, Elayne Borges, todos os esfor\u00e7os est\u00e3o sendo feitos na busca de alternativas que venham minimizar esses problemas recorrentes. \u201cAs constantes quedas de energia registradas nos \u00faltimos dias agravaram a situa\u00e7\u00e3o, mas estamos aqui com toda nossa equipe t\u00e9cnica para atuar em qualquer emerg\u00eancia\u201d.<\/p>\n<p>O gerente da CERB em Juazeiro, C\u00e9sar Torres, informou que j\u00e1 existem projetos no PAC para atender seis comunidades daquela regi\u00e3o, incluindo Carna\u00edba, Juremal e Massaroca. \u201cEstamos aqui para refor\u00e7ar essa parceria do Estado com o Munic\u00edpio, discutir e elaborar um plano de a\u00e7\u00e3o para que em tempo h\u00e1bil possamos encontrar uma solu\u00e7\u00e3o definitiva de todos esses problemas\u201d, afirmou o representante da CERB que estava acompanhado de equipe t\u00e9cnica do \u00f3rg\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Ascom PMJ\/SAAE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A diretora-presidente do Servi\u00e7o de \u00c1gua e Saneamento Ambiental\/SAAE -Juazeiro, Fabiana de Poss\u00eddio, e representantes da Companhia de Engenharia H\u00eddrica e de Saneamento da Bahia \u2013 CERB, estiveram reunidos na quarta-feira (30) com moradores e lideran\u00e7as do Distrito de Carna\u00edba em busca de alternativas para melhorar o sistema de abastecimento de \u00e1gua na comunidade, agravado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[11813,7744],"class_list":["post-75535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-fabiana-egashira","tag-saae-juazeiro-ba"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1.jpeg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1-300x200.jpeg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1.jpeg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1.jpeg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1.jpeg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1.jpeg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1.jpeg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1-300x333.jpeg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1.jpeg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2025\/05\/VISITA-SAAE-CARNAIBA-696x464-1.jpeg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A diretora-presidente do Servi\u00e7o de \u00c1gua e Saneamento Ambiental\/SAAE -Juazeiro, Fabiana de Poss\u00eddio, e representantes da Companhia de Engenharia H\u00eddrica e de Saneamento da Bahia \u2013 CERB, estiveram reunidos na quarta-feira (30) com moradores e lideran\u00e7as do Distrito de Carna\u00edba em busca de alternativas para melhorar o sistema de abastecimento de \u00e1gua na comunidade, agravado&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/75535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=75535"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/75535\/revisions"}],"predecessor-version":[{"id":75537,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/75535\/revisions\/75537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/75536"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=75535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=75535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=75535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}