{"id":83353,"date":"2026-02-05T13:17:29","date_gmt":"2026-02-05T16:17:29","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=83353"},"modified":"2026-02-05T13:17:29","modified_gmt":"2026-02-05T16:17:29","slug":"deputada-critica-edson-gomes-apos-video-polemico-viralizar-sempre-foi-reacionario","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2026\/02\/05\/deputada-critica-edson-gomes-apos-video-polemico-viralizar-sempre-foi-reacionario","title":{"rendered":"Deputada critica Edson Gomes ap\u00f3s v\u00eddeo pol\u00eamico viralizar: &#8216;Sempre foi reacion\u00e1rio&#8217;"},"content":{"rendered":"<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-4tptef66bh\">A deputada estadual Ol\u00edvia Santana (PCdoB) criticou publicamente o cantor de reggae Edson Gomes nesta quinta-feira (5). Em publica\u00e7\u00e3o nas redes sociais, a parlamentar afirmou que o posicionamento pol\u00edtico do artista n\u00e3o \u00e9 algo recente e classificou o m\u00fasico como \u201creacion\u00e1rio\u201d.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-n8uhgdv7hs\">No Instagram, Ol\u00edvia escreveu: &#8220;Edson Gomes \u00e9 reacion\u00e1rio. Sempre foi. As pessoas \u00e9 que se iludiram por causa das suas letras de m\u00fasicas, que mais parecem reflex\u00f5es de comunista&#8221;.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-sjoz0hfdel\">Conhecido por m\u00fasicas frequentemente utilizadas em atos e protestos de trabalhadores, Edson Gomes tem hist\u00f3rico de fazer declara\u00e7\u00f5es conservadoras.\u00a0Um v\u00eddeo que viralizou nesse in\u00edcio de m\u00eas mostra o artista falando ao p\u00fablico durante um show, em grava\u00e7\u00e3o cuja data n\u00e3o foi informada. No palco, ele fala de &#8220;reagir&#8221; a uma persegui\u00e7\u00e3o de comunistas, que tentariam doutrinar crian\u00e7as.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-8cu2g52hfq\">&#8220;Queria agradecer as m\u00e3es que trazem suas crian\u00e7as para ouvir esse reggae. \u00c9 muito bom, v\u00e3o sair daqui com algo positivo na mente. Sem maconha, sem droga, sem nada. S\u00f3 m\u00fasica, s\u00f3 a mensagem positiva para que quando crescerem, saberem tomar decis\u00e3o melhor que os pais. Nossos filhos s\u00e3o ca\u00e7ados pelos comunistas para que eles possam ser nada, para que se tornem uma presa, e n\u00f3s precisamos reagir, dar direcionamento a nossos filhos, para que n\u00e3o sejam no futuro uma presa, n\u00e3o estejam \u00e0 merc\u00ea da tirania, dos opressores, daqueles que enganam. Jah!&#8221;, afirma.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full\">\n<div id=\"embed-v302ihbbii\" class=\"component--embed \">\n<div class=\"twitter-tweet twitter-tweet-rendered\"><iframe id=\"twitter-widget-0\" class=\"\" title=\"X Post\" src=\"https:\/\/platform.twitter.com\/embed\/Tweet.html?dnt=false&amp;embedId=twitter-widget-0&amp;features=eyJ0ZndfdGltZWxpbmVfbGlzdCI6eyJidWNrZXQiOltdLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X2ZvbGxvd2VyX2NvdW50X3N1bnNldCI6eyJidWNrZXQiOnRydWUsInZlcnNpb24iOm51bGx9LCJ0ZndfdHdlZXRfZWRpdF9iYWNrZW5kIjp7ImJ1Y2tldCI6Im9uIiwidmVyc2lvbiI6bnVsbH0sInRmd19yZWZzcmNfc2Vzc2lvbiI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9LCJ0ZndfZm9zbnJfc29mdF9pbnRlcnZlbnRpb25zX2VuYWJsZWQiOnsiYnVja2V0Ijoib24iLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X21peGVkX21lZGlhXzE1ODk3Ijp7ImJ1Y2tldCI6InRyZWF0bWVudCIsInZlcnNpb24iOm51bGx9LCJ0ZndfZXhwZXJpbWVudHNfY29va2llX2V4cGlyYXRpb24iOnsiYnVja2V0IjoxMjA5NjAwLCJ2ZXJzaW9uIjpudWxsfSwidGZ3X3Nob3dfYmlyZHdhdGNoX3Bpdm90c19lbmFibGVkIjp7ImJ1Y2tldCI6Im9uIiwidmVyc2lvbiI6bnVsbH0sInRmd19kdXBsaWNhdGVfc2NyaWJlc190b19zZXR0aW5ncyI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9LCJ0ZndfdXNlX3Byb2ZpbGVfaW1hZ2Vfc2hhcGVfZW5hYmxlZCI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9LCJ0ZndfdmlkZW9faGxzX2R5bmFtaWNfbWFuaWZlc3RzXzE1MDgyIjp7ImJ1Y2tldCI6InRydWVfYml0cmF0ZSIsInZlcnNpb24iOm51bGx9LCJ0ZndfbGVnYWN5X3RpbWVsaW5lX3N1bnNldCI6eyJidWNrZXQiOnRydWUsInZlcnNpb24iOm51bGx9LCJ0ZndfdHdlZXRfZWRpdF9mcm9udGVuZCI6eyJidWNrZXQiOiJvbiIsInZlcnNpb24iOm51bGx9fQ%3D%3D&amp;frame=false&amp;hideCard=false&amp;hideThread=false&amp;id=2018867762035146992&amp;lang=pt&amp;maxWidth=560px&amp;origin=https%3A%2F%2Fwww.correio24horas.com.br%2Fbahia%2Fdeputada-critica-edson-gomes-apos-video-polemico-viralizar-sempre-foi-reacionario-0226&amp;sessionId=519566e26580135b917d849d03723ba87cd3cfda&amp;siteScreenName=correio24hba&amp;theme=light&amp;widgetsVersion=2615f7e52b7e0%3A1702314776716&amp;width=550px\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-tweet-id=\"2018867762035146992\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-tvqkes0i0e\">O trecho gerou rea\u00e7\u00f5es divergentes nas redes sociais. Boa parte dos f\u00e3s demonstrou decep\u00e7\u00e3o com a fala do cantor.\u00a0Um internauta escreveu: &#8220;\u00c9 triste ver o Edson Gomes, que passou a carreira toda cantando contra a opress\u00e3o e as injusti\u00e7as do sistema, agora cair em papo de &#8216;comunismo perseguindo crian\u00e7as&#8217;. Onde foi parar aquele discernimento cr\u00edtico das letras de &#8216;Camel\u00f4&#8217; e &#8216;Campo de Batalha&#8217;? Decepcionante&#8221;. Outro comentou: &#8220;virou um velho gag\u00e1 que v\u00ea comunistas atr\u00e1s da porta&#8221;.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-whrgx11h7f\">Por outro lado, apoiadores do artista reagiram concordando. &#8220;E onde est\u00e1 a mentira?&#8221;, escreveu um usu\u00e1rio do antigo Twitter. &#8220;Edson sempre esteve correto&#8221;, acrescentou outro.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-ix4g8solx3\">Na publica\u00e7\u00e3o, Ol\u00edvia Santana ampliou as cr\u00edticas e apontou contradi\u00e7\u00f5es entre a obra e as posi\u00e7\u00f5es pol\u00edticas do cantor. Ela afirmou que, embora suas m\u00fasicas tenham se tornado s\u00edmbolos de protesto e de cr\u00edticas ao sistema econ\u00f4mico, Edson Gomes teria se distanciado do p\u00fablico de esquerda que consagrou suas can\u00e7\u00f5es.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-1cbzlolgej\">&#8220;\u00c9dson Gomes comp\u00f5e como um comunista, mas fora da vida art\u00edstica age como qualquer pessoa de direita.\u00a0Contraditoriamente suas can\u00e7\u00f5es s\u00e3o cr\u00edticas duras ao capitalismo. e suas mazelas. \u201cEsse sistema \u00e9 um vampiro\u201d, \u201cVamos amigo lute, sen\u00e3o a gente acaba perdendo o que j\u00e1 conquistou\u201d viraram hinos nas manifesta\u00e7\u00f5es da classe trabalhadora. Mas Gomes nem deve se dar conta de que grande parte do seu p\u00fablico s\u00e3o pessoas de esquerda, os comunistas que ele tanto abomina.\u00a0\u00c9 triste ver sua radicaliza\u00e7\u00e3o \u00e0 direita nesta fase da sua vida&#8221;, acrescentou.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A deputada estadual Ol\u00edvia Santana (PCdoB) criticou publicamente o cantor de reggae Edson Gomes nesta quinta-feira (5). Em publica\u00e7\u00e3o nas redes sociais, a parlamentar afirmou que o posicionamento pol\u00edtico do artista n\u00e3o \u00e9 algo recente e classificou o m\u00fasico como \u201creacion\u00e1rio\u201d. No Instagram, Ol\u00edvia escreveu: &#8220;Edson Gomes \u00e9 reacion\u00e1rio. Sempre foi. As pessoas \u00e9 que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[197],"tags":[],"class_list":["post-83353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2.jpg",500,375,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2-300x225.jpg",300,225,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2.jpg",500,375,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2.jpg",500,375,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2.jpg",500,375,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2.jpg",500,375,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2.jpg",500,375,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2-300x375.jpg",300,375,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2.jpg",500,375,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/Adriely-Mendonca-2.jpg",500,375,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A deputada estadual Ol\u00edvia Santana (PCdoB) criticou publicamente o cantor de reggae Edson Gomes nesta quinta-feira (5). Em publica\u00e7\u00e3o nas redes sociais, a parlamentar afirmou que o posicionamento pol\u00edtico do artista n\u00e3o \u00e9 algo recente e classificou o m\u00fasico como \u201creacion\u00e1rio\u201d. No Instagram, Ol\u00edvia escreveu: &#8220;Edson Gomes \u00e9 reacion\u00e1rio. Sempre foi. As pessoas \u00e9 que&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=83353"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83353\/revisions"}],"predecessor-version":[{"id":83355,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83353\/revisions\/83355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/83354"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=83353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=83353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=83353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}