{"id":83444,"date":"2026-02-08T13:27:35","date_gmt":"2026-02-08T16:27:35","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=83444"},"modified":"2026-02-08T13:27:35","modified_gmt":"2026-02-08T16:27:35","slug":"diretora-presidente-do-saae-se-reune-com-representantes-do-exercito-e-da-defesa-civil-para-avaliacao-da-operacao-pipa","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2026\/02\/08\/diretora-presidente-do-saae-se-reune-com-representantes-do-exercito-e-da-defesa-civil-para-avaliacao-da-operacao-pipa","title":{"rendered":"Diretora-presidente do SAAE se re\u00fane com representantes do Ex\u00e9rcito e da Defesa Civil para avalia\u00e7\u00e3o da Opera\u00e7\u00e3o Pipa"},"content":{"rendered":"<div class=\"post-header-area\">\n<p><span style=\"font-size: 1rem;\">Diante do atual quadro de estiagem no interior do munic\u00edpio de Juazeiro, a Diretora-presidente do Servi\u00e7o de \u00c1gua e Saneamento Ambiental-SAAE, \u00a0Fabiana de Poss\u00eddio, preocupada com a situa\u00e7\u00e3o das comunidades afetadas pela seca, convidou representantes do Ex\u00e9rcito Brasileiro e da Defesa Civil Municipal, \u00a0para discutirem melhorias na distribui\u00e7\u00e3o de \u00e1gua pot\u00e1vel no interior, \u00a0atrav\u00e9s da Opera\u00e7\u00e3o Pipa, coordenada pelo Ex\u00e9rcito. Trata-se de um Programa do Governo Federal para atender regi\u00f5es onde n\u00e3o h\u00e1 rede de \u00e1gua do SAAE. \u00a0&#8220;Compreendemos a urg\u00eancia dos moradores, \u00a0por isso mesmo convocamos essa reuni\u00e3o para averiguar de que forma, junto com a Defesa Civil, agilizar o cadastramento de novos apontadores para aprova\u00e7\u00e3o e o munic\u00edpio ser contemplado com o maior n\u00famero de pessoas que atendam ao \u00a0regulamento da Opera\u00e7\u00e3o Pipa&#8221; , explicou Fabiana.<\/span><\/p>\n<\/div>\n<div class=\"post-content-area\">\n<p>Durante o encontro, \u00a0os representantes do Ex\u00e9rcito, \u00a0Coronel Brasil e o Capit\u00e3o Mam\u00e9dio falaram das dificuldades em atender todas as comunidades e explicaram os crit\u00e9rios \u00a0necess\u00e1rios para inscri\u00e7\u00f5es de novos contemplados, mediante a assinatura do pr\u00f3ximo contrato, que ocorrer\u00e1 em mar\u00e7o. Segundo os oficiais, \u00a0existem uma s\u00e9rie de regras exigidas pelo Governo Federal, dentre as exig\u00eancias, uma delas \u00e9 que as cisternas devem ser fechadas e com capacidade para 16 mil litros que ser\u00e3o conferidas pela equipe t\u00e9cnica do Ex\u00e9rcito.<\/p>\n<p>Nesse novo contrato, \u00a0refor\u00e7a o Coronel, \u00a0as pessoas que se inscreveram e atenderem a todas as exig\u00eancias cadastrais, \u00a0ser\u00e3o contempladas. Ficou acordado tamb\u00e9m na reuni\u00e3o que, \u00a0a Defesa Civil disponibilizar\u00e1 um representante para acompanhar as visitas t\u00e9cnicas e as avalia\u00e7\u00f5es em campo.<\/p>\n<p>&nbsp;<\/p>\n<p>Ascom PMJ<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Diante do atual quadro de estiagem no interior do munic\u00edpio de Juazeiro, a Diretora-presidente do Servi\u00e7o de \u00c1gua e Saneamento Ambiental-SAAE, \u00a0Fabiana de Poss\u00eddio, preocupada com a situa\u00e7\u00e3o das comunidades afetadas pela seca, convidou representantes do Ex\u00e9rcito Brasileiro e da Defesa Civil Municipal, \u00a0para discutirem melhorias na distribui\u00e7\u00e3o de \u00e1gua pot\u00e1vel no interior, \u00a0atrav\u00e9s da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[],"class_list":["post-83444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42.jpeg",500,500,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42-300x300.jpeg",300,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42.jpeg",500,500,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42.jpeg",500,500,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42.jpeg",500,500,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42.jpeg",500,500,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42.jpeg",500,500,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42-300x443.jpeg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42.jpeg",500,500,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-07-at-15_47_42.jpeg",500,500,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Diante do atual quadro de estiagem no interior do munic\u00edpio de Juazeiro, a Diretora-presidente do Servi\u00e7o de \u00c1gua e Saneamento Ambiental-SAAE, \u00a0Fabiana de Poss\u00eddio, preocupada com a situa\u00e7\u00e3o das comunidades afetadas pela seca, convidou representantes do Ex\u00e9rcito Brasileiro e da Defesa Civil Municipal, \u00a0para discutirem melhorias na distribui\u00e7\u00e3o de \u00e1gua pot\u00e1vel no interior, \u00a0atrav\u00e9s da&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=83444"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83444\/revisions"}],"predecessor-version":[{"id":83449,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/83444\/revisions\/83449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/83448"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=83444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=83444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=83444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}