{"id":8393,"date":"2020-03-20T10:47:08","date_gmt":"2020-03-20T13:47:08","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=8393"},"modified":"2020-03-20T10:49:58","modified_gmt":"2020-03-20T13:49:58","slug":"uaua-prefeitura-prepara-demissoes-em-massa-denuncia-vereador","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2020\/03\/20\/uaua-prefeitura-prepara-demissoes-em-massa-denuncia-vereador","title":{"rendered":"UAU\u00c1: Prefeitura prepara demiss\u00f5es em massa, denuncia vereador"},"content":{"rendered":"<p style=\"text-align: justify;\">O presidente da C\u00e2mara Municipal de Uau\u00e1, vereador Nilson Andrade (sem partido) est\u00e1 preocupado com as pessoas que ser\u00e3o exoneradas de seus cargos da Prefeitura Municipal nas pr\u00f3ximas horas. Nilson lembrou que o momento n\u00e3o \u00e9 bom devido as amea\u00e7as do H1N1 e do corona v\u00edrus que se instalou na Bahia, e que o momento deveria ser de aten\u00e7\u00e3o e acolhimento para essas pessoas que dependem do sal\u00e1rio para manterem o sustento de fam\u00edlias.<\/p>\n<p style=\"text-align: justify;\">O presidente da C\u00e2mara Municipal de Uau\u00e1, vereador Nilson Andrade (sem partido) est\u00e1 preocupado com as pessoas que ser\u00e3o exoneradas de seus cargos da Prefeitura Municipal nas pr\u00f3ximas horas. Nilson lembrou que o momento n\u00e3o \u00e9 bom devido as amea\u00e7as do H1N1 e do corona v\u00edrus que se instalou na Bahia, e que o momento deveria ser de aten\u00e7\u00e3o e acolhimento para essas pessoas que dependem do sal\u00e1rio para manterem o sustento de fam\u00edlias.<\/p>\n<p>O prefeito da cidade de Uau\u00e1, \u00e9 Lindomar Dantas (PCdoB) afilhado politico do coron\u00e9 Isaac Carvalho (PT).<\/p>\n<pre>Fonte de informa\u00e7\u00f5es: JAP<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Lindomar Dantas (PCdoB) segue a cartilha do coron\u00e9 Isaac Carvalho (PT).<\/p>\n","protected":false},"author":1,"featured_media":8395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199],"tags":[],"class_list":["post-8393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b.jpg",500,375,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b-300x225.jpg",300,225,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b.jpg",500,375,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b.jpg",500,375,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b.jpg",500,375,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b.jpg",500,375,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b.jpg",500,375,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b-300x375.jpg",300,375,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b.jpg",500,375,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/03\/2699691124_64ce993c6e_b.jpg",500,375,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O prefeito Lindomar Dantas (PCdoB) segue a cartilha do coron\u00e9 Isaac Carvalho (PT).","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8393"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8393\/revisions"}],"predecessor-version":[{"id":8394,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8393\/revisions\/8394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/8395"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}