{"id":84670,"date":"2026-03-25T10:42:35","date_gmt":"2026-03-25T13:42:35","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=84670"},"modified":"2026-03-25T10:42:35","modified_gmt":"2026-03-25T13:42:35","slug":"prefeitura-de-juazeiro-inicia-melhorias-estruturais-no-lacen-e-ajusta-temporariamente-alguns-servicos","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2026\/03\/25\/prefeitura-de-juazeiro-inicia-melhorias-estruturais-no-lacen-e-ajusta-temporariamente-alguns-servicos","title":{"rendered":"Prefeitura de Juazeiro inicia melhorias estruturais no LACEN e ajusta temporariamente alguns servi\u00e7os"},"content":{"rendered":"<p>A Prefeitura de Juazeiro, por meio da Secretaria Municipal de Sa\u00fade (Sesau), informa que, a partir desta quarta-feira (25), dar\u00e1 in\u00edcio a melhorias estruturais no pr\u00e9dio do Laborat\u00f3rio Central de Sa\u00fade P\u00fablica (LACEN), localizado na Rua Ant\u00f4nio Pedro, n\u00ba 436, Centro, com o objetivo de qualificar ainda mais os servi\u00e7os ofertados \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>Em virtude da realiza\u00e7\u00e3o da reforma, alguns procedimentos eletivos estar\u00e3o temporariamente suspensos, com retorno previsto para a pr\u00f3xima segunda-feira (30), ap\u00f3s a conclus\u00e3o das adequa\u00e7\u00f5es no espa\u00e7o.<\/p>\n<p>Durante esse per\u00edodo, a Sesau assegura a manuten\u00e7\u00e3o de servi\u00e7os essenciais, que seguir\u00e3o dispon\u00edveis ao p\u00fablico no hor\u00e1rio das 8h \u00e0s 13h. Entre eles est\u00e3o: sorologias em geral, baciloscopias, testagem para Covid-19 e exames de Laborat\u00f3rio de An\u00e1lises (LAN).<\/p>\n<p>A Secretaria refor\u00e7a que as interven\u00e7\u00f5es s\u00e3o necess\u00e1rias para garantir melhores condi\u00e7\u00f5es de atendimento, mais conforto aos usu\u00e1rios e maior qualidade nos servi\u00e7os prestados.<\/p>\n<p>Em caso de d\u00favidas, a popula\u00e7\u00e3o pode entrar em contato por meio do WhatsApp, pelo n\u00famero (74) 98143-1857.<\/p>\n<p>___<br \/>\n<em>Texto: Camila Santana \u2013 Ascom PMJ\/Sesau<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Juazeiro, por meio da Secretaria Municipal de Sa\u00fade (Sesau), informa que, a partir desta quarta-feira (25), dar\u00e1 in\u00edcio a melhorias estruturais no pr\u00e9dio do Laborat\u00f3rio Central de Sa\u00fade P\u00fablica (LACEN), localizado na Rua Ant\u00f4nio Pedro, n\u00ba 436, Centro, com o objetivo de qualificar ainda mais os servi\u00e7os ofertados \u00e0 popula\u00e7\u00e3o. Em virtude [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":84671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[205],"tags":[],"class_list":["post-84670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1.jpeg",498,491,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1-300x296.jpeg",300,296,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1.jpeg",498,491,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1.jpeg",498,491,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1.jpeg",498,491,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1.jpeg",498,491,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1.jpeg",498,491,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1-300x443.jpeg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1.jpeg",498,491,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.40.55-768x1024-1.jpeg",498,491,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A Prefeitura de Juazeiro, por meio da Secretaria Municipal de Sa\u00fade (Sesau), informa que, a partir desta quarta-feira (25), dar\u00e1 in\u00edcio a melhorias estruturais no pr\u00e9dio do Laborat\u00f3rio Central de Sa\u00fade P\u00fablica (LACEN), localizado na Rua Ant\u00f4nio Pedro, n\u00ba 436, Centro, com o objetivo de qualificar ainda mais os servi\u00e7os ofertados \u00e0 popula\u00e7\u00e3o. Em virtude&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/84670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=84670"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/84670\/revisions"}],"predecessor-version":[{"id":84672,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/84670\/revisions\/84672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/84671"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=84670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=84670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=84670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}