{"id":84762,"date":"2026-03-28T13:57:15","date_gmt":"2026-03-28T16:57:15","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=84762"},"modified":"2026-03-28T18:14:16","modified_gmt":"2026-03-28T21:14:16","slug":"salvador-sargento-da-pm-morre-apos-sofrer-acidente-de-carro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2026\/03\/28\/salvador-sargento-da-pm-morre-apos-sofrer-acidente-de-carro","title":{"rendered":"Salvador: Sargento da PM morre ap\u00f3s sofrer acidente de carro"},"content":{"rendered":"<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-xmptq9lm9q\">Um sargento da Pol\u00edcia Militar da Bahia morreu ap\u00f3s sofrer um grave acidente de carro na sexta-feira (27), na BA-535, conhecida como Via Parafuso, no trecho de Cama\u00e7ari, na Regi\u00e3o Metropolitana de Salvador.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-tlfqkqzcap\">A v\u00edtima foi identificada como Alessander Nascimento dos Santos, de 45 anos. Ele era lotado na 52\u00aa Companhia Independente da Pol\u00edcia Militar (CIPM), em Lauro de Freitas.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-qqlp146a5n\">O policial foi arremessado para fora do ve\u00edculo com o impacto da colis\u00e3o. Equipes de resgate chegaram a ser acionadas, mas ele n\u00e3o resistiu aos ferimentos. As circunst\u00e2ncias do acidente n\u00e3o foram detalhadas.\u00a0Natural de Alagoinhas, Alessander tinha 23 anos de atua\u00e7\u00e3o na corpora\u00e7\u00e3o, era casado e deixa um filho.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-9chy790syl\">Em nota, a Pol\u00edcia Militar da Bahia lamentou a morte do sargento. &#8220;Neste momento de imensa dor, a corpora\u00e7\u00e3o se solidariza com seus familiares, amigos e irm\u00e3os de farda, rogando a Deus que conceda conforto e for\u00e7a para enfrentar esta irrepar\u00e1vel perda&#8221;, diz o comunicado.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-ss1ju455p6\">&#8220;O Sgt PM Alessander dedicou sua vida ao servi\u00e7o policial militar com coragem, honra e elevado senso de dever, sendo exemplo de compromisso com a prote\u00e7\u00e3o da sociedade baiana. Sua trajet\u00f3ria foi marcada pela lealdade \u00e0 miss\u00e3o e pelo respeito aos valores institucionais, deixando um legado que permanecer\u00e1 vivo na mem\u00f3ria de todos que com ele conviveram&#8221;, finaliza.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full font-normal text-[18px] leading-[30px] text-tw-theme-text-default\">\n<p id=\"paragrafo-k4f26c8yxb\">A cerim\u00f4nia de despedida ser\u00e1 realizada no sal\u00e3o de vel\u00f3rios do Grupo Leal, em Alagoinhas. O sepultamento est\u00e1 previsto para as 15h, no Cemit\u00e9rio Jardim Para\u00edso da Saudade.<\/p>\n<\/div>\n<div class=\"flex flex-col w-full\">\n<div id=\"embed-f7hfcz2s4r\" class=\"component--embed \"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um sargento da Pol\u00edcia Militar da Bahia morreu ap\u00f3s sofrer um grave acidente de carro na sexta-feira (27), na BA-535, conhecida como Via Parafuso, no trecho de Cama\u00e7ari, na Regi\u00e3o Metropolitana de Salvador. A v\u00edtima foi identificada como Alessander Nascimento dos Santos, de 45 anos. Ele era lotado na 52\u00aa Companhia Independente da Pol\u00edcia Militar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":84763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[202],"tags":[],"class_list":["post-84762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43.jpg",500,309,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43-300x185.jpg",300,185,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43.jpg",500,309,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43.jpg",500,309,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43.jpg",500,309,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43.jpg",500,309,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43.jpg",500,309,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43-300x309.jpg",300,309,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43.jpg",500,309,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2026\/03\/Capturar-43.jpg",500,309,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Um sargento da Pol\u00edcia Militar da Bahia morreu ap\u00f3s sofrer um grave acidente de carro na sexta-feira (27), na BA-535, conhecida como Via Parafuso, no trecho de Cama\u00e7ari, na Regi\u00e3o Metropolitana de Salvador. A v\u00edtima foi identificada como Alessander Nascimento dos Santos, de 45 anos. Ele era lotado na 52\u00aa Companhia Independente da Pol\u00edcia Militar&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/84762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=84762"}],"version-history":[{"count":3,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/84762\/revisions"}],"predecessor-version":[{"id":84771,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/84762\/revisions\/84771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/84763"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=84762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=84762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=84762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}